{"id":99599,"date":"2016-11-14T01:38:40","date_gmt":"2016-11-14T03:38:40","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=99599"},"modified":"2016-11-14T01:38:40","modified_gmt":"2016-11-14T03:38:40","slug":"novela-sol-nascente-cesar-adia-plano-para-incriminar-mario","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/novela-sol-nascente-cesar-adia-plano-para-incriminar-mario\/99599","title":{"rendered":"Novela &#8220;Sol Nascente&#8221;: C\u00e9sar adia plano para incriminar M\u00e1rio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sol_nascente_cesar_rafael-cardoso-150x112.jpg\" alt=\"sol_nascente_cesar_rafael-cardoso\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-93942\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sol_nascente_cesar_rafael-cardoso-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sol_nascente_cesar_rafael-cardoso-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><em><strong>Novela &#8220;Sol Nascente&#8221;:<\/strong><\/em> C\u00e9sar (Rafael Cardoso) leva uma surra dos capangas de Massao (Marcos Tumura). Para se vingar, o vil\u00e3o manda Jo\u00e3o Amaro (Rafael Zulu) encomendar a morte do japon\u00eas e colocar a culpa em Mario (Bruno Gagliasso). Ap\u00f3s brigar com a fam\u00edlia, Milena (Giovanna Lancellotti) arruma trabalho no bar de Mano (\u00c1lamo Fac\u00f3). Jo\u00e3o Amaro aparece no bar de Mano e explica que precisa de um servi\u00e7o dele. Os bandidos decidem usar Milena como isca para incriminar Mario pela morte de Massao. Mas, dias depois, Cesar manda Jo\u00e3o Amaro adiar plano e n\u00e3o fazer nada contra Massao.<\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cSol Nascente\u201d, Lenita flagra Mario e Alice discutindo. Vittorio avisa a Geppina que Milena vai trabalhar. Dora se incomoda com a presen\u00e7a de Tiago. Mano e sua turma de motoqueiros amea\u00e7am Ralf e Lenita. Cesar tenta conseguir uma nova empresa de exporta\u00e7\u00e3o para ganhar a licita\u00e7\u00e3o da Arraial Pescados. Sirlene chega a Arraial. Geppina convida Ralf e Lenita para jantar em sua casa. Damasceno mostra a Mieko a faca que encontrou no carro de Cesar. Damasceno avisa a Cesar que investigar\u00e1 o assalto que ele sofreu. Jo\u00e3o Amaro fica encantado com Dora. Tiago conversa com L\u00facia. Milena \u00e9 contratada para trabalhar no bar do Mano. Wagner comenta com Alice que a explos\u00e3o nas traineiras pode ter sido criminosa. Jo\u00e3o Amaro consegue os documentos da empresa falsa para entregar a Cesar. Yumi e Tiago se beijam. Alice diz a Cesar que Wagner acredita que a explos\u00e3o nas traineiras pode ter sido criminosa.<\/p>\n<p> Cesar tenta desqualificar o coment\u00e1rio de Wagner para Alice. Yumi se arrepende de ter beijado Tiago. Dora ateia fogo no enxoval de seu beb\u00ea. Damasceno conta para Elisa que est\u00e1 investigando o assalto sofrido por Cesar. Quirino consola Tiago. Cesar amea\u00e7a Wagner. Hir\u00f4 incentiva Cesar a reconquistar Alice. Vittorio apoia a decis\u00e3o de Mario em morar sozinho. Carol \u00e9 hostil com Sirlene. Cesar convida Paula para jantar. Chica pede para doutora L\u00facia ajudar Dora. Lenita pede para Alice fazer companhia a Sirlene no Rota. Ci\u00e7a critica Milena por aceitar trabalhar no bar do Mano. Gaetano se enfurece quando Mario informa que ir\u00e1 morar sozinho. Cesar procura Alice e se surpreende ao encontrar Sirlene.<\/p>\n<p> Cesar amea\u00e7a Sirlene e seu filho. Vittorio apoia o emprego de Milena. Ralf decide ir at\u00e9 o bar do Mano e se encontra com Vittorio. Sirlene n\u00e3o conta para Lenita que Cesar \u00e9 o pai de seu filho. Vittorio \u00e9 atendido por Milena e a elogia para Mano ao sair do bar. Lenita convida Vittorio para fazer um dueto com ela no palco do Rota 94. Tiago pensa em Yumi. Jo\u00e3o Amaro arma um plano com Mano contra Mario. Milena \u00e9 carinhosa com Vittorio. Cesar manda Jo\u00e3o Amaro vigiar Sirlene. Cesar invade o quarto de Alice. Mario n\u00e3o se entende com Gaetano e pede a Tanaka para falar com o av\u00f4. Alice n\u00e3o gosta de ver Cesar em seu quarto, mas ele finge passar mal. Mario flagra Alice cuidando de Cesar.<\/p>\n<p> Mario tira satisfa\u00e7\u00f5es com Alice, que fica abalada. Hir\u00f4 se oferece para ir com Cesar para a empresa. Mario n\u00e3o consegue esconder de Tanaka que n\u00e3o terminou seu romance com Alice. Sirlene vai embora e deixa um bilhete para Lenita. Yumi decide viajar e Mieko pede para ela falar com Tanaka. Dora n\u00e3o consegue ficar acordada e Tiago vela seu sono. Cesar se declara para Alice. Tanaka convence Gaetano a aceitar a ida de Mario para sua casa nova. Mario marca um encontro com Alice. Jo\u00e3o Amaro arma contra Sirlene, que sofre um acidente de carro. Alice pesca com as cai\u00e7aras. Cesar suspeita que Alice est\u00e1 \u00a0escondendo algo e comenta com Jo\u00e3o Amaro.\u00a0Damasceno presenteia Mieko com flores. Sirlene \u00e9 socorrida por uma ambul\u00e2ncia. Cesar flagra Alice e Mario se beijando.<\/p>\n<p> Cesar segue Alice e Mario. Damasceno convida Mieko para sair, e Tanaka aprova. Ralf tenta fazer com que Milena perdoe Lenita. Sirlene \u00e9 levada para um hospital. Tanaka prepara a viagem de Yumi. Dora se recusa a se tratar com um psiquiatra. Alice decide cuidar da galeria enquanto Yumi estiver fora. Ralf pensa em Milena. Akira convida Hir\u00f4 para ir ao Rota.\u00a0Peppino e Mario implicam com Gaetano. Damasceno descobre um vazamento de \u00f3leo no carro de Cesar e fica intrigado. Carolina se faz de v\u00edtima para Geppina. Cesar sofre por causa de Alice. Sinh\u00e1 instrui o neto sobre um novo plano. Lenita se preocupa com Sirlene. Carolina aparece no Rota 94.\u00a0Mario fica chateado. Cesar procura Mario.<\/p>\n<p>Cesar afirma a Mario que n\u00e3o tem mais interesse em Alice. Tanaka tenta tranquilizar Mieko. Akira pede para levar Hir\u00f4 ao Rota 94. Geppina prepara um jantar para Chica e Quirino e pede para Gaetano convidar Tanaka. Jo\u00e3o Amaro v\u00ea Tanaka com uma caixa de pertences e avisa a Sinh\u00e1. Damasceno investiga o \u00f3leo que tirou do carro de Cesar. Mario conta para Alice que Cesar esteve no Rota 94. Cesar fala para Carolina que Alice e Mario continuam juntos. Ralf fica arrasado com o fora que leva de Milena. Carolina \u00e9 simp\u00e1tica ao falar com Mario sobre a gravidez. Tanaka chega \u00e0 casa de Gaetano. Hir\u00f4 avisa a Mieko para ficar de olho em Damasceno e Elisa. Mario escuta Alice contar para Lenita sobre sua conversa com Paula. Jo\u00e3o Amaro revira o quarto de Tanaka. Mieko questiona Damasceno sobre seus sentimentos por Elisa. Mario \u00e9 hostil com Alice ao ver Cesar chegar.<\/p>\n<p> Alice descobre que Mario ouviu parte de sua conversa com Lenita. Mieko decide voltar para casa e Damasceno se entristece. Hir\u00f4 fica frustrada com o desprezo de Ralf. Alice pede para conversar com Wagner e Cesar o amea\u00e7a. Damasceno avisa a Elisa que ir\u00e1 se afastar dela. Chica percebe Tanaka perturbado ao falar de seu av\u00f4. Jo\u00e3o Amaro se esconde de Mieko. Alice n\u00e3o consegue falar com Mario. Lenita, Ralf e Mario inauguram o Moto Clube Rota 94. Jo\u00e3o Amaro vai buscar Tanaka na casa de Gaetano. Mano v\u00ea Ralf indo embora com Milena. Tanaka flagra Damasceno beijando Mieko. Vittorio pede para Milena assistir a seu show com Lenita. Hir\u00f4 sente ci\u00fames de Ralf com Milena. Sirlene teme denunciar Cesar. Elisa se insinua para Nuno e Vanda fica furiosa. Nanda e Peppino se beijam. Milena questiona os sentimentos de Ralf. Mario encontra Alice em sua casa.<\/p>\n<p> Alice tem uma conversa s\u00e9ria com Mario. Mano observa Ralf e Milena juntos. Hir\u00f4 fica frustrada com a recusa de Akira em beij\u00e1-la. Mario e Alice fazem as pazes. Carolina invade o quarto de Cesar, depois que Paula vai embora. Wagner tenta convencer Alice a esquecer que a explos\u00e3o na traineira foi criminosa. Ralf pede para Felipe ir at\u00e9 a casa de Sirlene. Cesar tenta comprar uma moto com Mario. Peppino conta para Hideo que ele e Nanda se beijaram. Mieko tenta entender a investiga\u00e7\u00e3o de Damasceno. Ralf pensa em Milena. Alice seleciona uma das empresas falsas indicadas por Cesar para fazer neg\u00f3cio. Lenita descobre que Sirlene se acidentou e comenta com Cesar. Hir\u00f4 desconfia do clima entre Mario e Alice. Lenita, Vittorio e Cesar visitam Sirlene. Mario e Alice entregam as doa\u00e7\u00f5es para Sanfona. Mieko se preocupa com Damasceno. Sirlene se apavora ao ver Cesar com Lucas.<\/p>\n<p> Cesar amea\u00e7a Sirlene e a obriga a morar em Arraial do Sol Nascente. Damasceno persegue o rastro de \u00f3leo deixado pelo carro de Cesar. Mario pensa em como ajudar mais a comunidade do Trevo. Milena pensa em Ralf. Alice prepara um piquenique para Mario. Sinh\u00e1 exige que Jo\u00e3o Amaro encontre a caixa com os pertences de Tanaka. Tiago leva Dora para falar com o psiquiatra. Damasceno chega at\u00e9 o galp\u00e3o abandonado e encontra Massao. Mario estranha ao saber que Cesar visitou Sirlene no hospital. Sinh\u00e1 exige que Massao continue no comando do contrabando e Cesar reage contrariado. Damasceno fotografa Massao. Alice estuda o relat\u00f3rio pericial sobre a explos\u00e3o das traineiras. Cesar manda Jo\u00e3o Amaro n\u00e3o fazer nada contra Massao. Damasceno mostra para Cesar a foto que tirou de Massao.<\/p>\n<p> Cesar finge n\u00e3o reconhecer Massao. Damasceno tenta falar com Jo\u00e3o Amaro sobre sua investiga\u00e7\u00e3o. Cesar afirma a Paula que Sirlene \u00e9 uma grande amiga. Alice tem uma lembran\u00e7a da explos\u00e3o. Jo\u00e3o Amaro avisa a Mano que Massao n\u00e3o ser\u00e1 eliminado. Massao fica encantado com Milena. Carolina implica com Paula. Jo\u00e3o Amaro pergunta a Cesar o que deve fazer com Massao e Damasceno. Alice pede para Patrick ajud\u00e1-la em sua investiga\u00e7\u00e3o. Wagner observa Cesar, Jo\u00e3o Amaro e Massao. Mario dorme com Alice. Milena beija Mano para provocar Ralf. Lenita questiona o irm\u00e3o sobre seu envolvimento com Milena.\u00a0Tiago\u00a0fica triste ao saber que Yumi viajou. Cesar compra uma moto de Mario. Damasceno mostra a foto de Massao para Tanaka, que o reconhece.\u00a0Cesar\u00a0alerta Massao antes de a Pol\u00edcia invadir o galp\u00e3o. <\/p>\n<p> Damasceno encontra o celular de Massao. Cesar e Massao fogem. Wagner tenta conter o nervosismo e Alice percebe. Lenita pede para Felipe ajudar Sirlene com sua mudan\u00e7a.\u00a0Cesar repreende Massao e convoca Mano para ajud\u00e1-los.\u00a0Mario pensa em incentivar os empres\u00e1rios a capacitarem os adultos da\u00a0comunidade. Patrick sugere que Alice contrate um perito para analisar os sinalizadores artesanais.\u00a0Cesar manda Jo\u00e3o Amaro resgatar o celular de Massao com Damasceno.\u00a0Carolina convida Mario para sair.\u00a0 Chica teme que o casamento de Dora acabe. Mario\u00a0e Ralf levam\u00a0Gaetano e Tanaka para passear de motocicleta. Felipe chega \u00e0 casa de Sirlene.\u00a0Mario, Ralf e Tanaka ajudam Gaetano a escolher um terno. Vittorio repreende Milena por destratar Lenita.\u00a0Yumi conta para Bernardo que se apaixonou por um homem casado. Tiago prefere n\u00e3o comentar sobre a crise em seu casamento\u00a0com Nuno.\u00a0Sirlene chega a Arraial.\u00a0Mario afirma a Alice que Cesar provocou a explos\u00e3o das traineiras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela &#8220;Sol Nascente&#8221;: C\u00e9sar (Rafael Cardoso) leva uma surra dos capangas de Massao (Marcos Tumura). Para se vingar, o vil\u00e3o manda Jo\u00e3o Amaro (Rafael Zulu) encomendar a morte do japon\u00eas e colocar a culpa em Mario (Bruno Gagliasso). Ap\u00f3s brigar com a fam\u00edlia, Milena (Giovanna Lancellotti) arruma trabalho no bar de Mano (\u00c1lamo Fac\u00f3). Jo\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93943,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[440],"class_list":{"0":"post-99599","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"tag-noticia-novela","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sol_nascente_mario_bruno-gagliasso.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/99599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=99599"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/99599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/93943"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=99599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=99599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=99599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}