{"id":98785,"date":"2016-11-01T20:43:38","date_gmt":"2016-11-01T22:43:38","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=98785"},"modified":"2016-11-01T20:43:38","modified_gmt":"2016-11-01T22:43:38","slug":"novela-a-lei-do-amor-tiao-acredita-que-esta-prestes-a-morrer","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/novela-a-lei-do-amor-tiao-acredita-que-esta-prestes-a-morrer\/98785","title":{"rendered":"Novela &#8220;A Lei do Amor&#8221;: Ti\u00e3o acredita que est\u00e1 prestes a morrer"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_resumo_novela_globo-150x112.jpg\" alt=\"a_lei_do_amor_resumo_novela_globo\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-94887\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_resumo_novela_globo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_resumo_novela_globo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><em><strong>Novela &#8220;A Lei do Amor&#8221;:<\/strong><\/em> ap\u00f3s atacar Hel\u00f4 (Claudia Abreu), tentar beij\u00e1-la e enforc\u00e1-la, Ti\u00e3o (Jos\u00e9 Mayer) \u00e9 atingido na cabe\u00e7a com um peso de papel. Depois, fica irritado com Let\u00edcia (Isabella Santoni), que o acusa de manipul\u00e1-la e estragar seu romance com Tiago (Humberto Carr\u00e3o). Ti\u00e3o surta e sai a vagar pela cidade sem saber aonde ir. O apag\u00e3o na mem\u00f3ria faz o banqueiro deduzir que tem algo grave, como um tumor cerebral ou algum tipo de dem\u00eancia. Por isso, ele fica &#8220;bonzinho&#8221;. Tenta contar sobre seu passado a Magn\u00f3lia (Vera Holtz), libera Hel\u00f4 para se casar com Pedro (Reynaldo Gianecchini) e promete aumentos de sal\u00e1rio a funcion\u00e1rios. O empres\u00e1rio repete sem parar que \u00e9 hora de deixar tudo em ordem para os filhos e age como se acreditasse de verdade que est\u00e1 prestes a morrer. Miro (Jorge Lucas), seu motorista e amigo, fica espantado. O vil\u00e3o pede para comer ovos coloridos em um boteco e tamb\u00e9m passa uma noite inteira a dan\u00e7ar forr\u00f3 com mulheres humildes no Centro de Tradi\u00e7\u00f5es Nordestinas, local simples frequentado por Miro. Do nada, Ti\u00e3o fala para Miro que n\u00e3o quer mais v\u00ea-lo em sua frente e sai de carro, desnorteado. O vil\u00e3o roda por horas at\u00e9 parar em uma estrada perto da represa de S\u00e3o Dimas, sem saber onde est\u00e1. Xanaia (Bella Piero) o encontra e chama Bruno (Armando Babaioff). Miro chega \u00e0 pens\u00e3o e fica surpreso com a presen\u00e7a do patr\u00e3o. Ap\u00f3s fazer uma bateria de exames, o banqueiro descobre que o &#8220;apag\u00e3o&#8221; foi estresse e que s\u00f3 precisa cuidar da press\u00e3o alta e fazer mais exerc\u00edcios f\u00edsicos. <\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cA Lei do Amor\u201d, Ti\u00e3o tenta manipular Let\u00edcia. Conrado avisa a Pedro para se manter afastado de Ti\u00e3o. Ti\u00e3o descobre que Magn\u00f3lia cuidar\u00e1 de Fausto em casa. J\u00e9ssica difama Salete para Amaro. Ciro se apavora com a chegada da pol\u00edcia \u00e0 tecelagem. Gledson pede para Mileide se afastar de Augusto. Leila incentiva Vit\u00f3ria a deixar Ciro. O delegado informa a Olavo e Hel\u00f4 que Pedro ser\u00e1 solto. Ti\u00e3o exige que Isabela esteja na equipe que servir\u00e1 o buf\u00ea na festa de anivers\u00e1rio de Let\u00edcia. Keila fica furiosa com o que Amaro conta sobre Salete. Venturini e Nacib s\u00e3o cercados por jornalistas. Ti\u00e3o afirma que n\u00e3o deixar\u00e1 Hel\u00f4 se afastar dele. Pedro sai da cadeia.<\/p>\n<p> Hel\u00f4 viaja com Pedro. Ana Luiza ouve Vit\u00f3ria dizer que foi obrigada por Ciro a depor contra Pedro. Ant\u00f4nio pede que Tiago termine seu noivado. Edu conta a Let\u00edcia que Ti\u00e3o possui um apartamento para encontros amorosos. Magn\u00f3lia pede um empr\u00e9stimo a Ti\u00e3o. Ana Luiza divulga o v\u00eddeo com o depoimento de Isabela no blog de Elio. Venturini e Nacib culpam Fausto pelas empresas de fachada. Hel\u00f4 e Pedro chegam ao s\u00edtio de Olavo. Valdir filma Tiago e Isabela se beijando e avisa a Ti\u00e3o que eles foram a um hotel. Magn\u00f3lia culpa Aline pela presen\u00e7a dos jornalistas em sua casa. Amaro faz um v\u00eddeo de J\u00e9ssica difamando Salete. Ti\u00e3o pressiona Let\u00edcia a ligar para Hel\u00f4.<\/p>\n<p> Let\u00edcia enfrenta Ti\u00e3o. Pedro conta a Hel\u00f4 que recebeu uma carta amea\u00e7adora na cadeia. Augusto descobre o que Amaro fez contra Salete e o demite. J\u00e9ssica se surpreende com o tratamento que recebe da m\u00e3e. Magn\u00f3lia expulsa Nacib de sua casa. Camila pede para visitar o t\u00famulo de Carmem. Marc\u00e3o n\u00e3o deixa Vit\u00f3ria se embriagar. Xanaia acompanha Ruty Raquel em seus encontros. Magn\u00f3lia manda Tiago falar com Let\u00edcia. Ana Luiza discute com Elio por causa de Isabela. Fl\u00e1via critica Salete por n\u00e3o ter sido dura com J\u00e9ssica. Let\u00edcia acusa Hel\u00f4 de rejeitar Ti\u00e3o. Salete procura Augusto. Ti\u00e3o briga com Hel\u00f4.<\/p>\n<p> Yara cuida de Hel\u00f4, mas a critica por n\u00e3o contar para Pedro o que aconteceu. Ti\u00e3o vai para o hospital. Salete fica arrasada ao descobrir que J\u00e9ssica a difamou. Tiago afirma a Isabela que ir\u00e1 se separar de Let\u00edcia. Ti\u00e3o sabota a bebida de Let\u00edcia. Pascoal avisa a H\u00e9rcules que Salete n\u00e3o pode mais ser sua vice-prefeita. Let\u00edcia passa mal e Hel\u00f4 desconfia de Ti\u00e3o. Tiago \u00e9 informado da interna\u00e7\u00e3o da noiva e fala com Isabela. Ti\u00e3o amea\u00e7a Hel\u00f4. Hel\u00f4 avisa a Pedro que sua filha foi internada. Ana Luiza consegue se comunicar com Fausto. Augusto faz um com\u00edcio na pra\u00e7a e todos o aplaudem. H\u00e9rcules pede que Magn\u00f3lia seja sua vice-prefeita. Venturini exige que Luciane encontre a gar\u00e7onete que o denunciou. Pedro chega ao hospital. Tiago termina o noivado com Let\u00edcia.<\/p>\n<p>Let\u00edcia pergunta a Tiago se ele est\u00e1 apaixonado por outra pessoa.\u00a0Let\u00edcia culpa Ti\u00e3o\u00a0por\u00a0seu rompimento.\u00a0Fausto tenta se comunicar com\u00a0Analu.\u00a0Isabela decide\u00a0ir \u00e0\u00a0pol\u00edcia com\u00a0Elio\u00a0e\u00a0Analu. Pascoal avisa a Venturini que descobriu que Isabela era a gar\u00e7onete que estava na festa de Fausto.\u00a0Mileide\u00a0deixa J\u00e9ssica assustada\u00a0com suas previs\u00f5es. Ant\u00f4nio\u00a0ofende J\u00e9ssica\u00a0e desmente as cal\u00fanias contra Salete em entrevista aos jornalistas. Tiago\u00a0revela\u00a0a Isabela que terminou o noivado. David enfrenta Ti\u00e3o. Magn\u00f3lia\u00a0demite Aline.\u00a0Hel\u00f4\u00a0acusa Ti\u00e3o de ter intoxicado Let\u00edcia. Aline invade o quarto de Vit\u00f3ria.<\/p>\n<p> Aline exige que Vit\u00f3ria conven\u00e7a Magn\u00f3lia a\u00a0readimiti-la no\u00a0emprego. Ti\u00e3o se\u00a0recusa a conceder o div\u00f3rcio para\u00a0Hel\u00f4. Fl\u00e1via amea\u00e7a contar sobre o furto de J\u00e9ssica, se ela n\u00e3o desmentir as cal\u00fanias contra Salete.\u00a0Fininho assiste a entrevista\u00a0de J\u00e9ssica pela TV. Vit\u00f3ria pede \u00e0\u00a0m\u00e3e que n\u00e3o demita Aline. A concentra\u00e7\u00e3o de pessoas em solidariedade a Salete convence os jornalistas.\u00a0Mileide\u00a0nega abrigo a Amaro. David pede demiss\u00e3o para Ti\u00e3o. Isabela aceita o convite de Tiago para ir ao Rio de Janeiro.\u00a0 Magn\u00f3lia desconfia\u00a0de\u00a0que Aline chantageou Vit\u00f3ria. Let\u00edcia\u00a0promove\u00a0uma festa de anivers\u00e1rio e convida Tiago.\u00a0Ti\u00e3o comenta com Bruno que teve um lapso de mem\u00f3ria e afirma que est\u00e1 doente.\u00a0Hel\u00f4\u00a0avisa a Let\u00edcia que\u00a0ela precisa saber da verdade.<\/p>\n<p> Bruno avisa a\u00a0Hel\u00f4\u00a0que Ti\u00e3o precisa de exames. Robinson pergunta a Camila se ela est\u00e1 saindo com Arlindo.\u00a0Hel\u00f4\u00a0desconfia da cena de Ti\u00e3o pedindo perd\u00e3o a Let\u00edcia. Let\u00edcia avisa ao pai que vai voltar a trabalhar na empresa. Vit\u00f3ria\u00a0teme perder seu beb\u00ea.\u00a0Hel\u00f4\u00a0diz a Pedro que tem uma d\u00edvida com ele. Ana Luiza conversa com\u00a0Elio\u00a0sobre a investiga\u00e7\u00e3o\u00a0para descobrir o que o av\u00f4 e Suzana iriam fazer em Bragan\u00e7a.\u00a0Fininho liga para\u00a0J\u00e9ssica exigindo parte da quantia\u00a0que ela ganhou com a cal\u00fania que criou contra a m\u00e3e. David demonstra interesse em conhecer Salete e pede a Ant\u00f4nio para lhe apresentar. Pedro pergunta a\u00a0Hel\u00f4\u00a0se ela\u00a0esconde algo dele.<\/p>\n<p> Hel\u00f4\u00a0diz a Pedro que precisa\u00a0lhe\u00a0contar algo. Magn\u00f3lia repreende Ciro por sua neglig\u00eancia\u00a0com Vit\u00f3ria. Elio\u00a0se infiltra junto aos jornalistas para fazer perguntas a Magn\u00f3lia. Ana Luiza beija\u00a0Elio\u00a0e incentiva o rapaz a lutar por ela.\u00a0Robinson apresenta Fl\u00e1via a David. Magn\u00f3lia repreende Camila por estar saindo com Arlindo. Ana Luiza enfrenta Magn\u00f3lia, quando a av\u00f3 critica seu namoro com\u00a0Elio. Ti\u00e3o liga para David pedindo para o ex-funcion\u00e1rio voltar para a empresa. Pedro pede a Ant\u00f4nio que d\u00ea um voto de confian\u00e7a a Olavo. Fininho amea\u00e7a incendiar o posto de Salete se J\u00e9ssica n\u00e3o pagar a d\u00edvida que tem com ele. Let\u00edcia se deixa envolver com a chantagem emocional de Ti\u00e3o. Ti\u00e3o procura Pedro\u00a0para falar de\u00a0Hel\u00f4.<\/p>\n<p> Ti\u00e3o insinua\u00a0a Pedro que\u00a0Hel\u00f4\u00a0esconde\u00a0informa\u00e7\u00f5es\u00a0dele. Tiago revela a Magn\u00f3lia que\u00a0est\u00e1 apaixonado.\u00a0Vit\u00f3ria confessa a\u00a0Padre Paulo que Ciro\u00a0atentou contra sua vida.\u00a0Zuza\u00a0defende Magn\u00f3lia, ao ouvir Marc\u00e3o e Sans\u00e3o\u00a0a acusarem\u00a0de corrup\u00e7\u00e3o. Ana Luiza diz a Tiago que ele n\u00e3o deveria ter aberto m\u00e3o da tecelagem. Aline\u00a0beija Tiago\u00a0e declara sua paix\u00e3o. Leila conta a Magn\u00f3lia que Ti\u00e3o passou a noite dan\u00e7ando forr\u00f3 com ela. Aline conta a Magn\u00f3lia que Tiago est\u00e1 apaixonado por uma gar\u00e7onete. Pedro entra na mans\u00e3o, avisando a Magn\u00f3lia que voltou para ficar. <\/p>\n<p> Pedro avisa a Magn\u00f3lia que voltou para cuidar do pai e de Ana Luiza. Pedro avisa a J\u00e1der que passar\u00e1 a custear o tratamento do pai.\u00a0Pascoal sugere a H\u00e9rcules que\u00a0Mileide\u00a0seja sua\u00a0candidata\u00a0a\u00a0vice. Salete revela a Flavia que est\u00e1 sofrendo pelo mal que J\u00e9ssica lhe fez. O pedido de cassa\u00e7\u00e3o de Venturini \u00e9 aprovado no Senado. Camila ajuda J\u00e9ssica a fugir. Vit\u00f3ria entra em p\u00e2nico ao ver Aline entrar em seu quarto no hospital, mas \u00e9 tranquilizada pela chegada de Augusto. Isabela avisa a Tiago que ele corre\u00a0perigo, ficando\u00a0a\u00a0seu\u00a0lado. Magn\u00f3lia conta a Ti\u00e3o que Tiago est\u00e1 com Isabela. Salete aconselha Rodney a voltar para a mulher. Ciro flagra Augusto no quarto de Vit\u00f3ria.\u00a0Hel\u00f4\u00a0revela a Pedro que eles t\u00eam um filho juntos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela &#8220;A Lei do Amor&#8221;: ap\u00f3s atacar Hel\u00f4 (Claudia Abreu), tentar beij\u00e1-la e enforc\u00e1-la, Ti\u00e3o (Jos\u00e9 Mayer) \u00e9 atingido na cabe\u00e7a com um peso de papel. Depois, fica irritado com Let\u00edcia (Isabella Santoni), que o acusa de manipul\u00e1-la e estragar seu romance com Tiago (Humberto Carr\u00e3o). Ti\u00e3o surta e sai a vagar pela cidade sem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94887,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[440],"class_list":{"0":"post-98785","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"tag-noticia-novela","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_resumo_novela_globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/98785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=98785"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/98785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/94887"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=98785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=98785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=98785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}