{"id":98202,"date":"2016-10-25T17:02:48","date_gmt":"2016-10-25T19:02:48","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=98202"},"modified":"2016-10-25T17:02:48","modified_gmt":"2016-10-25T19:02:48","slug":"novela-a-lei-do-amor-pedro-e-helo-entregam-provas-de-corrupcao-para-a-policia","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/novela-a-lei-do-amor-pedro-e-helo-entregam-provas-de-corrupcao-para-a-policia\/98202","title":{"rendered":"Novela &#8220;A Lei do Amor&#8221;: Pedro e Hel\u00f4 entregam provas de corrup\u00e7\u00e3o para a pol\u00edcia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_novela_globo_resumo-150x112.jpg\" alt=\"a_lei_do_amor_novela_globo_resumo\" width=\"150\" height=\"112\" class=\"alignleft size-thumbnail wp-image-94344\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_novela_globo_resumo-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_novela_globo_resumo-265x198.jpg 265w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><em><strong>Novela &#8220;A Lei do Amor&#8221;:<\/strong><\/em> ap\u00f3s provas plantadas e o depoimento de Vit\u00f3ria (Camila Morgado), Pedro (Reynaldo Gianecchini) \u00e9 preso e acusado de ser o autor do atentado que matou Suzana (Regina Duarte) e deixou Fausto (Tarc\u00edsio Meira) em estado vegetativo. Logo depois, Pedro pede que Hel\u00f4 (Claudia Abreu) e Olavo (Tato Gabus Mendes) mostrem \u00e0 pol\u00edcia a sala secreta no escrit\u00f3rio de seu pai. Tiago (Humberto Carr\u00e3o) ajuda Hel\u00f4 e coloca Ciro (Thiago Lacerda) para fora do local na hora em que o delegado e sua equipe chegam. Hel\u00f4 abre a sala secreta e o delegado manda as provas para o DHPP (Delegacia Estadual de Homic\u00eddios e Prote\u00e7\u00e3o \u00e0 Pessoa). O delegado diz a Olavo que vai fazer o poss\u00edvel para soltar Pedro no mesmo dia. O caso se torna um esc\u00e2ndalo. O senador Venturini (Ot\u00e1vio Augusto) e o deputado Arlindo (Maur\u00edcio machado) passam a ser investigados. Pedro \u00e9 solto. Do lado de fora, Hel\u00f4 o recebe com um beijo apaixonado.   <\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cA Lei do Amor\u201d, Hel\u00f4 se preocupa com a possibilidade de Tiago gostar de outra mo\u00e7a. Yara entra em p\u00e2nico ao saber que Ritinha passou mal. Isabela admite que se sentiu atra\u00edda por Tiago. Hel\u00f4 enfrenta Ti\u00e3o para impedi-lo de agredir Edu. Pedro tenta descobrir com Tiago quem \u00e9 Isabela. Let\u00edcia constata que J\u00e9ssica furtou sua pulseira e o rel\u00f3gio de Tiago. Os auditores contratados por Pedro chegam \u00e0 tecelagem e Ciro se revolta. Let\u00edcia acusa J\u00e9ssica de roubo e Salete defende a filha. Hel\u00f4 tenta se consolar com Yara. Salete aceita ser vice na chapa de H\u00e9rcules pela Prefeitura. Zelito sugere que Tiago v\u00e1 \u00e0 sua casa conversar com Isabela. Ciro exige que Magn\u00f3lia escolha entre ele e Pedro para assumir a diretoria da tecelagem. Hel\u00f4 questiona Tiago sobre seu envolvimento com Isabela.<\/p>\n<p>Pedro afirma que n\u00e3o ficar\u00e1 na tecelagem. Hel\u00f4 pede para Tiago resolver seus problemas antes de se casar com Let\u00edcia. Salete exige que Robinson devolva a pulseira de Let\u00edcia e o rel\u00f3gio de Tiago. Ciro pede demiss\u00e3o. Camila implica com Aline. Fininho amea\u00e7a J\u00e9ssica. Pedro revela a Magn\u00f3lia que descobriu uma conta no exterior em seu nome. Tiago e Let\u00edcia discutem. Edu descobre que Ti\u00e3o quer envi\u00e1-lo para um col\u00e9gio interno no exterior. Pascoal convence Marc\u00e3o a gravar uma propaganda pol\u00edtica para H\u00e9rcules. Edu briga com Ti\u00e3o e sai de casa. Gigi obriga Ant\u00f4nio a se desculpar com Ruty Raquel. Miro critica Marc\u00e3o pela propaganda eleitoral. Elio decide fazer novas postagens contra a fam\u00edlia Leit\u00e3o. Ciro incentiva Vit\u00f3ria a ficar contra Pedro. Ti\u00e3o exige que Edu volte para casa com ele e Pedro o enfrenta. Tiago vai \u00e0 casa de Isabela.<\/p>\n<p>Tiago vai ao teatro com Isabela. Let\u00edcia fica abalada com os argumentos de Hel\u00f4 sobre seu noivado. Ciro manipula Vit\u00f3ria sobre a briga que Pedro teve com Fausto. Venturini tenta se insinuar para Salete. Elio pede autoriza\u00e7\u00e3o a Ana Luiza para postar a not\u00edcia sobre o atropelamento de Marc\u00e3o. Tiago e Isabela se beijam. Salete desiste de ser a vice de H\u00e9rcules. Isabela v\u00ea uma foto do noivado de Tiago e fica abalada. Vit\u00f3ria passa mal e Ciro a leva para o hospital. Camila pede para sair com Robinson. Pedro comemora suas descobertas sobre Ciro e Ti\u00e3o. Magn\u00f3lia n\u00e3o consegue convencer Juninho a desmentir a postagem de Elio. Ciro manda Fininho colocar a arma do atentado contra Fausto no barco de Pedro e avisa \u00e0 Pol\u00edcia. Magn\u00f3lia se enfurece ao encontrar Augusto no quarto de Vit\u00f3ria. Pedro entrega o dossi\u00ea contra Ciro. O delegado recebe a confirma\u00e7\u00e3o sobre a arma encontrada no barco de Pedro.<\/p>\n<p>Tiago tenta n\u00e3o decepcionar Let\u00edcia. Isabela conta para Zelito sobre seu\u00a0 encontro com Tiago. Ti\u00e3o manda Miro descobrir quem s\u00e3o os pais de Sofia. Ana Luiza avisa a Pedro que est\u00e3o tentando incrimin\u00e1-lo no atentado contra Fausto. Salete tira satisfa\u00e7\u00f5es com H\u00e9rcules e Venturini. Marc\u00e3o destrata Aline. Ti\u00e3o pede conselhos a Magn\u00f3lia. A Pol\u00edcia procura por Pedro. J\u00e9ssica humilha Ruty Raquel. Vit\u00f3ria dep\u00f5e contra Pedro. Magn\u00f3lia repreende Padre Paulo por ter aceitado uma contribui\u00e7\u00e3o em nome da Prefeitura. Camila descobre que pegou o celular de Gledson e encontra uma foto de Pedro com Suzana. Pedro entrega a Hel\u00f4 a chave do aposento secreto da sala de Fausto. Camila leva a foto que encontrou de Pedro para a delegacia. Ruty Raquel desiste de jantar com Ant\u00f4nio. Isabela sofre \u00e0 espera de Tiago. Pedro se apresenta na delegacia e descobre que pode ser preso.<\/p>\n<p>Pedro conversa com o delegado e acaba preso. Let\u00edcia se surpreende ao saber que Pedro ajudou Hel\u00f4 com seu av\u00f4. Ti\u00e3o manda Valdir investigar Isabela. Tiago e Ana Luiza culpam Vit\u00f3ria pela pris\u00e3o do tio e Ciro finge defender a esposa. Elio e Olavo tentam desqualificar o depoimento de Vit\u00f3ria. Luciene sente ci\u00fames de Salete. Ciro tenta compensar Marc\u00e3o por n\u00e3o denunciar Vit\u00f3ria. Juninho fala sobre o atropelamento de Marc\u00e3o em seu depoimento. Tiago n\u00e3o atende aos telefonemas de Let\u00edcia. Elio faz um v\u00eddeo com a den\u00fancia de Isabela contra Venturini e Nacib. Hel\u00f4 descobre que Ti\u00e3o humilhou Edu na frente da namorada. Isabela quase \u00e9 atropelada.? <\/p>\n<p> Zelito salva Isabela e acha que foi um atentado. Hel\u00f4 enfrenta Ti\u00e3o e Let\u00edcia fica a seu lado. Isabela decide n\u00e3o atender o telefonema de Tiago. Misael e Yara se preocupam com a dedica\u00e7\u00e3o de Aline a Magn\u00f3lia. Pedro se assusta com a visita da madrasta. Ana Luiza percebe uma rea\u00e7\u00e3o de Fausto e comunica a Bruno. Edu, Tiago e Hel\u00f4 se surpreendem quando Let\u00edcia acredita na farsa de Ti\u00e3o. Ruty Raquel decide sair com Ant\u00f4nio. Pedro conta para Olavo sobre o aposento secreto no escrit\u00f3rio de Fausto. Santa estranha uma sa\u00edda noturna de Magn\u00f3lia. Tiago flagra Let\u00edcia mexendo em seu celular. Magn\u00f3lia anuncia a volta de Ciro \u00e0 tecelagem. Olavo avisa a Celso que possui provas para libertar Pedro. Let\u00edcia ouve Ti\u00e3o afirmar que n\u00e3o quer que Pedro saia da cadeia.<\/p>\n<p> Ti\u00e3o tenta manipular Let\u00edcia. Conrado avisa a Pedro para se manter afastado de Ti\u00e3o. Ti\u00e3o descobre que Magn\u00f3lia cuidar\u00e1 de Fausto em casa. J\u00e9ssica difama Salete para Amaro. Ciro se apavora com a chegada da pol\u00edcia \u00e0 tecelagem. Gledson pede para Mileide se afastar de Augusto. Leila incentiva Vit\u00f3ria a deixar Ciro. O delegado informa a Olavo e Hel\u00f4 que Pedro ser\u00e1 solto. Ti\u00e3o exige que Isabela esteja na equipe que servir\u00e1 o buf\u00ea na festa de anivers\u00e1rio de Let\u00edcia. Keila fica furiosa com o que Amaro conta sobre Salete. Venturini e Nacib s\u00e3o cercados por jornalistas. Ti\u00e3o afirma que n\u00e3o deixar\u00e1 Hel\u00f4 se afastar dele. Pedro sai da cadeia.<\/p>\n<p> Hel\u00f4 viaja com Pedro. Ana Luiza ouve Vit\u00f3ria dizer que foi obrigada por Ciro a depor contra Pedro. Ant\u00f4nio pede que Tiago termine seu noivado. Edu conta a Let\u00edcia que Ti\u00e3o possui um apartamento para encontros amorosos. Magn\u00f3lia pede um empr\u00e9stimo a Ti\u00e3o. Ana Luiza divulga o v\u00eddeo com o depoimento de Isabela no blog de Elio. Venturini e Nacib culpam Fausto pelas empresas de fachada. Hel\u00f4 e Pedro chegam ao s\u00edtio de Olavo. Valdir filma Tiago e Isabela se beijando e avisa a Ti\u00e3o que eles foram a um hotel. Magn\u00f3lia culpa Aline pela presen\u00e7a dos jornalistas em sua casa. Amaro faz um v\u00eddeo de J\u00e9ssica difamando Salete. Ti\u00e3o pressiona Let\u00edcia a ligar para Hel\u00f4.<\/p>\n<p> Let\u00edcia enfrenta Ti\u00e3o. Pedro conta a Hel\u00f4 que recebeu uma carta amea\u00e7adora na cadeia. Augusto descobre o que Amaro fez contra Salete e o demite. J\u00e9ssica se surpreende com o tratamento que recebe da m\u00e3e. Magn\u00f3lia expulsa Nacib de sua casa. Camila pede para visitar o t\u00famulo de Carmem. Marc\u00e3o n\u00e3o deixa Vit\u00f3ria se embriagar. Xanaia acompanha Ruty Raquel em seus encontros. Magn\u00f3lia manda Tiago falar com Let\u00edcia. Ana Luiza discute com Elio por causa de Isabela. Fl\u00e1via critica Salete por n\u00e3o ter sido dura com J\u00e9ssica. Let\u00edcia acusa Hel\u00f4 de rejeitar Ti\u00e3o. Salete procura Augusto. Ti\u00e3o briga com Hel\u00f4.<\/p>\n<p> Yara cuida de Hel\u00f4, mas a critica por n\u00e3o contar para Pedro o que aconteceu. Ti\u00e3o vai para o hospital. Salete fica arrasada ao descobrir que J\u00e9ssica a difamou. Tiago afirma a Isabela que ir\u00e1 se separar de Let\u00edcia. Ti\u00e3o sabota a bebida de Let\u00edcia. Pascoal avisa a H\u00e9rcules que Salete n\u00e3o pode mais ser sua vice-prefeita. Let\u00edcia passa mal e Hel\u00f4 desconfia de Ti\u00e3o. Tiago \u00e9 informado da interna\u00e7\u00e3o da noiva e fala com Isabela. Ti\u00e3o amea\u00e7a Hel\u00f4. Hel\u00f4 avisa a Pedro que sua filha foi internada. Ana Luiza consegue se comunicar com Fausto. Augusto faz um com\u00edcio na pra\u00e7a e todos o aplaudem. H\u00e9rcules pede que Magn\u00f3lia seja sua vice-prefeita. Venturini exige que Luciane encontre a gar\u00e7onete que o denunciou. Pedro chega ao hospital. Tiago termina o noivado com Let\u00edcia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela &#8220;A Lei do Amor&#8221;: ap\u00f3s provas plantadas e o depoimento de Vit\u00f3ria (Camila Morgado), Pedro (Reynaldo Gianecchini) \u00e9 preso e acusado de ser o autor do atentado que matou Suzana (Regina Duarte) e deixou Fausto (Tarc\u00edsio Meira) em estado vegetativo. Logo depois, Pedro pede que Hel\u00f4 (Claudia Abreu) e Olavo (Tato Gabus Mendes) mostrem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[440],"class_list":{"0":"post-98202","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"tag-noticia-novela","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/a_lei_do_amor_novela_globo_resumo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/98202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=98202"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/98202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/94344"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=98202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=98202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=98202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}