{"id":89507,"date":"2016-07-02T16:20:32","date_gmt":"2016-07-02T19:20:32","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=89507"},"modified":"2016-07-02T22:13:34","modified_gmt":"2016-07-03T01:13:34","slug":"mega-sena-1833-premio-de-r-55-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/mega-sena-1833-premio-de-r-55-milhoes\/89507","title":{"rendered":"Mega Sena 1833: pr\u00eamio de R$ 5,5 milh\u00f5es"},"content":{"rendered":"<p><strong><em>Mega Sena<\/em><\/strong> 1833: n\u00e3o houve acertador na faixa principal do concurso anterior. A loteria Caixa Mega Sena de hoje pode pagar o pr\u00eamio princial de R$ 5,5 milh\u00f5es. O sorteio do concurso 1833 da modalidade ser\u00e1 realizado, \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 na cidade de Limoeiro (PE).<\/p>\n\n<p>Na poupan\u00e7a, o pr\u00eamio Mega Sena 1833 renderia quase R$ 36 mil por m\u00eas. O valor do pr\u00eamio tamb\u00e9m seria suficiente para adquirir uma frota de 36 carros de luxo.<\/p>\n<p>Como jogar<br \/>\nA aposta m\u00ednima na Mega Sena 1833 custa R$ 3,50 e pode ser feita at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia) de s\u00e1bado em qualquer uma das mais de 13 mil casas lot\u00e9ricas do pa\u00eds. Clientes da CAIXA com acesso ao internet banking podem fazer suas apostas na Mega Sena pelo computador. Basta ter conta corrente no banco e ser maior de 18 anos. O servi\u00e7o funciona diariamente, das 8h \u00e0s 22h (hor\u00e1rio de Bras\u00edlia), exceto em dias de sorteio, quando as apostas se encerram \u00e0s 19h, retornando \u00e0s 21h para o concurso seguinte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1833: n\u00e3o houve acertador na faixa principal do concurso anterior. A loteria Caixa Mega Sena de hoje pode pagar o pr\u00eamio princial de R$ 5,5 milh\u00f5es. O sorteio do concurso 1833 da modalidade ser\u00e1 realizado, \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 na cidade de Limoeiro (PE). [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":64962,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,355],"tags":[],"class_list":{"0":"post-89507","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-mega-sena","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/mega_sena_resultado_hoje_loteria.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/89507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=89507"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/89507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/64962"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=89507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=89507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=89507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}