{"id":89266,"date":"2016-06-29T17:53:07","date_gmt":"2016-06-29T20:53:07","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=89266"},"modified":"2016-06-29T17:53:07","modified_gmt":"2016-06-29T20:53:07","slug":"lotofacil-1381-premio-de-r-37-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/lotofacil-1381-premio-de-r-37-milhoes\/89266","title":{"rendered":"Lotof\u00e1cil 1381: pr\u00eamio de R$ 3,7 milh\u00f5es"},"content":{"rendered":"<p><strong><em>Lotof\u00e1cil<\/em><\/strong> 1381: a loteria Caixa Lotof\u00e1cil acumulou e pode pagar o pr\u00eamio de R$ 3,7 milh\u00f5es para o apostador que acertar os 15 n\u00fameros do concurso 1381. O sorteio ser\u00e1 realizado, nesta quarta-feira (29), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que esta semana est\u00e1 estacionado em Limoeiro, estado de Pernambuco.<\/p>\n\n<p>Na poupan\u00e7a, o pr\u00eamio Lotof\u00e1cil 1381 renderia mais de R$ 20\u00a0mil por m\u00eas. O valor tamb\u00e9m seria suficiente para adquirir uma frota de 100 carros. Os sorteios da Lotof\u00e1cil s\u00e3o realizados tr\u00eas vezes por semana, \u00e0s segundas, quartas e sextas-feiras.<\/p>\n<p>Como jogar<br \/>\nPara jogar na Lotof\u00e1cil 1381, o apostador marca entre 15 a 18 n\u00fameros, dentre os 25 dispon\u00edveis no volante, e fatura o pr\u00eamio se acertar 11, 12, 13, 14 ou 15 n\u00fameros. Pode ainda deixar que o sistema escolha os n\u00fameros por meio da Surpresinha, ou concorrer com a mesma aposta por 3, 6, 9 ou 12 concursos consecutivos atrav\u00e9s da Teimosinha.<\/p>\n<p>A programa\u00e7\u00e3o das loterias est\u00e1 sujeita a altera\u00e7\u00f5es.<\/p>\n<p>Confira o bilhete impresso pelo terminal. Ele \u00e9 o \u00fanico comprovante para o recebimento do pr\u00eamio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotof\u00e1cil 1381: a loteria Caixa Lotof\u00e1cil acumulou e pode pagar o pr\u00eamio de R$ 3,7 milh\u00f5es para o apostador que acertar os 15 n\u00fameros do concurso 1381. O sorteio ser\u00e1 realizado, nesta quarta-feira (29), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que esta semana est\u00e1 estacionado em Limoeiro, estado de Pernambuco. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":65058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,357],"tags":[],"class_list":{"0":"post-89266","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-facil","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/lotofacil_resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/89266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=89266"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/89266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/65058"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=89266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=89266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=89266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}