{"id":89100,"date":"2016-06-28T23:48:04","date_gmt":"2016-06-29T02:48:04","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=89100"},"modified":"2016-06-29T02:10:55","modified_gmt":"2016-06-29T05:10:55","slug":"lotomania-1670-e-quina-4117-sorteio-em-2806","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/lotomania-1670-e-quina-4117-sorteio-em-2806\/89100","title":{"rendered":"Lotomania 1670 e Quina 4117: sorteio em 28\/06"},"content":{"rendered":"<p> Resultado da <strong><em>Lotomania<\/em><\/strong> 1670 e <strong><em>Quina<\/em><\/strong> 4117: ap\u00f3s o sorteio anterior, o pr\u00eamio principal da Lotomania foi dividido entre duas apostas, e valor do pr\u00eamio principal da Lotomania de hoje foi estimado em R$ 500.000,00. No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Quina acumulou pela segunda vez consecutiva. O valor estimado do pr\u00eamio principal da loteria Quina chegou a R$ 1.800.000,00. O sorteio dos concursos das Loterias Caixa Lotomania 1670 e Quina 4117 acontece na noite desta ter\u00e7a-feira (28\/06). Os resultados das loterias Caixa Lotomania e Quina s\u00e3o divulgados no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o Paulo\/SP), ou no Caminh\u00e3o da Sorte, que esta semana est\u00e1 estacionado em Limoeiro, Pernambuco.<\/p>\n\n\n<p>A loteria Caixa Quina permite aposta de 5 a 15 n\u00fameros dentre os 80 dispon\u00edveis no volante. Ganham pr\u00eamios os acertadores de 2, 3, 4 ou 5 n\u00fameros. \u00c9 poss\u00edvel concorrer com a mesma aposta por 3, 6, 12, 18 ou 24 concursos consecutivos com a Teimosinha.<\/p>\n<p>Para jogar na loteria Caixa Lotomania, basta escolher 50 entre os 100 n\u00fameros dispon\u00edveis no volante. Ganha quem acertar 15, 16, 17, 18, 19, 20 ou nenhum n\u00famero. Se n\u00e3o quiser escolher todos os n\u00fameros, o apostador pode marcar alguns e deixar que o sistema complete o jogo. Se preferir n\u00e3o escolher nenhum, basta optar pela surpresinha: o sistema escolhe todos os n\u00fameros por ele. <\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica.<br \/>\nEle \u00e9 o \u00fanico comprovante da sua aposta. Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>Fonte: Loterias Caixa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado da Lotomania 1670 e Quina 4117: ap\u00f3s o sorteio anterior, o pr\u00eamio principal da Lotomania foi dividido entre duas apostas, e valor do pr\u00eamio principal da Lotomania de hoje foi estimado em R$ 500.000,00. No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Quina acumulou pela segunda vez consecutiva. O valor estimado do pr\u00eamio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,359,358],"tags":[],"class_list":{"0":"post-89100","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-loteria","7":"category-loto-mania","8":"category-quina","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/89100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=89100"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/89100\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=89100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=89100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=89100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}