{"id":87790,"date":"2016-06-08T19:21:37","date_gmt":"2016-06-08T22:21:37","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=87790"},"modified":"2016-06-08T16:26:44","modified_gmt":"2016-06-08T19:26:44","slug":"novela-os-dez-mandamentos-resumo-0906-zur-comemora-gravidez-de-betania","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/novela-os-dez-mandamentos-resumo-0906-zur-comemora-gravidez-de-betania\/87790","title":{"rendered":"Novela \u201cOs Dez Mandamentos\u201d resumo 09\/06: Zur comemora gravidez de Bet\u00e2nia"},"content":{"rendered":"<p> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-83604\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_nova_temporada-150x112.jpg\" alt=\"os_dez_mandamentos_nova_temporada\" width=\"150\" height=\"112\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_nova_temporada-150x112.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_nova_temporada-265x198.jpg 265w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_nova_temporada-345x261.jpg 345w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><strong><em>Novela \u201cOs Dez Mandamentos\u201d resumo 09\/06<\/em><\/strong>: Bet\u00e2nia se sente mal e \u00e9 aparada por Emma e Haya. Haya tenta ajudar Bet\u00e2nia e Emma deduz que ela est\u00e1 gr\u00e1vida. Abner, Emma e Haya ficam felizes com a not\u00edcia. Bet\u00e2nia troca olhares de preocupa\u00e7\u00e3o com Zur. Bet\u00e2nia entra nervosa na sala de descanso e conta a Zur que o filho \u00e9 dele. Zur diz que est\u00e1 feliz por ter filho com Bet\u00e2nia, que responde brava e diz que eles n\u00e3o poder\u00e3o passar a vida juntos, e que o beb\u00ea ser\u00e1 filho do rei. Tanya fala para Emma que est\u00e1 feliz com a gravidez de Bet\u00e2nia, pois acha que isso afastar\u00e1 Zur dela. Balaque entra feliz nos aposentos e conversa com Bet\u00e2nia sobre a gravidez. Os dois se abra\u00e7am, mas Bet\u00e2nia fica preocupada com a situa\u00e7\u00e3o. <\/p>\n<p>No capitulo 049(*), novela \u201cOs Dez Mandamentos\u201d, quinta-feira, 09 de junho &#8211; Bala\u00e3o amaldi\u00e7oa Balaque e a rainha. Balaque pede que os oficiais matem Bala\u00e3o, mas ele os enfeiti\u00e7a. Bet\u00e2nia se sente mal e \u00e9 aparada por Emma e Haya. Zur e Abner treinam num duelo de espadas. Abner conta que a tia passou mal a tarde e Zur sai, dizendo que far\u00e1 uma visita a ela. Leila se encontra com Adira, que oferece ajuda com os tecidos para que Rishon a deixe em paz. Silo\u00e9 entra na sala e consola Leila. Bezalel desabafa com Deborah sobre sua preocupa\u00e7\u00e3o com Leila. Jerusa discute com Simut, que mant\u00e9m a postura r\u00edgida diante dela. Balaque e Elda discutem preocupados com a maldi\u00e7\u00e3o de Bala\u00e3o e decidem chamar os sacerdotes. Haya tenta ajudar Bet\u00e2nia e Emma deduz que ela est\u00e1 gr\u00e1vida. Abner, Emma e Haya ficam felizes com a not\u00edcia. Bet\u00e2nia troca olhares de preocupa\u00e7\u00e3o com Zur. Ana e Joana conversam sobre um poss\u00edvel interesse de Ar\u00e3o em Joana. Damarina entra e as chama para verem os vestidos de Yarin e Noemi. Abir\u00e3o ensina Tales a trabalhar com m\u00f3veis. Dat\u00e3 entra no galp\u00e3o e conversa com os dois. Cor\u00e1 se junta a eles e diz que gostaria de tomar o lugar de Mois\u00e9s e Ar\u00e3o. Bet\u00e2nia entra nervosa na sala de descanso e conta a Zur que o filho \u00e9 dele. Noemi e Yarin provam os vestidos e se mostram preocupadas com a noite de n\u00fapcias. Ana, In\u00eas e Damarina contam suas experi\u00eancias. Aoliabe diz que est\u00e1 preocupado com Abigail. Simut e Jerusa brigam, mas Jerusa admite que gosta de ser cuidada por ele e fazem as pazes. Zur diz que est\u00e1 feliz por ter filho com Bet\u00e2nia, que responde brava dizendo que eles n\u00e3o poder\u00e3o passar a vida juntas e que o beb\u00ea ser\u00e1 filho do rei. Rishon fica feliz com o tecido que Leila o entregou. Dorcas percebe que foi feito por Adira, mas diz que manter\u00e1 o segredo com Leila. Tanya fala para Emma que est\u00e1 feliz com a gravidez de Bet\u00e2nia, pois acha que isso afastar\u00e1 Zur dela. Balaque entra feliz nos aposentos e conversa com Bet\u00e2nia sobre a gravidez. Balaque diz que est\u00e1 ainda mais contente pois o filho que Bet\u00e2nia carregava ia contra a maldi\u00e7\u00e3o de Bala\u00e3o. Os dois se abra\u00e7am, mas Bet\u00e2nia fica preocupada com a situa\u00e7\u00e3o. Jerusa acaba de comer e come\u00e7a a discutir com Simut a respeito do sexo do beb\u00ea. Hur e Mois\u00e9s ficam satisfeitos com o p\u00e3o feito por Miri\u00e3. Gerson pergunta quando o acampamento seguir\u00e1, Mois\u00e9s responde que aguarda a instru\u00e7\u00e3o de Deus e Hur diz que est\u00e1 preocupado com Leila. Zelofeade conforta Abigail e faz com que ela coma um peda\u00e7o de p\u00e3o. <\/p>\n<p>Talita serve sopa a Rishon, que diz estar muito feliz com os tecidos de Leila e que vender\u00e1 o filho assim que nascer. Balaque faz um jantar e conta a todos que Bet\u00e2nia est\u00e1 gr\u00e1vida. Elda desconfia da situa\u00e7\u00e3o e Zur se retira, chateado. Ana conversa com Josu\u00e9 para que ele fale com Ar\u00e3o sobre o interesse de Joana. Eleazar e In\u00eas falam sobre o Ar\u00e3o e Joana, quando Ar\u00e3o entra. Eleazar pergunta ao pai a respeito e ele responde que n\u00e3o pensa em um novo amor. Leila diz que precisa preparar roupas para o beb\u00ea, Talita fica triste e tenta disfar\u00e7ar. Elda encontra Zur e pede que ele esque\u00e7a Bet\u00e2nia e procure uma outra mulher para ficar bem. Josu\u00e9 entra na tenda para falar com Ar\u00e3o sobre Joana. Ar\u00e3o levanta e diz que resolver\u00e1 essa hist\u00f3ria. Ar\u00e3o conversa com Joana e diz que ela pode contar com a amizade dele sempre. Joana sai decepcionada e conta a Ana que Ar\u00e3o n\u00e3o quer nada com ela. <\/p>\n<p>Tanya chega para falar sobre a gravidez de Bet\u00e2nia com Zur, que se mostra incomodado. Tanya percebe e os dois se beijam. Mois\u00e9s se aproxima de Ar\u00e3o, a coluna de nuvem se move e Mois\u00e9s diz que \u00e9 hora de partir. Hebreus caminham pelo deserto liderados por Mois\u00e9s e Ar\u00e3o. O tempo passa e hebreus celebram o casamento de Calebe e Noemi e de Quenaz e Yarin. O tempo passa novamente, Silo\u00e9 v\u00ea as roupas feitas por Adira para seu filho, Lemuel faz carinho na barriga da esposa. Leila, com nove meses de gravidez, entrega os tecidos feitos por Adira para Rishon. Simut continua mimando Jerusa, que est\u00e1 com barriga de sete meses. Leila grita de dor e Dorcas faz o parto do beb\u00ea, que \u00e9 um menino. Adira ajuda o parto de Silo\u00e9, que est\u00e1 com dificuldades. Bezalel e Simut conversam, quando hebreus chegam carregando Gahiji, desfalecido. Leila termina de amamentar o beb\u00ea, quando Rishon entra e diz que o menino pertence a ele.<\/p>\n<p>(*) edi\u00e7\u00e3o da Rede Record, Novela \u201cOs Dez Mandamentos\u201d, sujeito a altera\u00e7\u00e3o de data e conte\u00fado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cOs Dez Mandamentos\u201d resumo 09\/06: Bet\u00e2nia se sente mal e \u00e9 aparada por Emma e Haya. Haya tenta ajudar Bet\u00e2nia e Emma deduz que ela est\u00e1 gr\u00e1vida. Abner, Emma e Haya ficam felizes com a not\u00edcia. Bet\u00e2nia troca olhares de preocupa\u00e7\u00e3o com Zur. Bet\u00e2nia entra nervosa na sala de descanso e conta a Zur [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":83604,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,424,371,343],"tags":[441],"class_list":{"0":"post-87790","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-os-dez-mandamentos","9":"category-rede-record","10":"category-televisao","11":"tag-resumo-do-dia","12":"entry","13":"gs-1","14":"gs-odd","15":"gs-even","16":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/os_dez_mandamentos_nova_temporada.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/87790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=87790"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/87790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/83604"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=87790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=87790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=87790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}