{"id":85282,"date":"2016-04-29T16:32:58","date_gmt":"2016-04-29T19:32:58","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=85282"},"modified":"2016-04-29T16:32:20","modified_gmt":"2016-04-29T19:32:20","slug":"lotomania-1653-sorteio-em-2904","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/lotomania-1653-sorteio-em-2904\/85282","title":{"rendered":"Lotomania 1653: sorteio em 29\/04"},"content":{"rendered":"<p>Resultado da\u00a0<em><strong>Lotomania<\/strong><\/em>\u00a01653: o valor do pr\u00eamio principal da loteria Lotomania foi estimado em R$ 1.500.000,00. No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Lotomania acumulou.\u00a0O\u00a0sorteio do concurso da Lotomania 1653 acontece nesta sexta-feira (29\/04). Os resultados da\u00a0Loteria Lotomania\u00a0s\u00e3o\u00a0divulgados no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o Paulo\/SP), ou no Caminh\u00e3o da Sorte, que esta semana est\u00e1 estacionado em Gua\u00edra, PR.<\/p>\n\n<p>Na Lotomania, voc\u00ea escolhe 50 n\u00fameros e ganha se acertar 15, 16, 17, 18, 19, 20 ou nenhum n\u00famero. Ela \u00e9 simples de apostar e f\u00e1cil de ganhar. Al\u00e9m de marcar no volante, voc\u00ea conta com outras formas de jogar. Voc\u00ea pode: apostar uma quantidade inferior a 50 n\u00fameros e deixar que o sistema complete o jogo para voc\u00ea; n\u00e3o marcar nada e deixar que o sistema escolha todos os n\u00fameros (Surpresinha) e\/ou repetir o mesmo jogo por 2 ou 4 semanas (Teimosinha).<\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica. Ele \u00e9 o \u00fanico comprovante da sua aposta.<\/p>\n<p>Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>Fonte: Loterias Caixa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado da\u00a0Lotomania\u00a01653: o valor do pr\u00eamio principal da loteria Lotomania foi estimado em R$ 1.500.000,00. No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Lotomania acumulou.\u00a0O\u00a0sorteio do concurso da Lotomania 1653 acontece nesta sexta-feira (29\/04). Os resultados da\u00a0Loteria Lotomania\u00a0s\u00e3o\u00a0divulgados no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,359],"tags":[],"class_list":{"0":"post-85282","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-loto-mania","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/85282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=85282"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/85282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/17778"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=85282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=85282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=85282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}