{"id":84936,"date":"2016-04-23T15:39:52","date_gmt":"2016-04-23T18:39:52","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=84936"},"modified":"2016-04-23T15:39:52","modified_gmt":"2016-04-23T18:39:52","slug":"mega-sena-1811-premio-de-r-25-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/mega-sena-1811-premio-de-r-25-milhoes\/84936","title":{"rendered":"Mega Sena 1811: pr\u00eamio de R$ 2,5 milh\u00f5es"},"content":{"rendered":"<p> <strong><em>Mega Sena<\/em><\/strong> 1811: uma aposta de Cabrob\u00f3, PE, ganhou o pr\u00eamio principal da loteria Caixa Mega Sena no \u00faltimo sorteio. A Mega Sena pode pagar R$ 2,5 milh\u00f5es neste s\u00e1bado (23). O sorteio do concurso 1811 da modalidade ser\u00e1 realizado, \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o Paulo\/SP), ou no Caminh\u00e3o da Sorte, que esta semana ficou em\u00a0Umuarama, PR.<\/p>\n\n<p>Na poupan\u00e7a, o pr\u00eamio Mega Sena 1811 renderia mais de R$ 18 mil por m\u00eas. O valor tamb\u00e9m seria suficiente para adquirir uma frota de 83 carros populares.<\/p>\n<p>A aposta m\u00ednima na Mega Sena 1811 custa R$ 3,50 e pode ser feita at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia) de quarta-feira em qualquer uma das mais de 13 mil casas lot\u00e9ricas do pa\u00eds. Clientes da CAIXA com acesso ao internet banking podem fazer suas apostas na Mega Sena pelo computador. Basta ter conta corrente no banco e ser maior de 18 anos. O servi\u00e7o funciona diariamente, das 8h \u00e0s 22h (hor\u00e1rio de Bras\u00edlia), exceto em dias de sorteio (quartas-feiras e s\u00e1bados), quando as apostas se encerram \u00e0s 19h, retornando \u00e0s 21h para o concurso seguinte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1811: uma aposta de Cabrob\u00f3, PE, ganhou o pr\u00eamio principal da loteria Caixa Mega Sena no \u00faltimo sorteio. A Mega Sena pode pagar R$ 2,5 milh\u00f5es neste s\u00e1bado (23). O sorteio do concurso 1811 da modalidade ser\u00e1 realizado, \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":64962,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,355],"tags":[],"class_list":{"0":"post-84936","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-mega-sena","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/mega_sena_resultado_hoje_loteria.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/84936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=84936"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/84936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/64962"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=84936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=84936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=84936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}