{"id":84396,"date":"2016-04-15T14:44:37","date_gmt":"2016-04-15T17:44:37","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=84396"},"modified":"2016-04-15T14:44:37","modified_gmt":"2016-04-15T17:44:37","slug":"dupla-sena-1481-sorteio-em-1504","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/dupla-sena-1481-sorteio-em-1504\/84396","title":{"rendered":"&#8220;Dupla Sena&#8221; 1481: sorteio em 15\/04"},"content":{"rendered":"<p>Resultado da<em><strong>\u00a0&#8220;Dupla Sena&#8221;\u00a0<\/strong><\/em>1481: no \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa &#8220;Dupla Sena&#8221; acumulou.\u00a0O\u00a0valor do pr\u00eamio principal do concurso loteria Caixa &#8220;Dupla Sena&#8221; de hoje foi estimado em R$ 2.400.000,00. O\u00a0sorteio do concurso da loteria Caixa &#8220;Dupla Sena&#8221; 1481 acontece nesta sexta-feira (15\/04).\u00a0O resultado da loteria &#8220;Dupla Sena&#8221; \u00e9\u00a0divulgado no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o Paulo\/SP).<\/p>\n\n<p>Na &#8220;Dupla Sena&#8221;, com o mesmo bilhete, voc\u00ea tem 2 chances de ganhar. Voc\u00ea escolhe de 6 a 15 n\u00fameros, entre os 50 dispon\u00edveis no volante, e participa de 2 sorteios por concurso. Se voc\u00ea n\u00e3o acertar 6 n\u00fameros no primeiro sorteio, pode ganhar no segundo. Nele, voc\u00ea ganha se acertar 4, 5 ou 6 n\u00fameros. Voc\u00ea pode deixar, ainda, que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 2, 4 ou 8 concursos consecutivos (Teimosinha).<\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica. Ele \u00e9 o \u00fanico comprovante da sua aposta. Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio.<\/p>\n<p>Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado da\u00a0&#8220;Dupla Sena&#8221;\u00a01481: no \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa &#8220;Dupla Sena&#8221; acumulou.\u00a0O\u00a0valor do pr\u00eamio principal do concurso loteria Caixa &#8220;Dupla Sena&#8221; de hoje foi estimado em R$ 2.400.000,00. O\u00a0sorteio do concurso da loteria Caixa &#8220;Dupla Sena&#8221; 1481 acontece nesta sexta-feira (15\/04).\u00a0O resultado da loteria &#8220;Dupla Sena&#8221; \u00e9\u00a0divulgado no Espa\u00e7o CAIXA Loterias (Av. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":65381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[360,335],"tags":[],"class_list":{"0":"post-84396","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dupla-sena","8":"category-loteria","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/dupla_sena_resultado.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/84396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=84396"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/84396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/65381"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=84396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=84396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=84396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}