{"id":84167,"date":"2016-04-12T15:38:25","date_gmt":"2016-04-12T18:38:25","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=84167"},"modified":"2016-04-12T15:39:00","modified_gmt":"2016-04-12T18:39:00","slug":"timemania-865-e-quina-4057-sorteio-em-1204","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/timemania-865-e-quina-4057-sorteio-em-1204\/84167","title":{"rendered":"Timemania 865 e Quina 4057: sorteio em 12\/04"},"content":{"rendered":"<p>Resultado da <em><strong>Timemania<\/strong><\/em> 865 e\u00a0<em><strong>Quina<\/strong><\/em>\u00a04057: o valor estimado do pr\u00eamio principal da loteria Caixa Quina \u00e9 de R$ 500.000,00.\u00a0No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Quina foi dividido entre 3 apostas. O valor estimado do pr\u00eamio principal da loteria Caixa Timemania chegou a R$ 2.000.000,00. No \u00faltimo sorteio o pr\u00eamio\u00a0principal da loteria Timemania tamb\u00e9m acumulou. O\u00a0sorteio dos concursos das Loterias Caixa Timemania 865 e Quina 4057 acontece na noite desta ter\u00e7a-feira (12\/04). Os resultados da Timemania\u00a0e Quina s\u00e3o divulgados no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o Paulo\/SP), ou no Caminh\u00e3o da Sorte.<\/p>\n<p>Verifique o resultado da loteria:<\/p>\n\n\n<p>A Quina permite aposta em 5, 6 ou 7 n\u00fameros, entre os 80 dispon\u00edveis. S\u00e3o 6 sorteios semanais: de segunda-feira a s\u00e1bado, ap\u00f3s \u00e0s 20h. O apostador ganha se acertar 3, 4 ou 5 n\u00fameros. E pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 3, 6, 12, 18 ou 24 concursos consecutivos (Teimosinha).O bilhete de aposta deve ser conferido em uma lot\u00e9rica. N\u00e3o existindo aposta premiada, em concurso regular, na 1\u00aa, 2\u00aa ou 3\u00aa faixa(s), o(s) valor(es) acumula(m) para o concurso seguinte, na 1\u00aa faixa de premia\u00e7\u00e3o.<\/p>\n<p>Na Timemania, seu palpite vale uma bolada. Ao todo s\u00e3o oitenta n\u00fameros e oitenta clubes de futebol, voc\u00ea escolhe dez n\u00fameros e um Time do Cora\u00e7\u00e3o. Voc\u00ea pode deixar ainda que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo por 2 ou 4 concursos consecutivos (Teimosinha).<\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica. Ele \u00e9 o \u00fanico comprovante da sua aposta.<br \/>\nOs pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>Fonte: Loterias Caixa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado da Timemania 865 e\u00a0Quina\u00a04057: o valor estimado do pr\u00eamio principal da loteria Caixa Quina \u00e9 de R$ 500.000,00.\u00a0No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Quina foi dividido entre 3 apostas. O valor estimado do pr\u00eamio principal da loteria Caixa Timemania chegou a R$ 2.000.000,00. No \u00faltimo sorteio o pr\u00eamio\u00a0principal da loteria Timemania [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":59368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,358,361],"tags":[],"class_list":{"0":"post-84167","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-quina","9":"category-time-mania","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/timemania_resultado_loteria_caixa.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/84167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=84167"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/84167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/59368"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=84167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=84167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=84167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}