{"id":80952,"date":"2016-02-13T22:17:25","date_gmt":"2016-02-14T00:17:25","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=80952"},"modified":"2016-02-15T12:13:19","modified_gmt":"2016-02-15T14:13:19","slug":"mega-sena-1790-e-quina-4008-sorteio-em-1302","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2016\/mega-sena-1790-e-quina-4008-sorteio-em-1302\/80952","title":{"rendered":"Mega Sena 1790 e Quina 4008: sorteio em 13\/02"},"content":{"rendered":"<p>Resultado da\u00a0<em><strong>Mega Sena<\/strong><\/em>\u00a01790 e\u00a0<em><strong>Quina<\/strong><\/em>\u00a04008: no \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Mega Sena acumulou. O valor do pr\u00eamio principal da Mega Sena\u00a0de hoje\u00a0foi estimado em R$ 18.000.000,00.\u00a0O valor estimado do pr\u00eamio principal da loteria Caixa Quina chegou a R$ 500.000,00.\u00a0No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Quina saiu para uma aposta de Taquari, RS.\u00a0O sorteio dos concursos das Loterias Mega Sena 1790 e Quina 4008 acontece na noite deste s\u00e1bado (13\/02). Os resultados da Mega Sena e Quina s\u00e3o divulgados no Espa\u00e7o CAIXA Loterias (Av. Cruzeiro do Sul, n\u00ba. 1.800 \u2013 Terminal Rodovi\u00e1rio do Tiet\u00ea, S\u00e3o Paulo\/SP), ou no Caminh\u00e3o da Sorte, que esta semana ficou estacionado em Fortaleza, CE.<\/p>\n<p><br \/>\n<\/p>\n<p>A loteria Quina permite aposta em 5, 6 ou 7 n\u00fameros, entre os 80 dispon\u00edveis. S\u00e3o 6 sorteios semanais: de segunda-feira a s\u00e1bado, ap\u00f3s \u00e0s 20h. O apostador ganha se acertar 3, 4 ou 5 n\u00fameros. E pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 3, 6, 12, 18 ou 24 concursos consecutivos (Teimosinha).O bilhete de aposta deve ser conferido em uma lot\u00e9rica. N\u00e3o existindo aposta premiada, em concurso regular, na 1\u00aa, 2\u00aa ou 3\u00aa faixa(s), o(s) valor(es) acumula(m) para o concurso seguinte, na 1\u00aa faixa de premia\u00e7\u00e3o.<\/p>\n<p>A Mega Sena \u00e9 a loteria que paga milh\u00f5es para o acertador dos 6 n\u00fameros sorteados. Mas quem acerta 4 ou 5 n\u00fameros tamb\u00e9m ganha. Para realizar o sonho de ser o pr\u00f3ximo milion\u00e1rio, voc\u00ea deve marcar de 6 a 15 n\u00fameros, entre os 60 dispon\u00edveis no volante. Voc\u00ea pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com a mesma aposta por 2, 4 ou 8 concursos consecutivos (Teimosinha).<\/p>\n<p>O Bol\u00e3o CAIXA \u00e9 a possibilidade que o apostador tem de realizar apostas e dividir com seus amigos ou familiares em v\u00e1rias cotas\/fra\u00e7\u00f5es, bastando preencher o campo pr\u00f3prio no volante ou solicitar diretamente ao atendente da lot\u00e9rica. Tudo com muita seguran\u00e7a e garantia de recebimento do pr\u00eamio, no caso de aposta premiada.<\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica.<\/p>\n<p>Ele \u00e9 o \u00fanico comprovante da sua aposta. Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>Fonte: Loterias Caixa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado da\u00a0Mega Sena\u00a01790 e\u00a0Quina\u00a04008: no \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Mega Sena acumulou. O valor do pr\u00eamio principal da Mega Sena\u00a0de hoje\u00a0foi estimado em R$ 18.000.000,00.\u00a0O valor estimado do pr\u00eamio principal da loteria Caixa Quina chegou a R$ 500.000,00.\u00a0No \u00faltimo sorteio o pr\u00eamio principal da loteria Caixa Quina saiu para uma aposta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":64962,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[335,355,358],"tags":[],"class_list":{"0":"post-80952","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-mega-sena","9":"category-quina","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/mega_sena_resultado_hoje_loteria.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/80952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=80952"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/80952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/64962"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=80952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=80952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=80952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}