{"id":66089,"date":"2015-02-07T20:15:58","date_gmt":"2015-02-07T22:15:58","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=66089"},"modified":"2015-02-07T20:15:58","modified_gmt":"2015-02-07T22:15:58","slug":"novela-imperio-silviano-enfrenta-a-ira-de-jose-alfredo","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2015\/novela-imperio-silviano-enfrenta-a-ira-de-jose-alfredo\/66089","title":{"rendered":"Novela \u201cImp\u00e9rio\u201d: Silviano enfrenta a ira de Jos\u00e9 Alfredo"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo-187x187.jpg\" alt=\"Imperio_Alexandre_Nero_Jose_Alfredo\" width=\"187\" height=\"187\" class=\"alignleft size-medium wp-image-60040\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo-187x187.jpg 187w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo-150x150.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo-110x110.jpg 110w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo-50x50.jpg 50w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/a><em><strong>Novela \u201cImp\u00e9rio\u201d:<\/strong><\/em> Jos\u00e9 Alfredo (Alexandre Nero) descobre que Maria Marta (Lilia Cabral) foi casada com Silviano (Othon Bastos). Sentindo-se tra\u00eddo, o Comendador pressiona Silviano para ver se ele confessa que \u00e9 Fabr\u00edcio Melga\u00e7o e est\u00e1 por tr\u00e1s das arma\u00e7\u00f5es de Maur\u00edlio (Carmo Dalla Vecchia). Silviano demontra que n\u00e3o entendeu a acusa\u00e7\u00e3o e irrita ainda mais Jos\u00e9 Alfredo. O Comendador demite Silviano e o expulsa de sua casa. Silviano reflete e pergunta se Z\u00e9 tem \u00f3dio do Fabr\u00edcio Melga\u00e7o. O Comendador diz que vai destruir o inimigo. Silviano decreta: que ven\u00e7a o mais cruel e impiedoso. Marta defende Silviano e Z\u00e9 lembra do bilhete que o ex-marido deixou para ela na Sui\u00e7a. Silviano xinga Jos\u00e9 Alfredo e a fam\u00edlia aparece para apartar a briga. <\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cImp\u00e9rio\u201d, Cristina impede Cora de falar com Jos\u00e9 Alfredo. Josu\u00e9 ouve Merival se declarar para Maria Marta. Maria Marta chora ao ver Maria \u00cdsis com Jos\u00e9 Alfredo. Noely se apresenta para Magn\u00f3lia como uma f\u00e3 e consegue um emprego com ela. Carmem desconfia de Orville. Jos\u00e9 Alfredo acredita que Merival possa ser um de seus inimigos. Maur\u00edlio instala uma c\u00e2mera na sala de Jos\u00e9 Alfredo. Silviano se recusa a sentar-se \u00e0 mesa com a fam\u00edlia de Maria Marta e todos estranham. Leonardo ouve Felipe amea\u00e7ar Enrico e avisa a Cl\u00e1udio. Jos\u00e9 Alfredo leva Maria \u00cdsis para seu quarto na mans\u00e3o. \u00c9rika e Robert\u00e3o se assustam com Noely. Cora questiona Cristina sobre a festa em homenagem ao Comendador. Cl\u00e1udio \u00e9 ferido por Felipe no lugar de Enrico. Jos\u00e9 Alfredo conversa com Merival. Maur\u00edlio assiste \u00e0 discuss\u00e3o entre Merival e Jos\u00e9 Alfredo. Felipe foge e Xana cuida de Cl\u00e1udio. Josu\u00e9 tenta convencer Jos\u00e9 Alfredo de que Maria Marta pode estar envolvida com Merival. Maria \u00cdsis enfrenta Maria Marta. Enrico avisa a Beatriz sobre o atentado e Leonardo tenta tranquiliz\u00e1-la. Jos\u00e9 Alfredo humilha Maria Marta. Leonardo leva Enrico para o hospital. Maria Clara v\u00ea Maria Marta e Silviano dan\u00e7ando juntos. Orville confessa a Jonas que n\u00e3o quer mais explorar Salvador. Cl\u00e1udio \u00e9 operado e Leonardo conforta Beatriz. Maria Clara e Jo\u00e3o Lucas descobrem que Silviano j\u00e1 foi casado. Marilda vai \u00e0 casa de Xana \u00e0 procura de Luciano. Carmem denuncia Salvador. Beatriz intima Enrico a doar sangue para Cl\u00e1udio. Jos\u00e9 Alfredo encontra Maur\u00edlio sentado em sua sala na joalheria Imp\u00e9rio. Jos\u00e9 Alfredo discute com Maur\u00edlio e Danielle fica intrigada. Enrico foge do hospital e Vicente tenta falar com ele. Magn\u00f3lia instrui Noely e Severo observa a mo\u00e7a. Pietro conta para T\u00e9o sobre o atentado contra Cl\u00e1udio. Jonas e Carmem se unem contra Orville. Cora se oferece para falar sobre o passado de Jos\u00e9 Alfredo e T\u00e9o fica animado. Maria Clara encontra Enrico e avisa a Beatriz. Cora pede que T\u00e9o a ajude a ter um encontro com Jos\u00e9 Alfredo. Tuane pede para desfilar da escola de samba. Beatriz d\u00e1 um ultimato em Enrico. Jos\u00e9 Alfredo demite Jos\u00e9 Pedro.<\/p>\n<p> Maria Marta n\u00e3o aceita a demiss\u00e3o de Jos\u00e9 Pedro. Beatriz cobra novamente uma resposta de Enrico. Amanda conversa com Jos\u00e9 Pedro. Jos\u00e9 Pedro enfrenta Jos\u00e9 Alfredo. Maria Clara e Cristina discutem. Enrico conversa com Beatriz sobre Cl\u00e1udio e ela se emociona. Maria Clara conversa com Amanda sobre Silviano. Cora conversa com T\u00e9o. Ant\u00f4nio vai ao sal\u00e3o da Xana. Xana e Luciano se encontram. Cora e T\u00e9o v\u00e3o \u00e0 joalheria Imp\u00e9rio. Helena e Orville conversam sobre Salvador. Ant\u00f4nio se declara para Nan\u00e1. Silviano avisa a Maria Marta que Jos\u00e9 Pedro saiu de casa. Danielle debocha de Jos\u00e9 Pedro. Maria Clara diz que vai dormir na casa de Xana. Cora faz uma revela\u00e7\u00e3o sobre Maria Marta para Jos\u00e9 Alfredo. Jos\u00e9 Alfredo custa acreditar no que Cora disse a ele. Jos\u00e9 Pedro e Amanda conversam ao telefone. Danielle questiona Maur\u00edlio e ele liga para o seu comparsa misterioso. Vicente serve o jantar na casa de Xana. Cristina consola Xana. Jos\u00e9 Alfredo pensa no que Cora disse e conversa com Josu\u00e9. Magn\u00f3lia visita Maria \u00cdsis. Marta mostra fotos do \u00e1lbum a Silviano. Jos\u00e9 Alfredo e Maria \u00cdsis v\u00e3o \u00e0 casa de Magn\u00f3lia. Otoniel conversa com Ismael e Manoel no bar. Ismael pede para Lorraine rasgar o cheque que recebeu de \u00c9rika. Amanda visita Jos\u00e9 Pedro no hotel. Elivaldo fala para a fam\u00edlia que vai fazer vestibular. Magn\u00f3lia conversa com Jos\u00e9 Alfredo e \u00c9rika. Xana diz a Nan\u00e1 o motivo pelo qual est\u00e1 triste. Helena amea\u00e7a Jonas. Leonardo e Amanda escolhem um ve\u00edculo para o neg\u00f3cio deles. Beatriz se declara para Cl\u00e1udio. Juliana e X\u00eania se estranham. Jos\u00e9 Alfredo enfrenta Maria Marta. Jos\u00e9 Alfredo cobra explica\u00e7\u00f5es de Maria Marta sobre seu casamento com Silviano. Du conversa com Jo\u00e3o Lucas. Antoninho convida Jos\u00e9 Alfredo para desfilar na escola Uni\u00e3o de Santa Tereza. Silviano chora olhando foto de seu casamento com Maria Marta. Josu\u00e9 e Jos\u00e9 Alfredo procuram \u00e1lbum que Maur\u00edlio deu para Maria Marta. Magn\u00f3lia decide comprar um camarote para o carnaval. \u00c9rika parabeniza T\u00e9o por sucesso da campanha de doa\u00e7\u00e3o de sangue para Cl\u00e1udio. X\u00eania arma plano para boicotar fantasia de Juju. Xana e Nan\u00e1 levam Luciano para casa de acolhimento. Maria Marta conta para Maria Clara que Jos\u00e9 Alfredo descobriu seu segredo com Silviano. Nan\u00e1 conta para Xana que quer casar com Ant\u00f4nio para adotar Luciano e Xana fica decepcionada. Maria Isis, Ant\u00f4nio e Vicente visitam Cl\u00e1udio no hospital. Maria Clara v\u00ea Jos\u00e9 Pedro conversando com Merival. T\u00e9o Pereira recebe flores.<\/p>\n<p> Jos\u00e9 Alfredo diz a Cristina que acredita que Silviano seja Fabr\u00edcio Melga\u00e7o. Jos\u00e9 Pedro acredita ter conseguido o apoio de Maria Clara para interceder por ele e Merival junto a Jos\u00e9 Alfredo. Maria Marta estranha a aus\u00eancia de Silviano. Maria Clara revela para Jos\u00e9 Pedro que Maria Marta confirmou que foi casada com o mordomo. Maria Clara alerta o pai sobre a uni\u00e3o entre Merival e Jos\u00e9 Pedro. T\u00e9o confessa seu amor por Cl\u00e1udio para \u00c9rika. Jos\u00e9 Alfredo afirma a Maria Marta que Silviano pode ser seu inimigo. X\u00eania arma contra Juliane. Elivaldo discute com Tuane. Zez\u00e9 ouve quando Du e Jo\u00e3o Lucas comentam sobre Silviano. T\u00e9o visita Cl\u00e1udio. Xana decide convidar Ant\u00f4nio para morar com ele e Nan\u00e1. Cora demonstra descontrole para Cristina ao falar de Jos\u00e9 Alfredo. Jos\u00e9 Alfredo expulsa Silviano da mans\u00e3o. Silviano confronta e ofende Jos\u00e9 Alfredo. Maria Marta defende Silviano e Maria Clara questiona a m\u00e3e. X\u00eania troca os sapatos de Juliane. Atrav\u00e9s da c\u00e2mera instalada na sala de Jos\u00e9 Alfredo, Maur\u00edlio ouve quando o Comendador afirma que o denunciar\u00e1 \u00e0 pol\u00edcia. Elivaldo e Tuane se reconciliam. Maur\u00edlio se prepara para atirar contra Jos\u00e9 Alfredo. Silviano deixa a mans\u00e3o. Maur\u00edlio liga para Marc\u00e3o. Amanda presenteia Juliane com sand\u00e1lias novas e Antoninho permite que a sambista as use no desfile. X\u00eania se irrita com o fracasso de seu plano. Cora ouve a conversa entre Maur\u00edlio e Marc\u00e3o e tenta alertar Jos\u00e9 Alfredo que ele corre risco de morte, mas o Comendador n\u00e3o lhe d\u00e1 aten\u00e7\u00e3o. Manoel e Kelly se aproximam. Enrico e Beatriz comunicam a Cl\u00e1udio que ele ter\u00e1 alta do hospital. Elivaldo, Tuane e Cristina estranham a aus\u00eancia de Cora. Todos esperam Xana se arrumar para ir para o samb\u00f3dromo. X\u00eania manda Pietro seguir a van de Juliane. Silviano chora em sua casa. Daniele tenta intimidar Jos\u00e9 Pedro e depois encontra a fantasia de Maur\u00edlio. Magn\u00f3lia e Severo se surpreendem com o camarote no samb\u00f3dromo. Cl\u00e1udio volta para casa com a fam\u00edlia. Carmem ouve Helena falar com Salvador sobre uma exposi\u00e7\u00e3o. Come\u00e7a o desfile da Unidos de Santa Teresa.<\/p>\n<p> Cristina e Elivaldo tentam acalmar Cora. Jos\u00e9 Alfredo demonstra preocupa\u00e7\u00e3o com Cora. Maur\u00edlio se irrita por causa do desfecho de seu plano. Cora tenta conversar com Cristina e Elivaldo. Come\u00e7a a apura\u00e7\u00e3o das notas das escolas de samba e os envolvidos ficam ansiosos. Ismael e Lorraine conversam sobre Silviano. Jos\u00e9 Alfredo desconfia que a pessoa que tentou mat\u00e1-lo seja o Fabr\u00edcio Melga\u00e7o. Danielle questiona Maur\u00edlio sobre o que ele fez no carnaval e ele se irrita. Enrico ajuda Cl\u00e1udio. Noely se insinua para Robert\u00e3o. Lorraine liga para \u00c9rika. Jos\u00e9 Alfredo pede um favor para Maria Marta. Carmen liga para Jonas. Maria Marta conversa com Maria Clara e Jo\u00e3o Lucas sobre Jos\u00e9 Pedro. Vicente vai ao hospital para saber not\u00edcias sobre Cora. Lorraine vai a casa de Silviano. Cora balbucia algumas palavras no hospital. Silviano convida Lorraine para um caf\u00e9. Vicente consola Cristina. Antoninho e seus amigos comemoram o resultado da apura\u00e7\u00e3o. Silviano assume para Lorraine o seu amor por Maria Marta. Jos\u00e9 Alfredo desconfia de Silviano. Danielle questiona Maur\u00edlio sobre o atentado ao Comendador. Jos\u00e9 Pedro encontra com Bruna e a leva para tomar um sorvete. Maria Clara liga para Vicente para saber de Cora, e demonstra ci\u00fames por ele estar com Cristina. Cristina resolve ir em sua casa e Vicente pega carona com ela. Antoninho come\u00e7a a festa na escola de samba. Enrico vai \u00e0 casa de Leonardo e pede desculpas a ele. Cl\u00e1udio se emociona ao falar de Enrico para Beatriz. Maria Clara faz uma surpresa para Vicente, que n\u00e3o gosta. Jos\u00e9 Alfredo consola Elivaldo ao visitar Cora no hospital. Felipe segue Enrico. Maria Marta convida Clara\u00edde para sentar \u00e0 mesa de jantar. Maria Marta liga para Jos\u00e9 Pedro e ele finge n\u00e3o se sentir bem. Helena leva Salvador para visitar a galeria de arte onde far\u00e1 sua exposi\u00e7\u00e3o. Ismael chama aten\u00e7\u00e3o de Lorraine por ela ter ido \u00e0 casa de Silviano. Jos\u00e9 Alfredo questiona Maria Marta sobre a paternidade de Jos\u00e9 Pedro e eles discutem. Salvador pede Helena em casamento. Jos\u00e9 Alfredo chama Maria \u00cdsis para dormir em sua casa. Jos\u00e9 Alfredo exige um teste de DNA dos seus filhos com Maria Marta. Jos\u00e9 Alfredo enfrenta Maria Marta. Maria \u00cdsis tenta acalmar Jos\u00e9 Alfredo. Maria Marta desabafa com Du. Lorraine mente para Ismael. Vicente encontra com Cristina e Maria Clara fica incomodada. O m\u00e9dico conversa com Cristina e Elivaldo sobre Cora. Maria Clara conversa com Jos\u00e9 Pedro. Maria Marta liga para Merival. Magn\u00f3lia aceita um convite para um evento beneficente. Helena e Orville gostam da galeria onde far\u00e3o a exposi\u00e7\u00e3o de Salvador. Felipe observa Enrico. Noely ajuda Magn\u00f3lia a fazer compras. Josu\u00e9 observa o movimento na casa de Silviano. Maria Marta conversa pessoalmente com Merival. Silviano conversa com Lorraine. Josu\u00e9 questiona Lorraine sobre a visita que ela fez a Silviano. Josu\u00e9 conta para Jos\u00e9 Alfredo que a Lorraine esteve na casa de Silviano. Jos\u00e9 Alfredo resolve fazer exame de sangue nos seus familiares e em Silviano para saber o tipo sangu\u00edneo de cada um. Maria Clara discute com Jos\u00e9 Alfredo. Antoninho enfrenta X\u00eania. Carmen \u00e9 flagrada conversando com Salvador por Helena e Orville. Vicente se incomoda com algumas atitudes de Maria Clara. Ismael questiona Lorraine. Jos\u00e9 Pedro se recusa a fazer o exame de sangue. Jos\u00e9 Alfredo vai ao hospital visitar Cora.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cImp\u00e9rio\u201d: Jos\u00e9 Alfredo (Alexandre Nero) descobre que Maria Marta (Lilia Cabral) foi casada com Silviano (Othon Bastos). Sentindo-se tra\u00eddo, o Comendador pressiona Silviano para ver se ele confessa que \u00e9 Fabr\u00edcio Melga\u00e7o e est\u00e1 por tr\u00e1s das arma\u00e7\u00f5es de Maur\u00edlio (Carmo Dalla Vecchia). Silviano demontra que n\u00e3o entendeu a acusa\u00e7\u00e3o e irrita ainda mais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":60040,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-66089","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/Imperio_Alexandre_Nero_Jose_Alfredo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/66089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=66089"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/66089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/60040"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=66089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=66089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=66089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}