{"id":62936,"date":"2014-11-27T22:01:35","date_gmt":"2014-11-28T00:01:35","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=62936"},"modified":"2014-11-27T22:01:51","modified_gmt":"2014-11-28T00:01:51","slug":"timemania-657-e-quina-3650-sorteio-em-2711","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/timemania-657-e-quina-3650-sorteio-em-2711\/62936","title":{"rendered":"Timemania 657 e Quina 3650: sorteio em 27\/11"},"content":{"rendered":"<p>Resultado da\u00a0<em><strong>Timemania<\/strong><\/em>\u00a0657 e\u00a0<em><strong>Quina<\/strong><\/em>\u00a03650: o valor estimado do pr\u00eamio principal da loteria Quina \u00e9 de R$ 500.000,00.\u00a0No \u00faltimo sorteio o pr\u00eamio principal da loteria Quina saiu para uma aposta de Gravata\u00ed, RS. No \u00faltimo sorteio o pr\u00eamio\u00a0principal da loteria Timemania acumulou. O valor estimado do pr\u00eamio principal da loteria Caixa Timemania chegou a R$ 5.600.000,00.\u00a0O\u00a0sorteio dos concursos das Loterias Caixa Timemania 657 e Quina 3650 acontece na noite desta quinta-feira (27\/11). Os resultados da Timemania\u00a0e Quina s\u00e3o\u00a0divulgados no\u00a0programa Momento da Sorte, est\u00fadio da emissora RedeTV, Osasco\/SP, no Audit\u00f3rio da CAIXA ou no Caminh\u00e3o da Sorte,\u00a0que esta semana est\u00e1 estacionado\u00a0na Av. Dr. Quinzinho, s\/n\u00ba, (Estacionamento do Supermercado Ja\u00fa), Ja\u00fa\/SP.<\/p>\n<p>Verifique o resultado da loteria:<\/p>\n\n\n<p>A Quina permite aposta em 5, 6 ou 7 n\u00fameros, entre os 80 dispon\u00edveis. S\u00e3o 6 sorteios semanais: de segunda-feira a s\u00e1bado, ap\u00f3s \u00e0s 20h. O apostador ganha se acertar 3, 4 ou 5 n\u00fameros. E pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou concorrer com o mesmo jogo por 3, 6, 12, 18 ou 24 concursos consecutivos (Teimosinha).O bilhete de aposta deve ser conferido em uma lot\u00e9rica. N\u00e3o existindo aposta premiada, em concurso regular, na 1\u00aa, 2\u00aa ou 3\u00aa faixa(s), o(s) valor(es) acumula(m) para o concurso seguinte, na 1\u00aa faixa de premia\u00e7\u00e3o.<\/p>\n<p>Na Timemania, seu palpite vale uma bolada. Ao todo s\u00e3o oitenta n\u00fameros e oitenta clubes de futebol, voc\u00ea escolhe dez n\u00fameros e um Time do Cora\u00e7\u00e3o. Voc\u00ea pode deixar ainda que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo por 2 ou 4 concursos consecutivos (Teimosinha).<\/p>\n<p>Confira o bilhete impresso em uma casa lot\u00e9rica. Ele \u00e9 o \u00fanico comprovante da sua aposta.<\/p>\n<p>Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>Fonte: Loterias Caixa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado da\u00a0Timemania\u00a0657 e\u00a0Quina\u00a03650: o valor estimado do pr\u00eamio principal da loteria Quina \u00e9 de R$ 500.000,00.\u00a0No \u00faltimo sorteio o pr\u00eamio principal da loteria Quina saiu para uma aposta de Gravata\u00ed, RS. No \u00faltimo sorteio o pr\u00eamio\u00a0principal da loteria Timemania acumulou. O valor estimado do pr\u00eamio principal da loteria Caixa Timemania chegou a R$ 5.600.000,00.\u00a0O\u00a0sorteio dos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":59368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,358,361],"tags":[],"class_list":{"0":"post-62936","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-quina","9":"category-time-mania","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/timemania_resultado_loteria_caixa.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/62936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=62936"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/62936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/59368"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=62936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=62936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=62936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}