{"id":62418,"date":"2014-11-14T15:18:45","date_gmt":"2014-11-14T17:18:45","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=62418"},"modified":"2014-11-14T15:18:45","modified_gmt":"2014-11-14T17:18:45","slug":"lotomania-1504-premio-de-r-28-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/lotomania-1504-premio-de-r-28-milhoes\/62418","title":{"rendered":"Lotomania 1504: pr\u00eamio de R$ 2,8 milh\u00f5es"},"content":{"rendered":"<p><strong><em>Lotomania<\/em><\/strong> 1504: a loteria Caixa Lotomania segue acumulada e pode pagar o pr\u00eamio de R$ 2,8 milh\u00f5es para o apostador que acertar os 20 n\u00fameros do concurso 1504. Em raz\u00e3o do feriado da Proclama\u00e7\u00e3o da Rep\u00fablica, no s\u00e1bado, o sorteio ser\u00e1 realizado nesta sexta-feira (14), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 na cidade de Realeza (PR).<\/p>\n\n<p>Na poupan\u00e7a, o pr\u00eamio Lotomania 1504 renderia quase R$ 18 mil por m\u00eas. O valor tamb\u00e9m seria suficiente para adquirir uma frota de 93 carros populares. O pre\u00e7o da aposta \u00e9 \u00fanico: R$ 1,50. Para jogar na Lotomania, basta escolher 50 entre os 100 n\u00fameros dispon\u00edveis no volante. Ganha quem acertar 16, 17, 18, 19, 20 ou nenhum n\u00famero.<\/p>\n<p>Se n\u00e3o quiser escolher todos os n\u00fameros, o apostador Lotomania 1504 pode marcar alguns e deixar que o sistema complete o jogo. Se preferir n\u00e3o escolher nenhum, basta optar pela surpresinha: o sistema escolhe todos os n\u00fameros por ele. Com o jogo pronto, os apostadores ainda podem fazer uma aposta-espelho, que consiste numa nova aposta com os 50 n\u00fameros n\u00e3o registrados no jogo original. Optando pela teimosinha, pode-se concorrer com a mesma aposta por dois, quatro ou oito concursos consecutivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotomania 1504: a loteria Caixa Lotomania segue acumulada e pode pagar o pr\u00eamio de R$ 2,8 milh\u00f5es para o apostador que acertar os 20 n\u00fameros do concurso 1504. Em raz\u00e3o do feriado da Proclama\u00e7\u00e3o da Rep\u00fablica, no s\u00e1bado, o sorteio ser\u00e1 realizado nesta sexta-feira (14), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,359],"tags":[],"class_list":["post-62418","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loteria","category-loto-mania","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/62418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=62418"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/62418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/17778"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=62418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=62418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=62418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}