{"id":58584,"date":"2014-08-19T19:13:27","date_gmt":"2014-08-19T22:13:27","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=58584"},"modified":"2014-08-19T19:13:27","modified_gmt":"2014-08-19T22:13:27","slug":"novela-geracao-brasil-brian-oficializa-pedido-de-casamento","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/novela-geracao-brasil-brian-oficializa-pedido-de-casamento\/58584","title":{"rendered":"Novela \u201cGera\u00e7\u00e3o Brasil\u201d: Brian oficializa pedido de casamento"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-54394\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg-187x187.jpg\" alt=\"geracao_brasil_novela_globo_resumo.jpg\" width=\"187\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg-187x187.jpg 187w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg-150x150.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg-110x110.jpg 110w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg-50x50.jpg 50w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/a><strong><em>Novela \u201cGera\u00e7\u00e3o Brasil\u201d:<\/em><\/strong> Vander (Bernardo Marinho) participa do programa Gera\u00e7\u00e3o Nem-Nem e acaba reprogramando Brian (L\u00e1zaro Ramos). Lara (Elisa Pinheiro) assume o trabalho para fazer Brian voltar ao normal e consegue reverter o processo e pede Lara em casamento. Logo depois, Pamela (Claudia Abreu) convida Lara para um jantar e Brian resolve oficializar o pedido de casamento na frente dos familiares. O casal assusta os familiares quando comunica que Tom\u00e1s (Gabriel Palhares) vai viajar com eles na lua de mel.<\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cGera\u00e7\u00e3o Brasil\u201d Pamela enfrenta Jonas. Lara comenta com Brian sobre a tristeza de Iracema. Gl\u00e1ucia tenta convencer S\u00edlvio a voltar para casa. Herval acerta sua viagem para Florian\u00f3polis. Jonas manda Murphy priorizar o projeto do J\u00fanior. Brian aconselha Jonas a desistir de fabricar o J\u00fanior. Dante teme problemas com Rita ao ser avisado que o Trinca de Espadas foi convidado para fazer um show. Danusa pensa em como se explicar com Jonas. Pamela afirma a Megan que n\u00e3o se arrepende de ter ficado contra Jonas. Dante convida Rita para ir \u00e0 gafieira. Iracema aceita fazer palestras no Regenera. Brian e Lara se beijam. Rita sai com Dante. Megan consegue ficar sozinha com Davi e prepara um jantar para ele. Gl\u00e1ucia aparece na mans\u00e3o Marra e avisa a Jonas que vai morar com ele. Megan e Davi se beijam novamente. Gl\u00e1ucia obriga Jonas a aceit\u00e1-la em sua casa. Linus come os ingredientes que Megan trouxe e Davi prepara um jantar para ela. Manuela diz a Fred que n\u00e3o pode ficar com Davi. Pamela n\u00e3o aceita que Gl\u00e1ucia se hospede em sua casa. Matias fica inseguro com Danusa. Davi resolve ficar com Megan. Rita e Fred sentem-se atra\u00eddos um pelo outro. Pamela vibra com a not\u00edcia de que Megan e Davi ficaram juntos. Danusa conta para Jonas que foi coagida a entregar as a\u00e7\u00f5es para Gl\u00e1ucia. Gl\u00e1ucia comenta com Aroeira que vai tirar proveito de Jonas. Brian tenta reprogramar o c\u00e9rebro de Jonas. Herval combina com D\u00e9bora seu encontro com Ver\u00f4nica. Jonas descobre que Ver\u00f4nica vai para Florian\u00f3polis. Davi ouve os elogios que Rita faz para Megan e fica pensativo. Jonas flagra Gl\u00e1ucia em seu escrit\u00f3rio. Gl\u00e1ucia disfar\u00e7a a sua presen\u00e7a no escrit\u00f3rio e enfrenta Jonas. Megan tenta seduzir Davi. Manuela pede para Arthur ajud\u00e1-la a observar B\u00f3ris. Dorothy organiza o escrit\u00f3rio de Barata. Marisa pede uma nova chance para S\u00edlvio. Jonas amea\u00e7a tirar o patroc\u00ednio da Parker TV se Pamela apresentar o J\u00fanior em seu programa. Dorothy e Susana conversam sobre o namoro de seus filhos. Vander inicia sua din\u00e2mica com Brian. Ap\u00f3s uma discuss\u00e3o com Pamela, Jonas decide sair de casa. Ver\u00f4nica chega a Florian\u00f3polis. Herval se prepara para viajar. Manuela v\u00ea Davi e Megan se beijando. Pamela afirma a Dorothy que n\u00e3o sofrer\u00e1 pelo marido. Jonas bate \u00e0 porta do quarto do hotel de Ver\u00f4nica e diz que saiu de casa. Pamela procura Herval. Pamela e Herval se beijam. Jonas pede para Ver\u00f4nica ficar com ele. Davi e Megan namoram. Manuela sofre por causa de Davi. Dante avisa a Rita que sair\u00e1 em turn\u00ea, e ela pensa em Fred. Herval e Pamela passam a noite juntos. Ernesto v\u00ea quando Pamela deixa a Plugar, e a apresentadora pede sigilo sobre sua presen\u00e7a no local. Marisa decide voltar com S\u00edlvio para o apartamento de Gl\u00e1ucia, j\u00e1 que a sogra n\u00e3o mora mais l\u00e1. Herval se arruma para viajar. Brian fica inseguro com a reprograma\u00e7\u00e3o de Vander. Pamela avisa a Davi que n\u00e3o poder\u00e1 lan\u00e7ar o J\u00fanior em seu programa. Megan, Ernesto e Davi pensam em fundar uma nova empresa para lan\u00e7ar o J\u00fanior. Herval chega ao hotel onde Ver\u00f4nica est\u00e1 hospedada.<\/p>\n<p> Herval se hospeda ao lado do quarto de Ver\u00f4nica. Lara se comove ao ver o entrosamento entre Tom\u00e1s e Shin. Davi e Megan namoram. Ernesto sonha com Pamela. Dorothy estranha a demora de Brian em aparecer com Vander para o Gera\u00e7\u00e3o Nem-Nem. Brian decide reprogramar Vander ao vivo. Pamela inicia o Gera\u00e7\u00e3o Nem-Nem sobre Vander. Ver\u00f4nica e Jonas se divertem juntos. Herval tenta surpreender Ver\u00f4nica. Manuela sofre por causa de Davi, e Fred tenta consol\u00e1-la. Davi conta para Rita sobre a nova empresa com Ernesto. Vander reprograma Brian. Pamela sofre pensando em Jonas. Herval flagra Jonas no quarto de Ver\u00f4nica. Ver\u00f4nica pede para Jonas conversar com Pamela antes de assumirem um relacionamento. Herval insiste com D\u00e9bora para que Ver\u00f4nica escreva a biografia de Jonas. Lara tenta fazer Brian voltar ao normal. Vander consegue beijar Luene. Lara prende Brian no quarto. Jonas afirma a Ver\u00f4nica que Gl\u00e1ucia n\u00e3o contar\u00e1 para Pamela sobre o caso deles. Megan tenta consolar Pamela. Ver\u00f4nica conta para Edna que Jonas vai se separar. Jesus Hernandez chega para se hospedar na mans\u00e3o Marra, e Jonas pede a Pamela que os dois finjam estar casados. Lara procura uma forma de reprogramar Brian. Moreira se preocupa com o futuro do programa Gera\u00e7\u00e3o Nem-Nem. Pamela conta para Dorothy que seu casamento acabou. Jonas avisa a Manuela que ela apresentar\u00e1 o projeto 4D para Jesus, durante um jantar em sua casa. B\u00f3ris pensa em sabotar Manuela. Lara consegue reprogramar Brian, e ele a pede em casamento. Herval afirma a D\u00e9bora que acabar\u00e1 com o romance entre Ver\u00f4nica e Jonas. Ver\u00f4nica questiona Jonas sobre sua conversa com Pamela. Ver\u00f4nica se decepciona com Jonas ao saber que ele tem que fingir estar casado com Pamela. Murphy comenta sobre o entrosamento entre Manuela e Arthur. Pamela convida Lara e sua fam\u00edlia para o jantar em homenagem a Jesus, e Brian decide oficializar seu noivado. B\u00f3ris se prepara para sabotar a apresenta\u00e7\u00e3o de Manuela e comenta com Ludmila. Rita encontra Fred na Gambiarra. Jonas fica mexido com a confian\u00e7a de Pamela. Rita se sensibiliza com os elogios de Fred. Gl\u00e1ucia n\u00e3o consegue se impor para Iracema. Manuela fica incomodada ao ver Davi com Megan. Pamela \u00e9 ir\u00f4nica com Jonas ao v\u00ea-lo irritado por causa de Davi. Brian entrega a Lara um anel semelhante ao seu. Fred tenta beijar Rita. B\u00f3ris boicota Manuela e atinge Pamela por engano.<\/p>\n<p> Ludmila teme ser descoberta como c\u00famplice, e B\u00f3ris tenta tranquiliz\u00e1-la. Manuela fica alterada, e Arthur se preocupa. Manuela desmaia no colo de Davi, que a socorre com Edmilson e Megan. Pamela come\u00e7a a mudar seu comportamento no evento. Susana e Dorothy ficam alarmadas quando Brian e Lara dizem que levar\u00e3o Tom\u00e1s para a lua de mel. Jonas fica chocado ao ver Pamela dan\u00e7ando com Ernesto. Breno avisa a Davi que Manuela pode ter sido intoxicada. Pamela faz um show e convence Jesus a firmar parceria com a Marra. Rita e Fred pensam um no outro. Gl\u00e1ucia faz intriga de Pamela para Jonas. Megan fica chateada quando Davi prefere ir embora a passar a noite com ela. Arthur cuida de Manuela. Pamela se imp\u00f5e diante de Jonas. Arthur e Manuela se beijam. Pamela seduz Jonas. Jonas leva Pamela para deitar. Manuela pensa em Davi e Arthur. Megan discute com Jonas e decide sair de casa. Rita confessa para Valdeci que quase beijou Fred. Zac V\u00edrus conta para Manuela que B\u00f3ris tamb\u00e9m boicotou Ernesto na festa Gal\u00e1xia Andr\u00f4meda. Dorothy ouve Jonas falando de Ver\u00f4nica para Brian. Megan conta para Davi sobre a briga com o pai, e Herval se anima. Jonas demite B\u00f3ris. Jonas procura Ver\u00f4nica. Rita se encontra por acaso com Fred. Dorothy conta para Pamela que Megan saiu de casa. Davi v\u00ea Manuela e Arthur se beijando. Vicente flagra Ver\u00f4nica e Jonas juntos. Ver\u00f4nica e Jonas tentam disfar\u00e7ar, mas Vicente percebe o clima entre os dois. Megan e Davi encontram com Manuela e Arthur na Gambiarra. Ludmila se insinua para Ernesto. Dorothy exige que Brian conte sobre o romance entre Jonas e Ver\u00f4nica. Mosca revela para Manuela que Megan vai morar com Davi. Ver\u00f4nica decide se afastar de Jonas por causa de Vicente. Pamela encontra Herval na Plugar. Dorothy questiona Barata sobre Ver\u00f4nica. Moreira avisa a Pamela que o Gera\u00e7\u00e3o Nem-Nem vai sair do ar. Matias conta para Danusa que se inscreveu em um curso pela internet. Rita pensa em Fred e fica desconcertada na presen\u00e7a de Dante. Pamela pede para Jonas sair de casa, e Gl\u00e1ucia implora que o filho a deixe ficar na mans\u00e3o. Manuela e Arthur ficam juntos. Ver\u00f4nica diz a Jonas que eles precisam se afastar. Herval manda para Pamela as imagens de Jonas e Ver\u00f4nica juntos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cGera\u00e7\u00e3o Brasil\u201d: Vander (Bernardo Marinho) participa do programa Gera\u00e7\u00e3o Nem-Nem e acaba reprogramando Brian (L\u00e1zaro Ramos). Lara (Elisa Pinheiro) assume o trabalho para fazer Brian voltar ao normal e consegue reverter o processo e pede Lara em casamento. Logo depois, Pamela (Claudia Abreu) convida Lara para um jantar e Brian resolve oficializar o pedido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":54394,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-58584","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/geracao_brasil_novela_globo_resumo.jpg.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/58584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=58584"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/58584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/54394"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=58584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=58584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=58584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}