{"id":58013,"date":"2014-08-05T19:06:52","date_gmt":"2014-08-05T22:06:52","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=58013"},"modified":"2014-08-05T19:06:52","modified_gmt":"2014-08-05T22:06:52","slug":"novela-boogie-oogie-rafael-sai-atras-de-sandra-e-abandona-vitoria","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/novela-boogie-oogie-rafael-sai-atras-de-sandra-e-abandona-vitoria\/58013","title":{"rendered":"Novela \u201cBoogie Oogie\u201d: Rafael sai atr\u00e1s de Sandra e abandona Vit\u00f3ria"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-56551\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo-187x187.jpg\" alt=\"novela_boogie_oogie_resumo_globo\" width=\"187\" height=\"187\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo-187x187.jpg 187w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo-150x150.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo-110x110.jpg 110w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo-50x50.jpg 50w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/a><strong><em>Novela \u201cBoogie Oogie\u201d:<\/em><\/strong> Sandra (Isis Valverde) perde o noivo Alex (Fernando Belo) em uma explos\u00e3o com o avi\u00e3o que Rafael (Marco Pigossi) estava pilotando. Sandra n\u00e3o se conforma com o acidente e sofre por ter perdido o noivo. Dias depois, Sandra descobre que Vit\u00f3ria (Bianca Bin) e Rafael preparam uma festa de noivado e fica chocada com a celebra\u00e7\u00e3o. Na festa, Rafael pede Vit\u00f3ria em casamento e Sandra interrompe o evento. Ela arma um esc\u00e2ndalo e foge. Rafael sai atr\u00e1s de Sandra e abandona Vit\u00f3ria.<\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cBoogie Oogie\u201d Sandra fica indignada com o atraso de Alex. Vit\u00f3ria acena para Rafael, sem saber que o monomotor que ele pilota est\u00e1 em pane. A caminho da Igreja, Alex avista o avi\u00e3o de Rafael caindo. Ele tenta ajudar o piloto, e o monomotor explode. No dia anterior ao desastre, Rafael tenta terminar o namoro com Vit\u00f3ria, mas ela desconversa. Rafael fica deslumbrado ao ver Sandra vestida de noiva. Susana chega de surpresa dos Estados Unidos para se hospedar na casa de In\u00eas. Leonor pergunta a Amaury de onde conhece Carlota. Pedro discute com Alex e afirma ao irm\u00e3o que ficar\u00e1 com Sandra. Augusta diz a Alex que n\u00e3o ir\u00e1 ao casamento do filho. Susana v\u00ea Fernando entrar em um hotel acompanhado de uma mulher. Susana confessa a In\u00eas que, por vingan\u00e7a, trocou o beb\u00ea de Fernando e Carlota na maternidade. De volta ao dia do casamento de Sandra e Alex, um homem consegue escapar das chamas do monomotor. Rafael consegue sobreviver \u00e0 explos\u00e3o do monomotor. Ot\u00e1vio avisa a Sandra que o padre n\u00e3o quer mais esperar para fazer o casamento. In\u00eas fica horrorizada com a revela\u00e7\u00e3o de Susana sobre a troca dos beb\u00eas. Rafael vai at\u00e9 a igreja e se surpreende ao descobrir que a noiva para a qual dar\u00e1 a not\u00edcia da morte de Alex \u00e9 Sandra. Susana diz a In\u00eas que vai contar a verdade a Fernando. Sandra se desespera com a morte de Alex. Vit\u00f3ria escuta no r\u00e1dio que o monomotor de Rafael explodiu e que h\u00e1 uma v\u00edtima n\u00e3o identificada. Ela vai ao local do acidente. Rafael deixa Vit\u00f3ria e vai atr\u00e1s de Sandra. Vit\u00f3ria resolve apressar sua festa de noivado com Rafael e pede ajuda a Madalena. Sandra despreza Pedro. Susana procura a enfermeira que a ajudou com a troca dos beb\u00eas. Susana descobre que a enfermeira Marcia foi despedida do hospital. Rafael comenta com a fam\u00edlia que n\u00e3o quer saber do noivado depois do acidente. Sandra avisa \u00e0 fam\u00edlia que vai morar no apartamento que ela e Alex montaram. Madalena aconselha Carlota a conversar com Vit\u00f3ria. Fernando trata Gilda com rispidez, para que os outros empregados de sua ag\u00eancia de turismo n\u00e3o desconfiem de que ele tem um caso com ela. Rafael conta a Serginho que Alex pediu ajuda a ele antes que o monomotor explodisse. Carlota pergunta a Amaury se Vit\u00f3ria sabe quem ele \u00e9. Rafael tenta contar a Sandra sobre o acidente, mas ela o evita. Cristina destr\u00f3i os objetos que Rafael tem da ex-namorada. Leonor pergunta a Carlota se o \u00f3dio que sente de Ricardo e Luisa tem rela\u00e7\u00e3o com o segredo que ela guarda e que foi descoberto por Vit\u00f3ria. Fernando \u00e9 abordado por uma mulher na rua.<\/p>\n<p>Susana observa Fernando com Gilda. Ela segue Fernando at\u00e9 a floricultura. In\u00eas pede ajuda a Tadeu para mandar Susana para Nova York. Susana l\u00ea o cart\u00e3o do arranjo de flores comprado por Fernando sem que ele veja. Susana descobre que Gilda \u00e9 amante de Fernando. Fernando manda flores para Gilda e assina o cart\u00e3o como Juvenal. El\u00edsio manda Pedro ficar longe de Sandra. Gilda insinua que Fernando \u00e9 pai de seu filho. Beto convida Gilda para a festa de noivado de Vit\u00f3ria. Rafael comenta com Serginho que n\u00e3o consegue tirar Sandra da cabe\u00e7a. Rafael comenta com os tios que n\u00e3o deveria ter pedido Vit\u00f3ria em casamento e decide que n\u00e3o ir\u00e1 \u00e0 festa de noivado. Cristina e Mario conseguem convencer Rafael a comparecer \u00e0 festa de noivado. Carlota fica chocada quando Daniele diz a Madalena que veio da Argentina para ficar. Tadeu comenta com Sandra sobre o noivado de Rafael, e ela pede que o rapaz a leve at\u00e9 \u00e0 festa. Fernando fica surpreso quando v\u00ea Gilda na festa com Rodrigo. Sandra finge ser amiga de inf\u00e2ncia de Vit\u00f3ria e pede a Leonor para entrar na festa. Sandra conclui que Fernando beijou Gilda, ao ver uma mancha de batom em sua roupa. Daniele convida Rodrigo para mergulhar na piscina da mans\u00e3o de Fernando. Rafael se prepara para pedir Vit\u00f3ria em casamento, quando Sandra o interrompe. Sandra arma um esc\u00e2ndalo na festa de noivado de Vit\u00f3ria, e Rafael vai atr\u00e1s dela. In\u00eas tenta convencer Susana a desistir de procurar a enfermeira. Carlota insiste com Fernando para que Daniele volte para Buenos Aires. Susana se prontifica a cuidar de Vicente enquanto In\u00eas viaja. M\u00e1rio avisa a Cristina para deixar Rafael em paz. Susana leva Vicente para o hospital, com intuito de encontrar a enfermeira. Augusta conta para Pedro que Alex a ajudava financeiramente. Sandra decide entregar suas alian\u00e7as para Augusta. Sandra sugere a Augusta que procure Fernando para resolver seus problemas financeiros.<\/p>\n<p>Sandra insiste para que Augusta procure Fernando para lhe pedir dinheiro. Fernando diz a Gilda que n\u00e3o quer Rodrigo em sua casa. Rafael e Vit\u00f3ria trocam alian\u00e7as de noivado, e o rapaz promete que esquecer\u00e1 Sandra. Fernando se nega a dar dinheiro para Augusta e acusa Sandra de oportunismo. Fernando fica furioso ao ver que Daniele convidou Rodrigo para jantar. Carlota desconfia da implic\u00e2ncia que o marido tem com Rodrigo. Madalena pede o endere\u00e7o de Sandra a Rafael. Beatriz diz \u00e0 filha que \u00e9 Rafael quem deve dar dinheiro para Augusta. Fernando v\u00ea Daniele beijando Rodrigo. Daniele ignora Fernando e vai embora com Rodrigo. Carlota confidencia a Leonor sua intui\u00e7\u00e3o de que Fernando guarda um segredo sobre Rodrigo. Susana v\u00ea as flores que Fernando comprou para a amante na casa de Celia, e tira conclus\u00f5es precipitadas. Susana diz a In\u00eas que C\u00e9lia \u00e9 amante de Fernando. Rafael procura Sandra para oferecer ajuda financeira, e ela sugere que o rapaz procure Augusta. Fernando encontra Susana na loja de Vit\u00f3ria. Fernando fica surpreso ao ver Susana na loja de sua filha. Rafael oferece ajuda para Augusta, mas \u00e9 impedido por Pedro. Daniele finge ir embora, mas se esconde na casa de Rodrigo. Carlota comenta com Leonor que Vit\u00f3ria n\u00e3o parece ser sua filha. Rafael v\u00ea Pedro beijar Sandra contra sua vontade. Susana diz a Fernando que ele a trocou por outra mulher e usou a gravidez de Carlota como pretexto. Susana mente para Fernando e diz que ir\u00e1 para Nova Iorque. Claudia diz que Ot\u00e1vio n\u00e3o obedeceu Elisio, e ele fica furioso. In\u00eas encontra Vicente desmaiado. Madalena se preocupa ao saber que Daniele n\u00e3o estava no aeroporto. Adriano conta para Ivete que viu Rafael com Sandra. Vit\u00f3ria descobre por Leda que Rafael foi visto na companhia de Sandra. Sandra se surpreende ao ver a porta de sua casa suja.<\/p>\n<p>Sandra \u00e9 obrigada a receber Vit\u00f3ria em sua casa. Rafael confessa a Serginho que ficou tocado com Sandra, mas escolhe Vit\u00f3ria. Sandra e Vit\u00f3ria descobrem que nasceram no mesmo dia. In\u00eas pede a Augusta que observe seu pai enquanto ela viaja. Susana conta a In\u00eas que encontrou M\u00e1rcia. Gilda pensa em uma forma de se livrar do convite para jantar na casa de C\u00e9lia. Claudia encomenda a In\u00eas um t\u00eanis dos Estados Unidos. Susana despista Fernando e viaja para procurar M\u00e1rcia. Gilda avisa a Rodrigo que n\u00e3o quer que ele se relacione com Daniele. Rodrigo resolve abrigar Daniele em sua casa, sem o conhecimento de Gilda. Susana chega \u00e0 casa de Marcia. Susana surpreende L\u00facia ao entrar em sua casa e perguntar por M\u00e1rcia. Vit\u00f3ria diz a Fernando que deixou Daniele no aeroporto e n\u00e3o sabe do paradeiro da prima. Gilda desconfia de que Rodrigo est\u00e1 envolvido no desaparecimento de Daniele. In\u00eas decide ir a Barra Mansa com Tadeu para encontrar M\u00e1rcia antes de Susana. M\u00e1rcia \u00e9 obrigada por In\u00eas a viajar com ela para o Rio em busca da crian\u00e7a que foi trocada por Vit\u00f3ria na maternidade. In\u00eas insiste para o pai abrigar M\u00e1rcia por um tempo em sua casa. Cristina v\u00ea Daniele com Rodrigo na porta do curso em que ela leciona e avisa a Carlota. Cristina avisa a Carlota que viu Daniele beijando Rodrigo. In\u00eas obriga M\u00e1rcia a ligar para a av\u00f3 e avisar que passar\u00e1 um tempo fora da cidade. In\u00eas insiste para que M\u00e1rcia se lembre da fam\u00edlia que ficou com a filha biol\u00f3gica de Fernando. Carlota amea\u00e7a contar que Vit\u00f3ria est\u00e1 envolvida no sumi\u00e7o de Daniele se ela n\u00e3o voltar para Buenos Aires. Daniele \u00e9 obrigada a aceitar a passagem que Carlota comprou. Susana oferece dinheiro para que Bruna pe\u00e7a demiss\u00e3o da Flower Fever. Vit\u00f3ria admite Susana como vendedora, no lugar de Bruna. Pedro sugere a In\u00eas que contrate Sandra como enfermeira de Vicente. Luisa e Ricardo chegam de Buenos Aires e v\u00e3o \u00e0 casa de Madalena para saber da filha Daniele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cBoogie Oogie\u201d: Sandra (Isis Valverde) perde o noivo Alex (Fernando Belo) em uma explos\u00e3o com o avi\u00e3o que Rafael (Marco Pigossi) estava pilotando. Sandra n\u00e3o se conforma com o acidente e sofre por ter perdido o noivo. Dias depois, Sandra descobre que Vit\u00f3ria (Bianca Bin) e Rafael preparam uma festa de noivado e fica [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":56551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-58013","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_boogie_oogie_resumo_globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/58013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=58013"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/58013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/56551"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=58013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=58013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=58013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}