{"id":57912,"date":"2014-08-03T18:47:05","date_gmt":"2014-08-03T21:47:05","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=57912"},"modified":"2014-08-03T18:47:05","modified_gmt":"2014-08-03T21:47:05","slug":"novela-imperio-teo-desconfia-que-maria-marta-roubou-lorraine","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/novela-imperio-teo-desconfia-que-maria-marta-roubou-lorraine\/57912","title":{"rendered":"Novela \u201cImp\u00e9rio\u201d: T\u00e9o desconfia que Maria Marta roubou Lorraine"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo-187x187.jpg\" alt=\"novela_imperio_resumo_globo\" width=\"187\" height=\"187\" class=\"alignleft size-medium wp-image-56550\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo-187x187.jpg 187w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo-150x150.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo-110x110.jpg 110w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo-50x50.jpg 50w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/a><strong><em>Novela \u201cImp\u00e9rio\u201d:<\/em><\/strong> T\u00e9o (Paulo Betti) descobre que Maria Marta (Lilia Cabral) deu dinheiro a Lorraine (Dani Barros) para evitar uma den\u00fancia contra Jos\u00e9 Pedro (Caio Blat) pela morte de seu irm\u00e3o. T\u00e9o liga para Maria Marta e fala sobre um atropelamento na estrada Rio-Petr\u00f3polis. Maria Marta pergunta se T\u00e9o sabe sobre o roubo do carro de Jos\u00e9 Pedro. T\u00e9o diz que sabe que n\u00e3o houve roubo e Maria Marta pede para conversar pessoalmente. No apartamento de T\u00e9o, o blogueiro conta que Lorraine est\u00e1 disposta a contar para a pol\u00edcia que uma certa dama da sociedade lhe deu dinheiro em troca de sil\u00eancio. A milion\u00e1ria diz que Lorraine precisaria provar o recebimento do dinheiro e T\u00e9o diz que a testemunha afirma ter ido \u00e0 mans\u00e3o de Petrop\u00f3lis. Maria Marta conta que n\u00e3o deu dinheiro para a chantagista e que Lorraine teria que mostrar a grana para provar o contr\u00e1rio. Como Lorraine foi assaltada, T\u00e9o percebe que Maria Marta pode ter sido a mandante do roubo. Maria Marta amea\u00e7a processar se algu\u00e9m publicar uma linha que seja a respeito deste assunto e encerra a conversa.<\/p>\n<p>Fonte Rede Globo \u2013 nos pr\u00f3ximos cap\u00edtulos da novela \u201cImp\u00e9rio\u201d Jos\u00e9 Alfredo discute com Cristina. Orville vai para o mesmo pres\u00eddio que Elivaldo. Maria Marta se surpreende ao saber que a sala de Jos\u00e9 Alfredo est\u00e1 trancada. Maria Clara mostra para o pai a nova cole\u00e7\u00e3o de joias. Merival fica incomodado com a presen\u00e7a de Maria Marta na reuni\u00e3o da empresa. Marisa tenta descobrir com Valqu\u00edria o que ela sabe sobre Maria Marta e Merival. Cl\u00e1udio vai \u00e0 casa de T\u00e9o. Jos\u00e9 Alfredo decide marcar uma reuni\u00e3o com os pais de Enrico. Cl\u00e1udio resolve terminar seu romance com Leonardo. Maria \u00cdsis se entristece quando Jos\u00e9 Alfredo desmarca o encontro. Lorraine e Ismael d\u00e3o um ultimato em \u00c9rika. Cl\u00e1udio chega em casa e \u00e9 carinhoso com Beatriz. Cora reclama de Cristina ter deixado Victor na casa de Xana. Cristina vai at\u00e9 a empresa de Jos\u00e9 Alfredo e ele se enfurece ao v\u00ea-la novamente. Cristina conta para Jos\u00e9 Alfredo que \u00e9 filha de Eliane. Lorraine fala para \u00c9rika que recebeu dinheiro de Maria Marta. Cora deixa Victor com Xana e vai para a loja Imp\u00e9rio. Cristina entrega a carta de Eliane para Jos\u00e9 Alfredo, mas Maria Marta se enfurece e a acusa de tentar dar um golpe em seu marido. Leonardo e Cl\u00e1udio pensam um no outro. \u00c9rika conta para T\u00e9o a hist\u00f3ria de Lorraine. Josu\u00e9 encontra Cristina e a leva para a loja Imp\u00e9rio. Cora v\u00ea a sobrinha sendo levada para dentro da empresa. Elivaldo encontra Orville no refeit\u00f3rio do pres\u00eddio. Xana regula o que Juliane vai levar para o marido na cadeia. Magn\u00f3lia, Severo e Robert\u00e3o armam um esc\u00e2ndalo no restaurante de Enrico. Maria Marta conta para os filhos sobre Cristina. Jos\u00e9 Alfredo avisa a Cora e Cristina que n\u00e3o dar\u00e1 dinheiro para elas. Cora insiste para que a sobrinha lute por seus direitos. Juliane \u00e9 abordada por visitantes na fila do pres\u00eddio. Tuane pede para Cristina deix\u00e1-la falar com Elivaldo antes dela. Cristina n\u00e3o cede seu lugar a Tuane. Orville conversa com sua advogada. Maria Marta tenta descobrir algo sobre Cristina com Jos\u00e9 Alfredo. Pietro tenta fazer Cora pagar pelo jornal que l\u00ea. Jos\u00e9 Alfredo manda Josu\u00e9 lev\u00e1-lo a Santa Teresa. Leonardo manda uma mensagem para Cl\u00e1udio. T\u00e9o diz para \u00c9rika se empenhar para descobrir o segredo de Cl\u00e1udio. O cerimonialista conversa com Beatriz sobre seu segredo do passado. Juliane fica nervosa ao chegar ao p\u00e1tio do pres\u00eddio. Carmem explica a Orville sua estrat\u00e9gia para o julgamento. Elivaldo incentiva Cristina a lutar por seus direitos com Jos\u00e9 Alfredo. Cora se joga na frente do carro de Jos\u00e9 Alfredo. Elivaldo afirma a Tuane que n\u00e3o deixar\u00e1 Victor ficar com ela. Jos\u00e9 Alfredo ignora Cora. Enrico flagra Cl\u00e1udio e Leonardo em sua casa.<\/p>\n<p>Leonardo e Cl\u00e1udio conseguem despistar Enrico. Um agente fala para Orville que um dos presos \u00e9 um bom pintor. Reginaldo garante a Tuane que conseguir\u00e1 a guarda de Victor. T\u00e9o marca um encontro com Maria Marta. Maria Clara, Enrico, Cl\u00e1udio e Beatriz escolhem o convite para o casamento. Cristina se surpreende com a visita de Jos\u00e9 Alfredo. Lorraine promete se vingar de Maria Marta. Marc\u00e3o sugere que Cristina pe\u00e7a dinheiro a Jos\u00e9 Alfredo. Cora sai de casa com o \u00e1lbum de fotos. Maria Marta manda Helena descobrir onde Jos\u00e9 Alfredo passou a tarde. Cora consegue entrar na loja Imp\u00e9rio. Fernando pergunta se Cristina quer exigir um exame de DNA. Vicente decide inovar na cozinha, sem a autoriza\u00e7\u00e3o de Enrico, e Ant\u00f4nio se preocupa. Enrico vai jantar em seu restaurante com Maria Clara e Beatriz. Cl\u00e1udio procura Leonardo e \u00c9rika o segue. Jos\u00e9 Alfredo encontra o \u00e1lbum de recortes. Cora se apavora ao ser presa dentro de um arm\u00e1rio por Jos\u00e9 Alfredo. Jos\u00e9 Alfredo lamenta por Eliane nunca t\u00ea-lo procurado. Cristina estranha o sumi\u00e7o de Cora. Maria Marta pergunta por seu novo motorista para Silviano. \u00c9rika descobre que Cl\u00e1udio se encontra com Leonardo. T\u00e9o fica radiante com a not\u00edcia sobre Cl\u00e1udio. Fernando pede para Cristina esquecer Jos\u00e9 Alfredo. Josu\u00e9 encontra um motorista para Maria Marta. Enrico desiste de demitir Vicente. Robert\u00e3o consegue o endere\u00e7o de T\u00e9o. Carmem recebe dinheiro de Juliane e observa a foto de Orville. Tuane se anima ao saber que a audi\u00eancia para conseguir a guarda de Victor foi marcada. Jos\u00e9 Alfredo manda o seguran\u00e7a soltar Cora pela manh\u00e3. Jo\u00e3o Lucas e Du v\u00e3o a um baile funk e s\u00e3o observados por uma gangue local. Maria Marta fica furiosa por n\u00e3o conseguir descobrir onde Jos\u00e9 Alfredo esteve. Jo\u00e3o Lucas sofre um assalto. Jo\u00e3o Lucas \u00e9 violentamente atacado pela gangue e Du fica horrorizada. T\u00e9o tenta encontrar Robert\u00e3o. Beatriz percebe Cl\u00e1udio preocupado e tenta ajud\u00e1-lo. Leonardo v\u00ea o bilhete do amante e o guarda com os outros. Vicente ajuda Jo\u00e3o Lucas e Du. Jos\u00e9 Alfredo n\u00e3o consegue dormir pensando no \u00e1lbum de recortes. Cristina se preocupa com Cora. Vicente leva Jo\u00e3o Lucas at\u00e9 Xana, que cuida de seus ferimentos. O seguran\u00e7a consegue libertar Cora do arm\u00e1rio. Maria Marta entrevista Brigel e encontra Cora nos corredores da empresa. Cristina flagra Vicente a observando. Helena n\u00e3o consegue manter Josu\u00e9 longe da empresa. Jos\u00e9 Alfredo fica furioso ao saber que Maria Marta levou Cora em casa. Lorraine tenta descobrir com \u00c9rika o endere\u00e7o de Maria Marta. Xana encontra a gangue e obriga o l\u00edder a devolver o que roubou de Jo\u00e3o Lucas. Orville fala com o preso que \u00e9 pintor. Maria Marta pede para falar com Cristina. Jos\u00e9 Alfredo e Maria Marta veem Jo\u00e3o Lucas sair da casa de Xana.<\/p>\n<p>Cora tenta impedir Maria Marta de se aproximar de Jo\u00e3o Lucas. Jos\u00e9 Alfredo leva o filho mais novo para fazer exames. Cristina decide conversar com Maria Marta. Jos\u00e9 Pedro reclama da possibilidade de ter mais uma irm\u00e3 e Maria Clara o repreende. Merival convence Jos\u00e9 Pedro a presidir uma reuni\u00e3o importante na empresa. Enrico pretende conversar com Vicente sobre algumas mudan\u00e7as no card\u00e1pio. Vicente pede o telefone de Cristina para Xana. Fernando se incomoda com a liga\u00e7\u00e3o de Vicente. Cora lembra que deixou o \u00e1lbum de recortes na \u201cImp\u00e9rio\u201d e corre para resgat\u00e1-lo. Orville tenta ver os quadros de Salvador. Juliane vai at\u00e9 uma galeria de arte e descobre que os quadros de seu marido est\u00e3o desvalorizados. Jos\u00e9 Alfredo recebe not\u00edcias de Jo\u00e3o Lucas e avisa a Maria Marta. Jos\u00e9 Alfredo se emociona quando Jo\u00e3o Lucas cochila em seus bra\u00e7os. Maria Marta vai para Santa Teresa e oferece dinheiro a Cristina. Maria Marta convence Cristina a aceitar a sua oferta. Carmem diz para Juliane pagar novamente por seus servi\u00e7os. Leonardo e Cl\u00e1udio discutem e \u00c9rika segue os dois. Maria Marta entrega um cheque para Cristina em troca de uma carta renunciando o parentesco com Jos\u00e9 Alfredo. Cora fica nervosa com a sobrinha por ela afirmar que cumprir\u00e1 a promessa que fez a Maria Marta. Cristina comemora com Xana e Nan\u00e1 a possibilidade de resolver os problemas de sua fam\u00edlia. Maria Marta mostra a carta escrita por Cristina para Jos\u00e9 Alfredo. Maria Marta n\u00e3o gosta de saber por Silviano que Lorraine tentou ligar para ela. Jos\u00e9 Alfredo marca um encontro com Maria \u00cdsis. Jos\u00e9 Alfredo guarda a carta escrita por Cristina em seu cofre. Magn\u00f3lia e Severo v\u00e3o para a casa de Maria \u00cdsis no intuito de pegar dinheiro. Cristina vai ao camel\u00f3dromo e mostra o cheque que recebeu de Maria Marta para Marc\u00e3o. Marc\u00e3o comemora com todos que trabalham no camel\u00f3dromo ao ver que Cristina vai ajud\u00e1-los a reerguer o espa\u00e7o. Jos\u00e9 Alfredo anuncia \u00e0 fam\u00edlia que ningu\u00e9m o substituir\u00e1 na empresa. Maria Marta diz a Jos\u00e9 Pedro para esperar a hora certa de assumir seu lugar na empresa. Jos\u00e9 Pedro conversa com Danielle sobre o discurso de Jos\u00e9 Alfredo. Maria Marta manda Merival tirar o irm\u00e3o de Cristina da pris\u00e3o. Magn\u00f3lia fica animada quando v\u00ea Jos\u00e9 Alfredo e Maria \u00cdsis, que tenta disfar\u00e7ar a presen\u00e7a dos pais para o Comendador. Cristina conversa com Merival sobre o seu irm\u00e3o. Tuane vai ao sal\u00e3o de Xana. Cristina diz para Elivaldo que vai tir\u00e1-lo da pris\u00e3o. Orville se surpreende com um desenho de Salvador. Juliane se lembra do tempo em que era rainha de bateria de sua escola de samba. Tuane vai ao encontro de Victor. Jos\u00e9 Pedro questiona Jos\u00e9 Alfredo sobre a sucess\u00e3o da empresa. Lorraine consegue falar com Maria Marta por telefone. Cristina fica nervosa ao ver Tuane com Victor.<\/p>\n<p>Cristina diz para Tuane que ela n\u00e3o conseguir\u00e1 a guarda de Victor. Jos\u00e9 Alfredo fala de forma r\u00edspida com Jos\u00e9 Pedro. Cora conversa com Cristina e reclama do dinheiro que ela acertou com Maria Marta. Orville observa Salvador desenhar na areia. Elivaldo diz para Orville que vai sair da cadeia. Juliane discute com Xenia, a nova madrinha de bateria da escola de samba. Helena diz para Maria Marta que ela est\u00e1 gastando muito dinheiro. Marisa entrega a Jos\u00e9 Pedro o relat\u00f3rio de despesas do \u00faltimo m\u00eas. Jos\u00e9 Alfredo elogia Maria Clara por seu trabalho como designer de joias. Orville conversa com Salvador sobre suas obras. Juliane pede dinheiro emprestado para Antoninho. Carmem se insinua para Orville. Erika vai at\u00e9 ao apartamento de Leonardo. Jos\u00e9 Alfredo chega ao restaurante de Enrico e Vicente afirma que pode fazer a comida pedida pelo Comendador. Lorraine cobra de Silviano a encomenda de Maria Marta. Leonardo se recusa a conversar com \u00c9rika. Jos\u00e9 Alfredo elogia a entrada servida no restaurante de Enrico. Lorraine aguarda ansiosa pela encomenda de Maria Marta. Xana conta para Juliane que Antoninho j\u00e1 foi garimpeiro. Merival diz para Elivaldo que consegue relaxar a pris\u00e3o dele. Reginaldo diz para a Tuane que ela conseguir\u00e1 a guarda de Victor. Maria Clara conversa com Jos\u00e9 Alfredo sobre a ambi\u00e7\u00e3o dele. Jos\u00e9 Alfredo fica encantado com a comida de Vicente e Enrico assume a autoria dos pratos. Maria Marta sugere para Danielle que ela procure um emprego. Maria \u00cdsis v\u00ea Jos\u00e9 Alfredo com Maria Clara e fica arrasada. Magn\u00f3lia pensa em convencer Maria \u00cdsis a engravidar de Jos\u00e9 Alfredo. \u00c9rika tenta convencer T\u00e9o a desistir de publicas not\u00edcias sobre o Cl\u00e1udio. Jos\u00e9 Alfredo flagra Magn\u00f3lia na casa de Maria \u00cdsis. Magn\u00f3lia inventa uma desculpa para Jos\u00e9 Alfredo, mas \u00e9 expulsa da casa de Maria \u00cdsis. Jos\u00e9 Pedro pede que Marisa lhe d\u00ea a folha de pagamento da empresa. Jos\u00e9 Alfredo fala para Maria \u00cdsis que a mulher que estava com ele \u00e9 sua filha. Magn\u00f3lia afirma que far\u00e1 Maria \u00cdsis engravidar. Jo\u00e3o Lucas garante a Du e Helena que vai descobrir quem \u00e9 a amante de seu pai. Maria Marta vai para uma delegacia e faz uma den\u00fancia dizendo que est\u00e1 sendo chantageada. Silviano e Brigel amea\u00e7am Ismael e Lorraine. Cora reclama dos gastos de Cristina. Fernando elogia Cristina. Jos\u00e9 Alfredo pergunta para Helena onde est\u00e1 Maria Marta e fica desconfiado com a resposta. Jos\u00e9 Alfredo pergunta para Jo\u00e3o Lucas quando ele vai come\u00e7ar a trabalhar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela \u201cImp\u00e9rio\u201d: T\u00e9o (Paulo Betti) descobre que Maria Marta (Lilia Cabral) deu dinheiro a Lorraine (Dani Barros) para evitar uma den\u00fancia contra Jos\u00e9 Pedro (Caio Blat) pela morte de seu irm\u00e3o. T\u00e9o liga para Maria Marta e fala sobre um atropelamento na estrada Rio-Petr\u00f3polis. Maria Marta pergunta se T\u00e9o sabe sobre o roubo do carro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":56550,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-57912","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/novela_imperio_resumo_globo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/57912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=57912"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/57912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/56550"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=57912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=57912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=57912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}