{"id":57884,"date":"2014-08-02T16:45:29","date_gmt":"2014-08-02T19:45:29","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=57884"},"modified":"2014-08-02T16:45:29","modified_gmt":"2014-08-02T19:45:29","slug":"timemania-608-premio-de-r-75-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/timemania-608-premio-de-r-75-milhoes\/57884","title":{"rendered":"Timemania 608: pr\u00eamio de R$ 7,5 milh\u00f5es"},"content":{"rendered":"<p><strong><em>Timemania<\/em><\/strong> 608: a loteria Caixa Timemania 608 segue acumulada e pode pagar o pr\u00eamio de R$ 7,5 milh\u00f5es para o apostador que acertar os sete n\u00fameros do concurso. O sorteio ser\u00e1 realizado, neste s\u00e1bado (02), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 na cidade de Marata\u00edzes (ES).<\/p>\n\n<p>Na poupan\u00e7a, o pr\u00eamio Timemania 608 renderia mais de R$ 45 mil por m\u00eas. O valor tamb\u00e9m seria suficiente para adquirir uma frota de 250 carros populares. A probabilidade de acerto na Timemania \u00e9 quase 50% maior que na Mega-Sena. Ao apostar, o cliente escolhe dez n\u00fameros no volante, e a modalidade sorteia sete, o que aumenta as chances de ganhar.<\/p>\n<p>Como jogar<\/p>\n<p>Os sorteios da Timemania s\u00e3o realizados tr\u00eas vezes por semana (ter\u00e7a-feira, quinta-feira e s\u00e1bado). Para jogar na Timemania, basta marcar 10 dentre 80 n\u00fameros e escolher um time do cora\u00e7\u00e3o. A cada concurso, s\u00e3o sorteados sete n\u00fameros e um time do cora\u00e7\u00e3o. Ganha o bilhete que tiver de tr\u00eas a sete acertos dos sete n\u00fameros sorteados. Se acertar o time do cora\u00e7\u00e3o, o apostador tamb\u00e9m ganha. As apostas podem ser feitas at\u00e9 uma hora antes do sorteio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Timemania 608: a loteria Caixa Timemania 608 segue acumulada e pode pagar o pr\u00eamio de R$ 7,5 milh\u00f5es para o apostador que acertar os sete n\u00fameros do concurso. O sorteio ser\u00e1 realizado, neste s\u00e1bado (02), \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 na cidade de Marata\u00edzes (ES). Na poupan\u00e7a, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,361],"tags":[],"class_list":{"0":"post-57884","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-time-mania","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/57884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=57884"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/57884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18093"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=57884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=57884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=57884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}