{"id":53373,"date":"2014-03-26T14:28:38","date_gmt":"2014-03-26T17:28:38","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=53373"},"modified":"2014-03-26T14:46:12","modified_gmt":"2014-03-26T17:46:12","slug":"pos-doutorado-em-engenharia-de-producao-com-bolsa-da-fapesp","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/pos-doutorado-em-engenharia-de-producao-com-bolsa-da-fapesp\/53373","title":{"rendered":"P\u00f3s-doutorado em Engenharia de Produ\u00e7\u00e3o com Bolsa da FAPESP"},"content":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 O\u00a0, um dos Centros de Pesquisa, Inova\u00e7\u00e3o e Difus\u00e3o (CEPIDs) apoiados pela FAPESP, tem uma oportunidade de <em><strong>Bolsa de P\u00f3s-Doutorado<\/strong> <\/em>para pesquisa no Instituto de Bioci\u00eancias, Letras e Ci\u00eancias Exatas (Ibilce) da Universidade Estadual Paulista (Unesp) de S\u00e3o Jos\u00e9 do Rio Preto.<\/p>\n<p>O bolsista selecionado atuar\u00e1 na \u00e1rea de Engenharia de Produ\u00e7\u00e3o em projeto intitulado \u201cModelos de otimiza\u00e7\u00e3o e m\u00e9todos de solu\u00e7\u00e3o para o suporte a decis\u00f5es no planejamento da produ\u00e7\u00e3o em f\u00e1bricas de m\u00f3veis\u201d.<\/p>\n<p>Ser\u00e1 desenvolvido um estudo de caso em f\u00e1bricas situadas nos Polos Moveleiros da regi\u00e3o noroeste do Estado de S\u00e3o Paulo. Os modelos matem\u00e1ticos e os m\u00e9todos de solu\u00e7\u00e3o propostos dever\u00e3o integrar um sistema de apoio a decis\u00f5es, desenvolvido pelo Grupo de Otimiza\u00e7\u00e3o e Modelagem da Unesp de S\u00e3o Jos\u00e9 do Rio Preto, que j\u00e1 est\u00e1 em fase de testes.<\/p>\n<p>Os candidatos devem ter profici\u00eancia e\/ou interesse em computa\u00e7\u00e3o, heur\u00edsticas, otimiza\u00e7\u00e3o cont\u00ednua e inteira e voca\u00e7\u00e3o para aplica\u00e7\u00e3o industrial, com o objetivo de desenvolver uma carreira vinculada ao setor produtivo com alto conte\u00fado de inova\u00e7\u00e3o tecnol\u00f3gica.<\/p>\n<p>Os interessados em participar da sele\u00e7\u00e3o devem encaminhar um arquivo em PDF contendo curriculum vitae com lista de publica\u00e7\u00f5es, carta de interesse \u2013 com detalhes da pesquisa passada e recente \u2013 e duas cartas de recomenda\u00e7\u00e3o para Socorro Rangel (socorro@ibilce.unesp.br).<\/p>\n<p>A data-limite para inscri\u00e7\u00f5es \u00e9 4 de maio de 2014. Mais informa\u00e7\u00f5es sobre a oportunidade:.<\/p>\n<p>O selecionado receber\u00e1 Bolsa de P\u00f3s-Doutorado da FAPESP (no valor de R$ 5.908,80 mensais) e Reserva T\u00e9cnica. A Reserva T\u00e9cnica de Bolsa de PD equivale a 15% do valor anual da bolsa e tem o objetivo de atender a despesas imprevistas e diretamente relacionadas \u00e0 atividade de pesquisa.<\/p>\n<p>Caso o bolsista de PD resida em domic\u00edlio diferente e precise se mudar para a cidade onde se localiza a institui\u00e7\u00e3o sede da pesquisa, poder\u00e1 ter direito a um Aux\u00edlio Instala\u00e7\u00e3o. Mais informa\u00e7\u00f5es sobre a Bolsa de P\u00f3s-Doutorado da FAPESP est\u00e3o dispon\u00edveis em\u00a0.<\/p>\n<p>Outras vagas de Bolsas de P\u00f3s-Doutorado, em diversas \u00e1reas do conhecimento, est\u00e3o no site FAPESP-Oportunidades, em\u00a0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 O\u00a0, um dos Centros de Pesquisa, Inova\u00e7\u00e3o e Difus\u00e3o (CEPIDs) apoiados pela FAPESP, tem uma oportunidade de Bolsa de P\u00f3s-Doutorado para pesquisa no Instituto de Bioci\u00eancias, Letras e Ci\u00eancias Exatas (Ibilce) da Universidade Estadual Paulista (Unesp) de S\u00e3o Jos\u00e9 do Rio Preto. O bolsista selecionado atuar\u00e1 na \u00e1rea de Engenharia de Produ\u00e7\u00e3o em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36244,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,351,370],"tags":[],"class_list":{"0":"post-53373","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-cursos","9":"category-inscricao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/aluno-vestibular.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/53373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=53373"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/53373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/36244"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=53373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=53373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=53373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}