{"id":5294,"date":"2009-07-13T13:45:10","date_gmt":"2009-07-13T17:45:10","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=5294"},"modified":"2009-07-27T02:09:49","modified_gmt":"2009-07-27T02:09:49","slug":"clima-tempo-forte-massa-polar-derruba-a-temperatura-na-regiao-sudeste-1207","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/clima-tempo-forte-massa-polar-derruba-a-temperatura-na-regiao-sudeste-1207\/5294","title":{"rendered":"Clima tempo: forte massa polar derruba a temperatura na regi\u00e3o Sudeste (12\/07)"},"content":{"rendered":"<p>Segundo a Climatempo, pr\u00f3xima madrugada ser\u00e1 fria e com geada no sul de Minas. A forte massa polar que entrou no Sudeste do Brasil provocou muito frio durante o amanhecer desta segunda-feira no centro-sul de Minas Gerais. No Sul de Minas, o Inmet registrou m\u00ednima de 0,6\u00baC abaixo de zero em Monte Verde. O aeroporto de Po\u00e7os de Caldas registrou 2\u00baC negativos. Em S\u00e3o Louren\u00e7o, a m\u00ednima foi de 2,5\u00baC.<br \/>\nNesta ter\u00e7a-feira, o ar frio polar ainda ser\u00e1 sentido por todo o Sudeste do Brasil. De forma geral, a tend\u00eancia \u00e9 de ligeira eleva\u00e7\u00e3o das temperaturas em rela\u00e7\u00e3o \u00e0 hoje, mas a sensa\u00e7\u00e3o de frio ainda ser\u00e1 grande. Pode gear novamente em algumas localidades mais altas do Sul de Minas Gerais.<\/p>\n<p>Fim de semana com ventania no Tri\u00e2ngulo Mineiro<br \/>\nA noite de s\u00e1bado come\u00e7ou com ventania em Uberl\u00e2ndia. Por volta das 18 horas, o aeroporto local registrou uma rajada de vento de 79,5 km\/h. Durante toda a tarde ocorreram muitas rajadas de vento no Tri\u00e2ngulo Mineiro, por conta da aproxima\u00e7\u00e3o de uma frente fria, que provocou chuva em algumas \u00e1reas da regi\u00e3o. Em Uberaba, entre meio-dia e 6 horas da tarde, o aeroporto local registrou sucessivas rajadas que variaram de 61 km\/h a 46 km\/h. Ontem tamb\u00e9m ventou forte por conta do ar polar que entrou na regi\u00e3o e, nesta segunda-feira, o dia amanheceu com vento fraco, de acordo com os meteorologistas.<\/p>\n<p>Sobre o Grupo Climatempo<\/p>\n<p>O Grupo Climatempo \u00e9 a maior empresa privada de meteorologia do pa\u00eds. Uma holding formada pela Climatempo Consultoria, Ag\u00eancia Climatempo, a TV Climatempo e a CLIMANET (Internet, servi\u00e7os de tecnologia e inform\u00e1tica). Atualmente, o Grupo Climatempo fornece conte\u00fado para os principais portais do pa\u00eds, mais de 50 retransmissoras de televis\u00e3o do Brasil, r\u00e1dios e tem cerca de mil clientes. Os dois principais segmentos atendidos s\u00e3o o de agroneg\u00f3cios e meios de comunica\u00e7\u00e3o. Al\u00e9m destes, fornece conte\u00fado meteorol\u00f3gico estrat\u00e9gico para produtoras, a ind\u00fastria eletroeletr\u00f4nica e t\u00eaxtil, com\u00e9rcio, moda e turismo, constru\u00e7\u00e3o civil, setor de energia, entre outros setores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo a Climatempo, pr\u00f3xima madrugada ser\u00e1 fria e com geada no sul de Minas. A forte massa polar que entrou no Sudeste do Brasil provocou muito frio durante o amanhecer desta segunda-feira no centro-sul de Minas Gerais. No Sul de Minas, o Inmet registrou m\u00ednima de 0,6\u00baC abaixo de zero em Monte Verde. O aeroporto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327],"tags":[],"class_list":{"0":"post-5294","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-clima","8":"entry","9":"gs-1","10":"gs-odd","11":"gs-even","12":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/5294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=5294"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/5294\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=5294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=5294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=5294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}