{"id":52914,"date":"2014-03-12T03:16:10","date_gmt":"2014-03-12T06:16:10","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=52914"},"modified":"2014-03-11T22:21:58","modified_gmt":"2014-03-12T01:21:58","slug":"mega-sena-1581-premio-de-r-25-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2014\/mega-sena-1581-premio-de-r-25-milhoes\/52914","title":{"rendered":"Mega Sena 1581: pr\u00eamio de R$ 2,5 milh\u00f5es"},"content":{"rendered":"<p><em><strong>Mega Sena<\/strong><\/em> 1581: nesta quarta-feira (12), a Mega Sena 1581 sorteia o pr\u00eamio de R$ 2,5 milh\u00f5es para o apostador que acertar os seis n\u00fameros do concurso. O sorteio ser\u00e1 realizado \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no est\u00fadio da Rede TV, em Osasco (SP), e transmitido ao vivo pelo programa Momento da Sorte. Se apenas um apostador levar o pr\u00eamio Mega Sena 1581 e aplicar todo o valor na Poupan\u00e7a da CAIXA, receber\u00e1 mensalmente cerca de R$ 15,3 mil em rendimentos. Caso prefira, pode adquirir 12 im\u00f3veis de R$ 200 mil cada, ou ainda uma frota de 83 carros populares.<\/p>\n\n<p>A aposta m\u00ednima na Mega Sena 1581 \u00e9 de R$ 2 e pode ser feita at\u00e9 as 19h da quarta-feira, em qualquer uma das lot\u00e9ricas do pa\u00eds. Clientes com acesso ao Internet Banking CAIXA (IBC) contam com a facilidade de fazer suas apostas pelo computador. Basta ter conta corrente no banco e ser maior de 18 anos.<\/p>\n<p>Lotomania:<br \/>\nA modalidade continua acumulada e pode pagar R$ 1,4 milh\u00e3o tamb\u00e9m na quarta-feira. O sorteio do concurso 1.434 ser\u00e1 realizado \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 em Arroio do Silva (SC), estacionado no Parque Municipal, \u00e0 Av. Barriga Verde.<\/p>\n<p>Para concorrer ao pr\u00eamio, basta o apostador escolher 50 n\u00fameros, dos 100 constantes do volante. Ganha quem acertar 20, 19, 18, 17, 16 ou nenhum n\u00famero. A Lotomania oferece ainda, ao apostador, a op\u00e7\u00e3o da Aposta-Espelho, na qual o sistema faz uma nova aposta selecionando os outros 50 n\u00fameros n\u00e3o registrados no jogo original. O pre\u00e7o de cada jogo \u00e9 R$ 1,50.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1581: nesta quarta-feira (12), a Mega Sena 1581 sorteia o pr\u00eamio de R$ 2,5 milh\u00f5es para o apostador que acertar os seis n\u00fameros do concurso. O sorteio ser\u00e1 realizado \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no est\u00fadio da Rede TV, em Osasco (SP), e transmitido ao vivo pelo programa Momento da Sorte. Se apenas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[335,355],"tags":[],"class_list":{"0":"post-52914","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria","8":"category-mega-sena","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/52914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=52914"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/52914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18079"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=52914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=52914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=52914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}