{"id":48322,"date":"2013-10-01T20:43:44","date_gmt":"2013-10-01T23:43:44","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=48322"},"modified":"2013-10-31T19:45:50","modified_gmt":"2013-10-31T21:45:50","slug":"novela-sangue-bom-amora-presa-apos-acidente-com-giane","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/novela-sangue-bom-amora-presa-apos-acidente-com-giane\/48322","title":{"rendered":"Novela Sangue Bom &#8211; Amora presa ap\u00f3s acidente com Giane"},"content":{"rendered":"<p><strong><em><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sangue-bom-resumo-novela-capitulo-episodio-rede-globo-proximo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-45202\" alt=\"sangue bom resumo novela capitulo episodio rede globo proximo\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sangue-bom-resumo-novela-capitulo-episodio-rede-globo-proximo-250x160.jpg\" width=\"250\" height=\"160\" \/><\/a>Novela Sangue Bom<\/em><\/strong> &#8211; Socorro (Tatiana Alvim) arruma um c\u00famplice misterioso e eles sabotam a van de Bento (Marco Pigossi). Giane (Isabelle Drummond) ficar presa dentro do carro e sofre um acidente. Socorro e seu c\u00famplice colocam Amora (Sophie Charlotte) na cena do crime e ela vai presa, acusada pelo acidente. Ap\u00f3s a confus\u00e3o, Socorro conversa com seu c\u00famplice pelo celular e Jonas (S\u00e9rgio Malheiros) ouve a conversa. Jonas espera uma distra\u00e7\u00e3o de Socorro, pega o celular, liga para o n\u00famero desconhecido e um homem atende. Jonas conta a hist\u00f3ria para Bento (Marco Pigossi), e ele come\u00e7a a investigar Socorro.<\/p>\n<p>Fonte Rede Globo \u2013 nos \u00faltimos cap\u00edtulos da\u00a0novela Sangue Bom \u00a0\u00c9rico n\u00e3o consegue se declarar e deseja boa sorte para Ver\u00f4nica em sua primeira turn\u00ea. A cantora segue viagem com Willy. Natan convida \u00c9rico para afogar as m\u00e1goas e os dois conversam em clima de paz. (Ap\u00f3s muita insist\u00eancia de Willy Bob, Ver\u00f4nica topa sair em uma longa turn\u00ea pelo Brasil inteiro na pele de Palmira Valente. Enquanto isso, \u00c9rico est\u00e1 cada vez mais certo de que a cantora \u00e9 a mulher de sua vida, embora a gata tendo dito a ele que Renata dever\u00e1 ser a escolhida. Mas o bofe tem que correr contra o tempo se quiser se declarar e ficar com Ver\u00f4nica para sempre! Ela e Willy s\u00e3o levados ao aeroporto por Natan e, j\u00e1 no sagu\u00e3o, os tr\u00eas s\u00e3o surpreendidos pela chegada de \u00c9rico gritando pelo nome de Ver\u00f4nica. A gata fica visivelmente emocionada com a supresa, mas, na \u00faltima hora, o bofe n\u00e3o consegue se declarar e apenas se despede da cantora. \u201cVer\u00f4nica, eu\u2026 Eu precisava vir, pra te dizer que\u2026 Boa sorte! Voc\u00ea merece todo o sucesso do mundo!\u201d, ele diz, hesitando em dizer o que realmente sente. Ver\u00f4nica agradece e parte na companhia de Willy Bob, deixando \u00c9rico e Natan ali. \u201cE a\u00ed, \u00c9ric\u00e3o? Vamos beber e chorar as m\u00e1goas?\u201d, sugere Natan. \u201cBora l\u00e1! Que essa mulher merece!\u201d, aceita \u00c9rico).<\/p>\n<p>Maur\u00edcio escuta quando Bento diz a Malu que ainda existe algo entre eles. O filho de Ver\u00f4nica fica perturbado e vai embora. Bento beija Malu (Malu desabafa com Mad\u00e1 sobre como Bento est\u00e1 empenhado em salvar Amora da acusa\u00e7\u00e3o pelo atentado contra Giane. \u201cPode n\u00e3o ser mais aquela paix\u00e3o cega, mas a rela\u00e7\u00e3o deles \u00e9 muito forte! Acho que \u00e9 um la\u00e7o indissol\u00favel, sabe?\u201d, lamenta Malu. Eis que Bento n\u00e3o morre t\u00e3o cedo! O gato aparece de surpresa e balan\u00e7a as estruturas emocionais de Malu. \u201cEu n\u00e3o me esqueci da gente, n\u00e3o\u2026 E quando essa tempestade passar\u2026 N\u00f3s dois vamos finalmente estar livres pra\u2026 Viver tudo aquilo que a gente n\u00e3o teve condi\u00e7\u00f5es de viver direito\u201d, dispara o florista a s\u00f3s com a gata. Maur\u00edcio chega bem na hora e, pela porta entreaberta, v\u00ea os dois com olhos no olhos. \u201cA gente ainda tem um lance muito forte, n\u00e3o adianta negar\u2026 Se n\u00e3o tivesse, c\u00ea ainda estaria namorando o Maur\u00edcio\u201d, continua Bento. Arrasado, Maur\u00edco sai apressado e sem ser notado. Apesar da insist\u00eancia de Bento, Malu fica receosa. \u201cTudo tem hora certa pra acontecer! Quando n\u00e3o acontece, \u00e9 porque n\u00e3o era pra ser!\u201d, ela analisa, dizendo em seguida que Amora sempre ser\u00e1 a mocinha em perigo e ele o pr\u00edncipe no cavalo branco que aparece para salv\u00e1-la. O florista contesta: \u201cC\u00ea acha que eu gosto ou pretendo fazer disso o objetivo da minha vida, Malu?\u201d. Mas a gata garante que ele sempre vai se sentir respons\u00e1vel pela ex-it-girl. Eis que Bento responde tascando um beij\u00e3o daqueles em Malu!).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela Sangue Bom &#8211; Socorro (Tatiana Alvim) arruma um c\u00famplice misterioso e eles sabotam a van de Bento (Marco Pigossi). Giane (Isabelle Drummond) ficar presa dentro do carro e sofre um acidente. Socorro e seu c\u00famplice colocam Amora (Sophie Charlotte) na cena do crime e ela vai presa, acusada pelo acidente. Ap\u00f3s a confus\u00e3o, Socorro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-48322","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/sangue-bom-resumo-novela-capitulo-episodio-rede-globo-proximo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/48322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=48322"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/48322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/45202"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=48322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=48322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=48322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}