{"id":4811,"date":"2009-07-07T11:31:00","date_gmt":"2009-07-07T15:31:00","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=4811"},"modified":"2009-07-07T11:31:00","modified_gmt":"2009-07-07T15:31:00","slug":"corpo-de-michael-jackson-pode-ser-levado-a-homenagem-que-sera-aberta-por-diana-ross-tmz","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/corpo-de-michael-jackson-pode-ser-levado-a-homenagem-que-sera-aberta-por-diana-ross-tmz\/4811","title":{"rendered":"Corpo de Michael Jackson pode ser levado \u00e0 homenagem que ser\u00e1 aberta por Diana Ross &#8211; TMZ"},"content":{"rendered":"<p>Quase duas semanas depois da morte de Michael Jackson, o mundo d\u00e1 adeus ao rei do pop, encerrada aos 50 anos ap\u00f3s uma parada card\u00edaca. Segundo a ABC e NBC o corpo de Michael Jackson ser\u00e1 levado ao gin\u00e1sio Staples Center nesta ter\u00e7a (7\/7) para a cerim\u00f4nia de despedida do cantor organizada pela fam\u00edlia. Antes por\u00e9m o corpo estaria sendo velado por amigos e familiares no cemit\u00e9rio Forest Lawn, em Los Angeles.<\/p>\n<p>A Fam\u00edlia de Michael Jackson comunicou a presen\u00e7a dos astros do basquete Kobe Bryant e Magic Johnson, a atriz Brooke Shields, o reverendo Al Sharpton, Martin Luther King 3\u00ba, assim como os cantores Usher, Stevie Wonder, Mariah Carey, Jennifer Hudson e o fundador da gravadora Motown, onde os Jackson Five fizeram carreira, Berry Gordy. Todos participar\u00e3o na homenagem. A homenagem deve contar ainda com apresenta\u00e7\u00e3o de Diana Ross, segundo a TMZ, grande amiga de Michael citada no testamento do cantor como tutora suplente de seus filhos.<\/p>\n<p>Diana Ross n\u00e3o confirmou a presen\u00e7a mas a atriz Elizabeth Taylor disse nesta segunda-feira que n\u00e3o est\u00e1 disposta a participar da homenagem p\u00fablica a Michael Jackson, por considerar o evento um circo. Taylor, 77, explicou, no Twitter: &#8220;Me pediram que falasse no Staples Center. N\u00e3o posso ser parte de um circo p\u00fablico. E n\u00e3o posso garantir que diria algo coerente&#8221;.<\/p>\n<p>O evento, segundo informou a rede de TV &#8220;CBS&#8221; de Los Angeles, nos Estados Unidos, ter\u00e1 dura\u00e7\u00e3o de 90 minutos. Os organizadores descartaram uma prociss\u00e3o f\u00fanebre e alguns analistas calculam que a homenagem poder\u00e1 ser o evento ao vivo mais assistido da hist\u00f3ria da televis\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quase duas semanas depois da morte de Michael Jackson, o mundo d\u00e1 adeus ao rei do pop, encerrada aos 50 anos ap\u00f3s uma parada card\u00edaca. Segundo a ABC e NBC o corpo de Michael Jackson ser\u00e1 levado ao gin\u00e1sio Staples Center nesta ter\u00e7a (7\/7) para a cerim\u00f4nia de despedida do cantor organizada pela fam\u00edlia. Antes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":{"0":"post-4811","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"entry","8":"gs-1","9":"gs-odd","10":"gs-even","11":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/4811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=4811"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/4811\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=4811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=4811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=4811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}