{"id":46232,"date":"2013-08-15T14:16:54","date_gmt":"2013-08-15T17:16:54","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=46232"},"modified":"2013-08-15T14:16:54","modified_gmt":"2013-08-15T17:16:54","slug":"amor-a-vida-alejandra-faz-ameacas-a-paulinha-no-cativeiro","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/amor-a-vida-alejandra-faz-ameacas-a-paulinha-no-cativeiro\/46232","title":{"rendered":"Amor \u00e0 Vida &#8211; Alejandra faz amea\u00e7as a Paulinha no cativeiro"},"content":{"rendered":"<p><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amor-a-vida-novela.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-45048\" alt=\"amor-a-vida-novela\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amor-a-vida-novela-250x160.jpg\" width=\"250\" height=\"160\" \/><\/a><strong><em>Amor \u00e0 Vida<\/em><\/strong> &#8211; Paulinha (Klara Castanho) est\u00e1 morrendo de medo de Alejandra (Maria Maya) ap\u00f3s ter sido sequestrada por ela e Ninho (Juliano Cazarr\u00e9). Depois de colocar a menina em um cativeiro, o foco da boliviana \u00e9 impedir que ela fuja. A bandida apela e amea\u00e7a acabar com a vida de Bruno (Malvino Salvador) se a garota tentar algo. \u201cSe n\u00e3o fizer direitinho o que eu disser, eu mando dar um jeito no seu pai. Entendeu, garota? N\u00e3o brinca comigo, porque as minhas brincadeiras s\u00e3o bem mais perigosas que as suas&#8221;, dispara Alejandra, que mostra uma foto de Bruno. Apavorada, Paulinha pede para Ninho devolv\u00ea-la, mas o hippie avisa que n\u00e3o tem mais jeito: eles v\u00e3o para o Peru. A menina acaba falando de Bruno, e os dois brigam.<\/p>\n<p>Fonte Rede Globo \u2013 Novela Amor \u00e0 Vida<\/p>\n<p>A novela Amor \u00e0 Vida conta com a dire\u00e7\u00e3o de n\u00facleo de Wolf Maya, e dire\u00e7\u00e3o geral de Mauro Mendon\u00e7a Filho. O autor Walcyr Carrasco retrata a pluralidade da grande S\u00e3o Paulo. Suas curiosidades, sotaques, g\u00edrias, dramas, moda, enfim, tudo o que a megal\u00f3pole abrange. Em seu primeiro folhetim para o hor\u00e1rio das nove, o autor d\u00e1 uma pista do que o p\u00fablico pode esperar: \u201cEmo\u00e7\u00e3o. Eu amo S\u00e3o Paulo. Sou do interior do Estado e vivo aqui desde os quinze anos. Conhe\u00e7o a cidade profundamente e quero retrat\u00e1-la em toda sua riqueza, beleza e paix\u00e3o\u201d. A nova trama traz \u00e0 tona a hist\u00f3ria da fam\u00edlia Khoury, propriet\u00e1ria do Hospital San Magno. Paolla Oliveira e Malvino Salvador encabe\u00e7am o elenco na pele dos protagonistas Paloma e Bruno. Os dois acabam se apaixonando por conta de Paula (Klara Castanho), que tem consultas peri\u00f3dicas com a pediatra. O pai de Paloma, C\u00e9sar Khoury (Antonio Fagundes), \u00e9 quem rege as regras no estabelecimento. Cl\u00ednico geral e casado com a dermatologista Pilar Khoury (Susana Vieira) desde os tempos de faculdade, procura sempre na filha o seu sucesso em vida. Parece que ele projeta seu pr\u00f3prio futuro nela. J\u00e1 a matriarca morre de amores pelo filho mais velho, F\u00e9lix Khoury (Mateus Solano), por quem o pai n\u00e3o tem tanto apre\u00e7o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amor \u00e0 Vida &#8211; Paulinha (Klara Castanho) est\u00e1 morrendo de medo de Alejandra (Maria Maya) ap\u00f3s ter sido sequestrada por ela e Ninho (Juliano Cazarr\u00e9). Depois de colocar a menina em um cativeiro, o foco da boliviana \u00e9 impedir que ela fuja. A bandida apela e amea\u00e7a acabar com a vida de Bruno (Malvino Salvador) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45048,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[379,375,343],"tags":[],"class_list":["post-46232","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novelas","category-rede-globo","category-televisao","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amor-a-vida-novela.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/46232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=46232"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/46232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/45048"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=46232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=46232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=46232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}