{"id":45742,"date":"2013-07-31T18:56:48","date_gmt":"2013-07-31T21:56:48","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=45742"},"modified":"2013-07-31T18:56:48","modified_gmt":"2013-07-31T21:56:48","slug":"flor-do-caribe-helio-ofende-os-pais","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/flor-do-caribe-helio-ofende-os-pais\/45742","title":{"rendered":"Flor do Caribe \u2013 H\u00e9lio ofende os pa\u00eds"},"content":{"rendered":"<p><!--NoAds--><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/flor-do-caribe-resumo-novela-capitulo-episodio-rede-globo-proximo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-45196\" alt=\"flor do caribe resumo novela capitulo episodio rede globo proximo\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/flor-do-caribe-resumo-novela-capitulo-episodio-rede-globo-proximo-250x160.jpg\" width=\"250\" height=\"160\" \/><\/a><strong><em>Flor do Caribe<\/em><\/strong>\u00a0\u2013\u00a0preocupados com a intima\u00e7\u00e3o que H\u00e9lio (Raphael Viana) recebeu, Donato (Luiz Carlos Vasconcelos) e Bibiana (Cyria Coentro) tentam convencer o filho a encontrar um bom advogado para defend\u00ea-lo. O executivo se ofende com a desconfian\u00e7a dos pais e garante que \u00e9 inocente. \u201cEu n\u00e3o vim pra esse mundo pra ser um perdedor med\u00edocre como voc\u00eas e terminar numa cadeia imunda! N\u00e3o vou mesmo! Voc\u00eas ainda v\u00e3o me ver no topo do mundo, bem l\u00e1 em cima, que \u00e9 o meu lugar!\u201d, solta, despejando toda sua raiva em cima deles. Sem ter para quem recorrer, o rapaz liga para Dion\u00edsio (S\u00e9rgio Mamberti) e exige que ele o tire dessa enrascada. O velho diz que H\u00e9lio ainda pode se dar muito bem e avisa que vai mandar algu\u00e9m busc\u00e1-lo em casa para lev\u00e1-lo at\u00e9 a delegacia. \u201cTalvez voc\u00ea tenha tirado a sorte grande (&#8230;) S\u00f3 depende de voc\u00ea, do tamanho da sua ambi\u00e7\u00e3o\u201d, afirma.<\/p>\n<p>Fonte Rede Globo \u2013 novela Flor do Caribe<\/p>\n<p>A hist\u00f3ria se passa na fict\u00edcia Vila dos Ventos. Flor do Caribe apresenta parte do elenco estreante na televis\u00e3o. \u00c9 o caso do ator Igor Rickli, do uruguaio Cesar Troncoso e da argentina Moro Anghileri. Na novela, amigos de inf\u00e2ncia se tornam rivais por um grande amor. Cassiano (Henri Castelli), Ester (Grazi Massafera) e Alberto (Igor Rickli) s\u00e3o amigos de inf\u00e2ncia em Flor do Caribe. Segundo a Rede Globo as temporadas de f\u00e9rias em Vila dos Ventos, uma cidade no litoral do Rio Grande do Norte, aproximaram os tr\u00eas, mas suas vidas seguiram caminhos distintos. Alberto se afasta por alguns anos para receber a forma\u00e7\u00e3o que lhe cabe como herdeiro do imp\u00e9rio constru\u00eddo pela fam\u00edlia Albuquerque, enquanto Ester e Cassiano vivem o amor que sentem um pelo outro e lutam para alcan\u00e7ar seus objetivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flor do Caribe\u00a0\u2013\u00a0preocupados com a intima\u00e7\u00e3o que H\u00e9lio (Raphael Viana) recebeu, Donato (Luiz Carlos Vasconcelos) e Bibiana (Cyria Coentro) tentam convencer o filho a encontrar um bom advogado para defend\u00ea-lo. O executivo se ofende com a desconfian\u00e7a dos pais e garante que \u00e9 inocente. \u201cEu n\u00e3o vim pra esse mundo pra ser um perdedor med\u00edocre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45196,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-45742","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/flor-do-caribe-resumo-novela-capitulo-episodio-rede-globo-proximo.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/45742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=45742"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/45742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/45196"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=45742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=45742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=45742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}