{"id":45537,"date":"2013-07-24T20:58:56","date_gmt":"2013-07-24T23:58:56","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=45537"},"modified":"2013-07-24T20:58:56","modified_gmt":"2013-07-24T23:58:56","slug":"novela-amor-a-vida-aline-e-edith-flagram-felix-com-amante","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/novela-amor-a-vida-aline-e-edith-flagram-felix-com-amante\/45537","title":{"rendered":"Novela Amor \u00e0 Vida \u2013 Aline e Edith flagram F\u00e9lix com amante"},"content":{"rendered":"<p><!--NoAds--><a href=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amor-a-vida-novela.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-45048\" alt=\"amor-a-vida-novela\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amor-a-vida-novela-250x160.jpg\" width=\"250\" height=\"160\" \/><\/a><em><strong>Novela Amor \u00e0 Vida<\/strong><\/em>\u00a0\u2013\u00a0ap\u00f3s semanas vendo F\u00e9lix (Mateus Solano) chegar tarde da noite em casa, todo feliz e contente, Edith (B\u00e1rbara Paz) resolve comprovar com seus pr\u00f3prios olhos o que o marido anda fazendo. A estilista pede a ajuda de Aline (Vanessa Gi\u00e1como) para descobrir a hora em que F\u00e9lix sai do San Magno e as duas resolvem seguir o executivo. Discretas, elas conseguem segui-lo de carro at\u00e9 uma academia. Ficam confusas, at\u00e9 que veem o executivo saindo ao lado do tal Anjinho (Lucas Malvacini). Edith puxa pela lembran\u00e7a e explica \u201c\u00c9 aquele rapaz com quem ele conversava pela Internet e chamava de Anjinho! Eu peguei os dois juntos! E o F\u00e9lix prometeu que nunca mais faria isso\u201d, lembra. Aline n\u00e3o perdoa a loira. \u201cE voc\u00ea acreditou. Ah, Edith, acorda! Seu marido d\u00e1 pinta!\u201d, dispara. Edith fica arrasada, mas pede para continuar seguindo os dois. Ao final, elas os veem entrarem na garagem do flat do modelo. A esposa de F\u00e9lix insiste em entrar para saber o que eles est\u00e3o fazendo, mas Aline diz que n\u00e3o \u00e9 preciso. \u201cPara de se enganar. Voc\u00ea sabe o que est\u00e3o fazendo. Ou o que v\u00e3o fazer. Edith, voc\u00ea n\u00e3o \u00e9 crian\u00e7a!&#8221;, afirma a secret\u00e1ria, que ainda a estimula a colocar a boca no trombone. &#8220;Bota os bichos para fora!\u201d, dispara.<\/p>\n<p>Fonte Rede Globo \u2013 Novela Amor \u00e0 Vida<\/p>\n<p>A novela Amor \u00e0 Vida conta com a dire\u00e7\u00e3o de n\u00facleo de Wolf Maya, e dire\u00e7\u00e3o geral de Mauro Mendon\u00e7a Filho. O autor Walcyr Carrasco retrata a pluralidade da grande S\u00e3o Paulo. Suas curiosidades, sotaques, g\u00edrias, dramas, moda, enfim, tudo o que a megal\u00f3pole abrange. Em seu primeiro folhetim para o hor\u00e1rio das nove, o autor d\u00e1 uma pista do que o p\u00fablico pode esperar: \u201cEmo\u00e7\u00e3o. Eu amo S\u00e3o Paulo. Sou do interior do Estado e vivo aqui desde os quinze anos. Conhe\u00e7o a cidade profundamente e quero retrat\u00e1-la em toda sua riqueza, beleza e paix\u00e3o\u201d. A nova trama traz \u00e0 tona a hist\u00f3ria da fam\u00edlia Khoury, propriet\u00e1ria do Hospital San Magno. Paolla Oliveira e Malvino Salvador encabe\u00e7am o elenco na pele dos protagonistas Paloma e Bruno. Os dois acabam se apaixonando por conta de Paula (Klara Castanho), que tem consultas peri\u00f3dicas com a pediatra. O pai de Paloma, C\u00e9sar Khoury (Antonio Fagundes), \u00e9 quem rege as regras no estabelecimento. Cl\u00ednico geral e casado com a dermatologista Pilar Khoury (Susana Vieira) desde os tempos de faculdade, procura sempre na filha o seu sucesso em vida. Parece que ele projeta seu pr\u00f3prio futuro nela. J\u00e1 a matriarca morre de amores pelo filho mais velho, F\u00e9lix Khoury (Mateus Solano), por quem o pai n\u00e3o tem tanto apre\u00e7o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novela Amor \u00e0 Vida\u00a0\u2013\u00a0ap\u00f3s semanas vendo F\u00e9lix (Mateus Solano) chegar tarde da noite em casa, todo feliz e contente, Edith (B\u00e1rbara Paz) resolve comprovar com seus pr\u00f3prios olhos o que o marido anda fazendo. A estilista pede a ajuda de Aline (Vanessa Gi\u00e1como) para descobrir a hora em que F\u00e9lix sai do San Magno e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45048,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[379,375,343],"tags":[],"class_list":{"0":"post-45537","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-novelas","8":"category-rede-globo","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/amor-a-vida-novela.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/45537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=45537"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/45537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/45048"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=45537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=45537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=45537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}