{"id":43205,"date":"2013-03-20T18:36:20","date_gmt":"2013-03-20T21:36:20","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=43205"},"modified":"2013-03-20T18:43:12","modified_gmt":"2013-03-20T21:43:12","slug":"mega-sena-1478-premio-de-r-10-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/mega-sena-1478-premio-de-r-10-milhoes\/43205","title":{"rendered":"Mega Sena 1478 &#8211; pr\u00eamio de R$ 10 milh\u00f5es"},"content":{"rendered":"<p><em><strong>Mega Sena<\/strong><\/em> 1478 &#8211; a Mega Sena desta quarta-feira (20) est\u00e1 acumulada e pode pagar R$ 10 milh\u00f5es para quem acertar os seis n\u00fameros do concurso 1478. O sorteio ser\u00e1 realizado no Caminh\u00e3o da sorte da CAIXA, que est\u00e1 estacionado na Avenida Doutor Lisboa, em frente ao Teatro Municipal de Pouso Alegre (MG). O sorteio Mega Sena 1478 ser\u00e1 transmitido ao vivo pelo programa Momento da Sorte, exibido pela TV Bandeirantes e Band News, a partir das 20h25 (hor\u00e1rio de Bras\u00edlia).<\/p>\n<p>&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n<p>Caso apenas um apostador acerte os n\u00fameros da sorte Mega Sena 1478, e aplique todo o valor do pr\u00eamio na Poupan\u00e7a da CAIXA, receber\u00e1 mais de R$ 41 mil em rendimentos por m\u00eas. Ou, se preferir, poder\u00e1 comprar 20 im\u00f3veis de R$ 500 mil cada, ou ainda uma frota de 83 carros de luxo.<\/p>\n<p>A aposta m\u00ednima na Mega Sena 1478 \u00e9 de R$ 2 e pode ser feita at\u00e9 as 19h desta quarta-feira, em qualquer uma das mais de 12.500 lot\u00e9ricas da CAIXA no pa\u00eds. Clientes com acesso ao Internet Banking CAIXA podem fazer suas apostas na Mega-Sena direto do computador. Para isso, basta ter conta corrente no banco e ser maior de 18 anos. O servi\u00e7o funciona das 8h \u00e0s 22h, exceto em dias de sorteios (quartas e s\u00e1bados), quando as apostas se encerram \u00e0s 19h, retornando \u00e0s 21h para o concurso seguinte.<\/p>\n<p>Bol\u00e3o CAIXA:<br \/>\nCom o Bol\u00e3o CAIXA, o apostador tem mais chances de ganhar na Mega-Sena. Basta reunir um grupo de amigos, escolher os n\u00fameros da sorte, marcar a quantidade de cotas e registrar o bilhete, em qualquer lot\u00e9rica do pa\u00eds. Ao ser registrada no sistema, a aposta gera um recibo para cada participante que, em caso de premia\u00e7\u00e3o, poder\u00e1 resgatar a sua parte do pr\u00eamio individualmente.<\/p>\n<p>Os bol\u00f5es para a Mega Sena 1478 t\u00eam pre\u00e7o m\u00ednimo de R$ 10, e cada cota deve ser de, pelo menos, R$ 4, sendo poss\u00edvel realizar um bol\u00e3o de no m\u00ednimo duas e no m\u00e1ximo 100 cotas. Caso o apostador adquira cotas de bol\u00f5es organizados pelas lot\u00e9ricas, poder\u00e1 pagar uma Tarifa de Servi\u00e7o adicional de at\u00e9 35% do valor da cota, a crit\u00e9rio da unidade lot\u00e9rica.<\/p>\n<p>Modalidades acumuladas:<br \/>\nA Timemania e a Lotomania tamb\u00e9m est\u00e3o acumuladas e, cada uma, vai sortear R$ 6 milh\u00f5es nesta quarta-feira. O pr\u00eamio pode garantir uma aposentadoria de mais de R$ 24 mil por m\u00eas, caso o ganhador invista todo dinheiro na Poupan\u00e7a da CAIXA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1478 &#8211; a Mega Sena desta quarta-feira (20) est\u00e1 acumulada e pode pagar R$ 10 milh\u00f5es para quem acertar os seis n\u00fameros do concurso 1478. O sorteio ser\u00e1 realizado no Caminh\u00e3o da sorte da CAIXA, que est\u00e1 estacionado na Avenida Doutor Lisboa, em frente ao Teatro Municipal de Pouso Alegre (MG). O sorteio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,355],"tags":[],"class_list":["post-43205","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-loteria","category-mega-sena","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/43205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=43205"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/43205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18079"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=43205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=43205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=43205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}