{"id":42823,"date":"2013-03-02T16:56:56","date_gmt":"2013-03-02T19:56:56","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=42823"},"modified":"2013-03-02T16:56:56","modified_gmt":"2013-03-02T19:56:56","slug":"mega-sena-1473-premio-de-r-10-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/mega-sena-1473-premio-de-r-10-milhoes\/42823","title":{"rendered":"Mega Sena 1473 &#8211; pr\u00eamio de R$ 10 milh\u00f5es"},"content":{"rendered":"<p><em><strong>Mega Sena<\/strong><\/em> 1473 &#8211;\u00a0a Caixa\u00a0estima pagar, neste s\u00e1bado (2), um pr\u00eamio de R$ 10 milh\u00f5es para o apostador que acertar os seis n\u00fameros do concurso Mega Sena 1473. O sorteio ser\u00e1 realizado \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 estacionado no Gin\u00e1sio Ayrton Senna, em Palmas (TO).<\/p>\n\n<p>Se um apostador levar o pr\u00eamio Mega Sena 1473\u00a0sozinho, poder\u00e1 se aposentar com uma renda superior a R$ 41 mil por m\u00eas, apenas investindo o pr\u00eamio na Poupan\u00e7a da CAIXA. Ou ainda, se preferir, poder\u00e1 adquirir, com o valor integral do pr\u00eamio, 20 im\u00f3veis de R$ 500 mil cada.<\/p>\n<p>A aposta m\u00ednima na Mega Sena 1473\u00a0\u00e9 de R$ 2 e pode ser efetuada at\u00e9 as 19h do s\u00e1bado, em qualquer uma das mais de 12 mil lot\u00e9ricas da CAIXA espalhadas pelo pa\u00eds. Clientes com acesso ao Internet Banking CAIXA (IBC) contam com a facilidade de fazer suas apostas no pr\u00f3prio computador. Para isso, basta ter conta no banco e ser maior de 18 anos. O servi\u00e7o fica dispon\u00edvel das 8h \u00e0s 22h (hor\u00e1rio de Bras\u00edlia), exceto em dias de sorteios (quartas e s\u00e1bados), quando as apostas se encerram \u00e0s 19h, retornando \u00e0s 21h para o concurso seguinte.<\/p>\n<p>Bol\u00e3o CAIXA:<br \/>\nApostadores podem somar for\u00e7as e concorrer ao pr\u00eamio com o Bol\u00e3o CAIXA. Para isso, basta preencher, no campo pr\u00f3prio do Bol\u00e3o, no volante, a quantidade de pessoas que participar\u00e3o da aposta. O apostador tamb\u00e9m pode solicitar diretamente ao atendente da lot\u00e9rica, informando os n\u00fameros da sorte e a quantidade de cotas desejada.<\/p>\n<p>Caso um grupo de 10 pessoas fa\u00e7a um bol\u00e3o de 10 n\u00fameros, para o sorteio deste s\u00e1bado, eles pagar\u00e3o individualmente R$ 42 e, caso sejam contemplados, cada apostador do grupo receber\u00e1 R$ 1 milh\u00e3o. O apostador tamb\u00e9m pode comprar cotas de bol\u00f5es organizados pelas lot\u00e9ricas. Nesse caso, poder\u00e1 ser cobrada uma Tarifa de Servi\u00e7o adicional de at\u00e9 35% do valor da cota.<\/p>\n<p>Novo limite para recebimento de pr\u00eamios nas Lot\u00e9ricas:<br \/>\nDesde a \u00faltima segunda-feira (25), o limite para recebimento de pr\u00eamios das Loterias da CAIXA, diretamente nas casas lot\u00e9ricas, que era de R$ 800, passou para R$ 1.710,78. O novo limite corresponde ao valor total do pr\u00eamio, e n\u00e3o ao valor individual de cada cota, em caso de a aposta ter sido efetuada na modalidade Bol\u00e3o CAIXA. A mudan\u00e7a facilita ainda mais o atendimento e a satisfa\u00e7\u00e3o dos apostadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1473 &#8211;\u00a0a Caixa\u00a0estima pagar, neste s\u00e1bado (2), um pr\u00eamio de R$ 10 milh\u00f5es para o apostador que acertar os seis n\u00fameros do concurso Mega Sena 1473. O sorteio ser\u00e1 realizado \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), no Caminh\u00e3o da Sorte da CAIXA, que est\u00e1 estacionado no Gin\u00e1sio Ayrton Senna, em Palmas (TO). Se um [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,355],"tags":[],"class_list":{"0":"post-42823","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-mega-sena","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/42823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=42823"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/42823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18079"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=42823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=42823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=42823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}