{"id":42784,"date":"2013-02-28T15:29:21","date_gmt":"2013-02-28T18:29:21","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=42784"},"modified":"2013-02-28T15:29:21","modified_gmt":"2013-02-28T18:29:21","slug":"prouni-convoca-candidatos-em-lista-de-espera","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/prouni-convoca-candidatos-em-lista-de-espera\/42784","title":{"rendered":"ProUni convoca candidatos em lista de espera"},"content":{"rendered":"<p><span style=\"font-size: 13px;\">Bras\u00edlia &#8211; As institui\u00e7\u00f5es de ensino convocam hoje (28) os candidatos em lista de espera do Programa Universidade para Todos (<\/span><em style=\"font-size: 13px;\"><strong>ProUni<\/strong><\/em><span style=\"font-size: 13px;\">). O resultado ser\u00e1 divulgado na\u00a0<\/span><a style=\"font-size: 13px;\" href=\"http:\/\/siteprouni.mec.gov.br\/\" target=\"_blank\">p\u00e1gina do ProUni<\/a><span style=\"font-size: 13px;\">, por meio da central de atendimento &#8211; telefone 0800 616161 &#8211; e nas institui\u00e7\u00f5es que participam do programa. Os candidatos ter\u00e3o de hoje a 5 de mar\u00e7o para comprovar as informa\u00e7\u00f5es. A perda do prazo ou a n\u00e3o comprova\u00e7\u00e3o dos dados implicar\u00e1, automaticamente, a reprova\u00e7\u00e3o do candidato.<\/span><\/p>\n<p>No\u00a0<a href=\"http:\/\/siteprouni.mec.gov.br\/documentacao.php\">site\u00a0do programa<\/a>\u00a0est\u00e3o detalhados os procedimentos necess\u00e1rios para obter a bolsa de estudo. Al\u00e9m de documentos pessoais, o candidato deve apresentar comprovantes de resid\u00eancia, de rendimentos e de conclus\u00e3o do ensino m\u00e9dio, entre outros.<\/p>\n<p>Aqueles que n\u00e3o forem pr\u00e9-selecionados ter\u00e3o uma segunda chance no dia 8 de mar\u00e7o, quando vai ocorrer a segunda chamada da lista de espera. Os convocados na segunda chamada devem comparecer aos locais indicados entre os dias 8 e 13 de mar\u00e7o.<\/p>\n<p>O ProUni concede bolsas de estudo integrais e parciais em institui\u00e7\u00f5es privadas de educa\u00e7\u00e3o superior para cursos de gradua\u00e7\u00e3o e sequenciais de forma\u00e7\u00e3o espec\u00edfica. Para o primeiro semestre deste ano, foram oferecidas 162.329 bolsas. O balan\u00e7o final do programa registrou 1.032.873 inscritos.<\/p>\n<p>As bolsas aumentaram em rela\u00e7\u00e3o ao n\u00famero oferecido no segundo semestre de 2012, quando foram ofertadas 90.311 &#8211; 72.018 a menos que este ano. Em rela\u00e7\u00e3o ao primeiro semestre de 2012, houve redu\u00e7\u00e3o &#8211; foram oferecidas no per\u00edodo 195.030 bolsas, 32.701 a mais que neste ano.<\/p>\n<p>Tem direito \u00e0 bolsa integral o candidato com renda familiar\u00a0per capita\u00a0at\u00e9 um sal\u00e1rio m\u00ednimo e meio (R$ 1.017). Para as bolsas parciais (50% da mensalidade), a renda familiar deve ser at\u00e9 tr\u00eas sal\u00e1rios m\u00ednimos (R$ 2.034) por pessoa.<\/p>\n<p>Mariana Tokarnia<br \/>\nRep\u00f3rter da Ag\u00eancia Brasil<\/p>\n<p>Edi\u00e7\u00e3o: Gra\u00e7a Adjuto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia &#8211; As institui\u00e7\u00f5es de ensino convocam hoje (28) os candidatos em lista de espera do Programa Universidade para Todos (ProUni). O resultado ser\u00e1 divulgado na\u00a0p\u00e1gina do ProUni, por meio da central de atendimento &#8211; telefone 0800 616161 &#8211; e nas institui\u00e7\u00f5es que participam do programa. Os candidatos ter\u00e3o de hoje a 5 de mar\u00e7o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23011,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,295],"tags":[],"class_list":["post-42784","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-inscricao","category-vestibular","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/prouni-inscricao.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/42784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=42784"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/42784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/23011"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=42784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=42784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=42784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}