{"id":41958,"date":"2013-01-07T17:17:32","date_gmt":"2013-01-07T19:17:32","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=41958"},"modified":"2013-01-07T17:17:32","modified_gmt":"2013-01-07T19:17:32","slug":"receita-libera-consulta-ao-primeiro-lote-da-malha-fina-do-ir-2012","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/receita-libera-consulta-ao-primeiro-lote-da-malha-fina-do-ir-2012\/41958","title":{"rendered":"Receita libera consulta ao primeiro lote da malha fina do IR 2012"},"content":{"rendered":"<p>Bras\u00edlia &#8211; A <em><strong>Receita<\/strong><\/em> Federal libera amanh\u00e3 (8) a consulta ao primeiro lote de restitui\u00e7\u00f5es do Imposto de Renda Pessoa F\u00edsica 2012 da malha fina. A consulta estar\u00e1 dispon\u00edvel no site da Receita. Ser\u00e3o liberadas tamb\u00e9m declara\u00e7\u00f5es dos exerc\u00edcios de 2011, 2010, 2009 e 2008. O dinheiro ser\u00e1 depositado no banco no dia 15 de janeiro de 2013.<\/p>\n<p>Para o exerc\u00edcio de 2012, ser\u00e3o creditadas restitui\u00e7\u00f5es a um total de 79.484 contribuintes, com corre\u00e7\u00e3o de 6%. Do exerc\u00edcio de 2011, ser\u00e3o creditadas restitui\u00e7\u00f5es para um total de 11.513 contribuintes, com corre\u00e7\u00e3o de 16,75 %.<\/p>\n<p>De 2010, ser\u00e3o 6.781 restitui\u00e7\u00f5es, com corre\u00e7\u00e3o de 26,9% e de 2009, o n\u00famero chega a 4.613 , corrigidas em 35,36%. Do exerc\u00edcio de 2008, ser\u00e3o creditadas restitui\u00e7\u00f5es para um total de 4.703 contribuintes, com corre\u00e7\u00e3o de 47,43%.<\/p>\n<p>Para saber se teve a declara\u00e7\u00e3o liberada, o contribuinte dever\u00e1 acessar a\u00a0<a href=\"http:\/\/www.receita.fazenda.gov.br\/\" target=\"_blank\">p\u00e1gina da Receita\u00a0<\/a>na\u00a0<span style=\"font-size: medium;\">i<\/span>nternet, ou ligar para o Receitafone, 146. Outra alternativa para as pessoas f\u00edsicas, informou a Receita, \u00e9 utilizar um aplicativo para tablets e smartphones que permite, entre outras coisas, a consulta das restitui\u00e7\u00f5es desde 1999 e a situa\u00e7\u00e3o cadastral de inscri\u00e7\u00e3o no CPF.<\/p>\n<p>A Receita lembra que a restitui\u00e7\u00e3o ficar\u00e1 dispon\u00edvel no banco durante um ano. Se o contribuinte n\u00e3o fizer o resgate nesse prazo, dever\u00e1 requer\u00ea-la por meio da internet, mediante o Formul\u00e1rio Eletr\u00f4nico.<\/p>\n<p>Caso o valor n\u00e3o seja creditado, o contribuinte poder\u00e1 procurar qualquer ag\u00eancia do Banco do Brasil ou ligar para a Central de Atendimento do banco por meio do telefone 4004-0001 (capitais), 0800-729-0001 (demais localidades) e 0800-729-0088 (deficientes auditivos), para agendar o cr\u00e9dito em conta-corrente ou poupan\u00e7a, em qualquer banco.<\/p>\n<p>Daniel Lima<br \/>\nRep\u00f3rter da Ag\u00eancia Brasil<br \/>\nEdi\u00e7\u00e3o: Gra\u00e7a Adjuto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia &#8211; A Receita Federal libera amanh\u00e3 (8) a consulta ao primeiro lote de restitui\u00e7\u00f5es do Imposto de Renda Pessoa F\u00edsica 2012 da malha fina. A consulta estar\u00e1 dispon\u00edvel no site da Receita. Ser\u00e3o liberadas tamb\u00e9m declara\u00e7\u00f5es dos exerc\u00edcios de 2011, 2010, 2009 e 2008. O dinheiro ser\u00e1 depositado no banco no dia 15 de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,7],"tags":[],"class_list":{"0":"post-41958","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-economia","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/receita-federal-irpf-2010.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/41958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=41958"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/41958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/23889"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=41958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=41958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=41958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}