{"id":41917,"date":"2013-01-04T11:42:15","date_gmt":"2013-01-04T13:42:15","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=41917"},"modified":"2013-01-09T20:51:32","modified_gmt":"2013-01-09T22:51:32","slug":"pos-em-psicologia-na-unesp-abre-inscricoes-em-fevereiro","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2013\/pos-em-psicologia-na-unesp-abre-inscricoes-em-fevereiro\/41917","title":{"rendered":"P\u00f3s em Psicologia na Unesp abre inscri\u00e7\u00f5es em fevereiro"},"content":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 O Programa de <em><strong>P\u00f3s-gradua\u00e7\u00e3o<\/strong><\/em> em Psicologia da Faculdade de Ci\u00eancias e Letras da Universidade Estadual Paulista (<em><strong>Unesp<\/strong><\/em>), no campus de Assis, estar\u00e1 com as inscri\u00e7\u00f5es abertas para mestrado e doutorado entre 25 de fevereiro e 12 de mar\u00e7o.<\/p>\n<p>Entre os objetivos do programa, est\u00e3o o desenvolvimento de pesquisas na \u00e1rea a partir de fen\u00f4menos psicol\u00f3gicos concretamente constitu\u00eddos na realidade social e a cria\u00e7\u00e3o de um polo de produ\u00e7\u00e3o cient\u00edfica, forma\u00e7\u00e3o de pesquisadores e difus\u00e3o de conhecimentos da \u00e1rea de Psicologia na regi\u00e3o de Assis.<\/p>\n<p>Ap\u00f3s uma reformula\u00e7\u00e3o feita a partir do ano 2000, o curr\u00edculo do programa de p\u00f3s se organizou sob a \u00e1rea de concentra\u00e7\u00e3o Psicologia e Sociedade e conta com duas linhas de pesquisa: Inf\u00e2ncia e Realidade Brasileira e Subjetividade e Sa\u00fade Coletiva.<\/p>\n<p>O edital est\u00e1 dispon\u00edvel em:\u00a0<a href=\"http:\/\/sgcd.assis.unesp.br\/#669,682\" target=\"_blank\">http:\/\/sgcd.assis.unesp.br\/#669,682<\/a><\/p>\n<p>&#8212;<\/p>\n<p>1.1. O Coordenador do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Psicologia da Faculdade de<br \/>\nCi\u00eancias e Letras \u2013 UNESP\/Campus de Assis, no uso de suas atribui\u00e7\u00f5es legais, torna<br \/>\np\u00fablico e estabelece as normas do processo seletivo para o preenchimento de vagas<br \/>\ndos cursos de Mestrado Acad\u00eamico e Doutorado do Programa de P\u00f3s-Gradua\u00e7\u00e3o em<br \/>\nPsicologia.<\/p>\n<p>1.2 O edital foi aprovado pelo Conselho do Programa de P\u00f3s-Gradua\u00e7\u00e3o em<br \/>\nPsicologia, da Faculdade de Ci\u00eancias e Letras \u2013 UNESP\/Campus de Assis, em<br \/>\nreuni\u00e3o realizada em 25\/10\/2012.<\/p>\n<p>1.3. Informa\u00e7\u00f5es sobre o Programa e Cursos podem ser obtidas na p\u00e1gina eletr\u00f4nica<br \/>\n<a href=\"http:\/\/sgcd.assis.unesp.br\/#!\/pos-graduacao\/cursos\/psicologia\/\" target=\"_blank\">http:\/\/sgcd.assis.unesp.br\/#!\/pos-graduacao\/cursos\/psicologia\/<\/a> ou na Se\u00e7\u00e3o T\u00e9cnica<br \/>\nde P\u00f3s-Gradua\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia FAPESP\u00a0\u2013 O Programa de P\u00f3s-gradua\u00e7\u00e3o em Psicologia da Faculdade de Ci\u00eancias e Letras da Universidade Estadual Paulista (Unesp), no campus de Assis, estar\u00e1 com as inscri\u00e7\u00f5es abertas para mestrado e doutorado entre 25 de fevereiro e 12 de mar\u00e7o. Entre os objetivos do programa, est\u00e3o o desenvolvimento de pesquisas na \u00e1rea a partir de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36246,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,351,370],"tags":[],"class_list":{"0":"post-41917","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-cursos","9":"category-inscricao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/professor-a.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/41917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=41917"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/41917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/36246"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=41917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=41917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=41917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}