{"id":41799,"date":"2012-12-24T05:42:13","date_gmt":"2012-12-24T07:42:13","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=41799"},"modified":"2012-12-22T22:47:57","modified_gmt":"2012-12-23T00:47:57","slug":"mercado-de-comunicacao-cresce-17-em-2012","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2012\/mercado-de-comunicacao-cresce-17-em-2012\/41799","title":{"rendered":"Mercado de comunica\u00e7\u00e3o cresce 17% em 2012"},"content":{"rendered":"<p>Sondagem feita pela Abracom revela que as <em><strong>ag\u00eancias de comunica\u00e7\u00e3o<\/strong><\/em> v\u00e3o crescer, em m\u00e9dia, 17% no ano de 2012. Com esse \u00edndice, a estimativa \u00e9 de que o mercado ter\u00e1 um faturamento global de R$ 2.340 bilh\u00f5es, contra os cerca de R$ 2 bilh\u00f5es em 2011.<\/p>\n<p>O levantamento, feito por amostragem, traz a opini\u00e3o dos empres\u00e1rios do setor sobre o mercado em 2012 e tamb\u00e9m perspectivas para o ano de 2013. As ag\u00eancias projetam um crescimento m\u00e9dio de 19%, em um momento de expans\u00e3o das oportunidades de neg\u00f3cios nos setores p\u00fablico e privado e de crescente valoriza\u00e7\u00e3o do trabalho de gest\u00e3o de relacionamentos, base dos servi\u00e7os prestados pelas ag\u00eancias.<\/p>\n<p>Segundo os empres\u00e1rios os fatores que impulsionam o crescimento do setor s\u00e3o a diversifica\u00e7\u00e3o da carteira de servi\u00e7os e amplia\u00e7\u00e3o da carteira de clientes.<\/p>\n<p>As ag\u00eancias tamb\u00e9m apontam o planejamento estrat\u00e9gico de neg\u00f3cios, o investimento em reten\u00e7\u00e3o de talentos e o aperfei\u00e7oamento da capta\u00e7\u00e3o de novos clientes como pontos relevantes no crescimento setorial.<\/p>\n<p>No come\u00e7o de 2012, a expectativa de crescimento superava os 20%, com algumas estimativas apontando cerca de 25% de expans\u00e3o no faturamento do setor. No entanto, as empresas pesquisadas afirmaram que o ano teve percal\u00e7os como o reflexo da crise econ\u00f4mica europeia em alguns setores da atividade econ\u00f4mica, o ano eleitoral e as expectativas n\u00e3o cumpridas plenamente de maior expans\u00e3o no setor p\u00fablico.<\/p>\n<p>Para a presidente do Conselho Diretivo da Abracom, Gisele Lorenzetti, no entanto, o crescimento de 17% deve ser comemorado. \u201cOs n\u00fameros de outros segmentos da ind\u00fastria da comunica\u00e7\u00e3o, como o de publicidade e m\u00eddia promocional, ficaram na faixa dos 10%. E a economia do pa\u00eds deve ficar perto de 1%. Nosso setor encontro espa\u00e7o para crescer, porque a comunica\u00e7\u00e3o corporativa ainda tem muito a oferecer \u00e0s empresas e governos\u201d, disse Lorenzetti.<\/p>\n<p>A partir de 2013, o acompanhamento dos n\u00fameros do setor ser\u00e1 feito trimestralmente, com boletins de an\u00e1lise econ\u00f4mica restrito aos associados e dados mais aprofundados. \u201cOs dados do mercado ser\u00e3o uma ferramenta de estrat\u00e9gia de neg\u00f3cios para que as ag\u00eancias filiadas possam planejar sua atua\u00e7\u00e3o no mercado\u201d, diz Carlos Henrique Carvalho, diretor-executivo. Esse trabalho ser\u00e1 coordenado pela diretoria para assuntos de gest\u00e3o empresarial, com acompanhamento de um servi\u00e7os de consultoria e an\u00e1lise econ\u00f4mica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sondagem feita pela Abracom revela que as ag\u00eancias de comunica\u00e7\u00e3o v\u00e3o crescer, em m\u00e9dia, 17% no ano de 2012. Com esse \u00edndice, a estimativa \u00e9 de que o mercado ter\u00e1 um faturamento global de R$ 2.340 bilh\u00f5es, contra os cerca de R$ 2 bilh\u00f5es em 2011. O levantamento, feito por amostragem, traz a opini\u00e3o dos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38940,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,7],"tags":[],"class_list":{"0":"post-41799","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-economia","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/grafico.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/41799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=41799"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/41799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/38940"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=41799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=41799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=41799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}