{"id":40788,"date":"2012-09-21T19:12:06","date_gmt":"2012-09-21T22:12:06","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=40788"},"modified":"2012-09-21T19:12:06","modified_gmt":"2012-09-21T22:12:06","slug":"tendencia-de-reducao-do-crescimento-economico-mundial","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2012\/tendencia-de-reducao-do-crescimento-economico-mundial\/40788","title":{"rendered":"Tend\u00eancia de redu\u00e7\u00e3o do crescimento econ\u00f4mico mundial"},"content":{"rendered":"<p>Bras\u00edlia \u2013 A Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio (OMC), em estudo publicado hoje (21), prev\u00ea redu\u00e7\u00e3o da meta de <em><strong>crescimento econ\u00f4mico global<\/strong><\/em> para 2012 e 2013. Segundo o diretor-geral da OMC, Pascal Lamy, h\u00e1 a tend\u00eancia de uma expans\u00e3o m\u00e9dia de 2,5%. Anteriormente, a previs\u00e3o era 3,7%. Para 2013, a estimativa \u00e9 crescimento econ\u00f4mico de 4,5%, sendo que a meta era 5,6%.<br \/>\nA organiza\u00e7\u00e3o prev\u00ea um crescimento de 1,5% das exporta\u00e7\u00f5es, ao longo deste ano, ante a estimativa de 2%. O c\u00e1lculo \u00e9 que a expans\u00e3o ser\u00e1 maior entre os pa\u00edses em desenvolvimento, registrando 5,6%, em m\u00e9dia, e menor nos desenvolvidos, que devem registrar aumento m\u00e9dio de 3,5%.<\/p>\n<p>No estudo, h\u00e1 informa\u00e7\u00f5es sobre o Brasil. Em um dos gr\u00e1ficos, o pa\u00eds aparece com n\u00fameros positivos nas exporta\u00e7\u00f5es e importa\u00e7\u00f5es de janeiro de 2011 at\u00e9 mar\u00e7o de 2012. Em abril deste ano, os dados come\u00e7am a cair e a tend\u00eancia de baixa \u00e9 cada vez maior. O gr\u00e1fico traz dados at\u00e9 agosto de 2012.<\/p>\n<p>Pelo texto, as importa\u00e7\u00f5es devem sofrer um processo de estagna\u00e7\u00e3o, em 2012, nas economias desenvolvidas ter um aumento robusto de 5,4% nos pa\u00edses em desenvolvimento (contra a previs\u00e3o anterior de 6,2%).<\/p>\n<p>A OMC adverte que v\u00e1rios aspectos do cen\u00e1rio econ\u00f4mico mundial ainda s\u00e3o preocupantes, como os dados dos Estados Unidos que refletem a alta do desemprego e a tend\u00eancia de um crescimento mais lento da ind\u00fastria na China. O \u00f3rg\u00e3o alerta ainda que h\u00e1 temores rondando a Europa em decorr\u00eancia da crise econ\u00f4mica internacional.<\/p>\n<p>Segundo Lamy, o mundo est\u00e1 cada vez mais \u201cinterdependente\u201d e os problemas causados pela crise econ\u00f4mica internacional acabam atingindo todos os pa\u00edses. Para ele, as medidas adotadas pela Uni\u00e3o Europeia, pelos Estados Unidos e pelo Fundo Monet\u00e1rio Internacional (FMI) contribuir\u00e3o para melhorar as estimativas para o pr\u00f3ximo ano.<\/p>\n<p>&#8220;Mas ainda h\u00e1 muito a ser feito. Precisamos de um compromisso renovado para revitalizar o sistema multilateral de com\u00e9rcio de tal forma que restaure a seguran\u00e7a econ\u00f4mica em um momento em que [esse fortalecimento] \u00e9 extremamente necess\u00e1rio. A \u00faltima coisa de que a economia mundial precisa agora \u00e9 a amea\u00e7a do protecionismo crescente&#8221;, disse Lamy.<\/p>\n<p>Pelo estudo, a desacelera\u00e7\u00e3o do com\u00e9rcio no primeiro semestre de 2012 foi impulsionado por uma redu\u00e7\u00e3o no ritmo de importa\u00e7\u00f5es dos pa\u00edses desenvolvidos e tamb\u00e9m pela queda nas exporta\u00e7\u00f5es. A OMC informa que os dados do estudo s\u00e3o provis\u00f3rios porque envolvem uma s\u00e9rie de fatores, como a evolu\u00e7\u00e3o econ\u00f4mica.<\/p>\n<p>De acordo com a organiza\u00e7\u00e3o, foi observado um \u201ccrescimento um pouco mais r\u00e1pido\u201d no quarto trimestre deste ano \u201cno mundo como um todo\u201d. Mas a tend\u00eancia \u00e9 um crescimento mais lento no come\u00e7o de 2013. O relat\u00f3rio completo, em ingl\u00eas, pode ser obtido no site da OMC.<\/p>\n<p>Renata Giraldi<br \/>\nRep\u00f3rter da Ag\u00eancia Brasil<br \/>\nEdi\u00e7\u00e3o: Juliana Andrade<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia \u2013 A Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio (OMC), em estudo publicado hoje (21), prev\u00ea redu\u00e7\u00e3o da meta de crescimento econ\u00f4mico global para 2012 e 2013. Segundo o diretor-geral da OMC, Pascal Lamy, h\u00e1 a tend\u00eancia de uma expans\u00e3o m\u00e9dia de 2,5%. Anteriormente, a previs\u00e3o era 3,7%. Para 2013, a estimativa \u00e9 crescimento econ\u00f4mico de 4,5%, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38938,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,7],"tags":[],"class_list":{"0":"post-40788","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-economia","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/economia1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/40788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=40788"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/40788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/38938"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=40788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=40788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=40788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}