{"id":40160,"date":"2012-08-08T21:32:26","date_gmt":"2012-08-09T00:32:26","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=40160"},"modified":"2012-08-08T21:32:26","modified_gmt":"2012-08-09T00:32:26","slug":"timemania-339-resultado-do-sorteio","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2012\/timemania-339-resultado-do-sorteio\/40160","title":{"rendered":"Timemania 339: resultado do sorteio"},"content":{"rendered":"<div><em><strong>Timemania 339<\/strong><\/em>\u00a0\u2013 o\u00a0<em><strong>resultado<\/strong><\/em>\u00a0da\u00a0Timemania concurso 339, sorteio desta quarta-feira (08\/08)\u00a0no caminh\u00e3o da sorte em Ascurra (SC), foi conferido pelo p\u00fablico e pelos auditores convidados. O pr\u00eamio foi muito esperado pelos apostadores. A expectativa tamb\u00e9m para saber o time do cora\u00e7\u00e3o. No \u00faltimo sorteio o pr\u00eamio principal acumulou. O pr\u00eamio de hoje estava estimado em 13 milh\u00f5es de reais.\u00a0<a href=\"https:\/\/www.redenoticia.com.br\/noticia\/loterias\">Confira os resultados das outras loterias Caixa.<\/a><\/div>\n<div>\n<p>Na Timemania seu palpite vale uma bolada. Ao todo s\u00e3o oitenta n\u00fameros e oitenta clubes de futebol, voc\u00ea escolhe dez n\u00fameros e um Time do Cora\u00e7\u00e3o.<\/p>\n<h3>Timemania:\u00a0resultado do sorteio 339<\/h3>\n<p>Os n\u00fameros sorteados no\u00a0Concurso 339 da\u00a0TimeMania, dia 08\/08\/2012, foram:<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"60\">07<\/td>\n<td width=\"60\">20<\/td>\n<td width=\"60\">33<\/td>\n<td width=\"60\">41<\/td>\n<td width=\"60\">45<\/td>\n<td width=\"60\">49<\/td>\n<td width=\"60\">50<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Time do cora\u00e7\u00e3o:\u00a0Flamengo (RJ)<\/p>\n<p>Voc\u00ea pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo por 2 ou 4 concursos consecutivos (Teimosinha). Os sorteios s\u00e3o realizados nas quartas e s\u00e1bados, a partir das 20:00h. Se voc\u00ea tiver de tr\u00eas a sete acertos dos 7 n\u00fameros sorteados, ganha. Se acertar o Time do Cora\u00e7\u00e3o, tamb\u00e9m ganha. O pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o. Dessa\u00a0porcentagem, ser\u00e1 deduzido o pagamento dos pr\u00eamios com valores fixos.N\u00e3o havendo acertador, o pr\u00eamio acumula para o concurso seguinte, na faixa de pr\u00eamios com 7 acertos. N\u00e3o deixe de conferir seu bilhete de aposta. Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>Fonte: Caixa Timemania<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Timemania 339\u00a0\u2013 o\u00a0resultado\u00a0da\u00a0Timemania concurso 339, sorteio desta quarta-feira (08\/08)\u00a0no caminh\u00e3o da sorte em Ascurra (SC), foi conferido pelo p\u00fablico e pelos auditores convidados. O pr\u00eamio foi muito esperado pelos apostadores. A expectativa tamb\u00e9m para saber o time do cora\u00e7\u00e3o. No \u00faltimo sorteio o pr\u00eamio principal acumulou. O pr\u00eamio de hoje estava estimado em 13 milh\u00f5es [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,361],"tags":[],"class_list":{"0":"post-40160","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-time-mania","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/40160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=40160"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/40160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18093"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=40160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=40160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=40160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}