{"id":39575,"date":"2012-06-27T20:28:11","date_gmt":"2012-06-27T23:28:11","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=39575"},"modified":"2012-06-27T20:34:13","modified_gmt":"2012-06-27T23:34:13","slug":"mega-sena-1401-premio-de-r25-milhoes","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2012\/mega-sena-1401-premio-de-r25-milhoes\/39575","title":{"rendered":"Mega Sena 1401: pr\u00eamio de R$25 milh\u00f5es"},"content":{"rendered":"<p><em><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18079\" title=\"resultado da mega sena\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Mega Sena<\/strong><\/em> 1401: a Mega Sena acumulou e vai pagar R$25 milh\u00f5es para o apostador que acertar as seis dezenas que ser\u00e3o sorteadas nesta quarta-feira (27), \u00e0s 20h25 (hor\u00e1rio de Bras\u00edlia). O concurso Mega Sena 1401 ser\u00e1 realizado no Caminh\u00e3o da Sorte, que est\u00e1 estacionado no centro de Parauapebas (PA), e ter\u00e1 transmiss\u00e3o ao vivo pela TV Bandeirantes.<\/p>\n<p>Veja o resultado:<\/p>\n<table width=\"95%\">\n<tbody>\n<tr>\n<td width=\"16%\"><strong>11<\/strong><\/td>\n<td width=\"16%\"><strong>12<\/strong><\/td>\n<td width=\"16%\"><strong>25<\/strong><\/td>\n<td width=\"16%\"><strong>33<\/strong><\/td>\n<td width=\"16%\"><strong>48<\/strong><\/td>\n<td width=\"16%\"><strong>54<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>O valor estimado do pr\u00eamio para quem acertar na Mega Sena 1401 garante o rendimento mensal de R$ 125 mil, caso o apostador decida aplicar todo o valor recebido na Poupan\u00e7a da CAIXA. Com a quantia, tamb\u00e9m \u00e9 poss\u00edvel investir em im\u00f3veis, comprando 125 casas no valor de R$ 200 mil cada. Ou ent\u00e3o, uma frota de 250 carros de luxo.<\/p>\n<p>A aposta m\u00ednima na Mega Sena 1401 \u00e9 de R$ 2 e pode ser efetuada at\u00e9 \u00e0s 19h (hor\u00e1rio de Bras\u00edlia) desta quarta, em qualquer uma das 11 mil lot\u00e9ricas do pa\u00eds. Clientes da CAIXA contam ainda com uma facilidade a mais na hora de apostar na Mega-Sena. Basta ser maior de 18 anos e possuir uma conta Pessoa F\u00edsica no banco, com acesso ao Internet Banking CAIXA (IBC), para fazer sua aposta sem sair de casa.<\/p>\n<p>Outra facilidade oferecida pelas Loterias \u00e9 a Surpresinha, op\u00e7\u00e3o em que o apostador pode deixar que o sistema escolha os n\u00fameros ou ainda concorrer com o mesmo jogo por 2, 4 ou 8 concursos consecutivos (Teimosinha).<\/p>\n<p>Timemania:<br \/>\nO concurso 327 da Timemania tamb\u00e9m est\u00e1 sem ganhador na faixa principal h\u00e1 mais de 5 concursos, e pode pagar nesta quarta R$ 6,7 milh\u00f5es. As apostas est\u00e3o abertas at\u00e9 uma hora antes do sorteio, que ser\u00e1 realizado \u00e0s 20h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mega Sena 1401: a Mega Sena acumulou e vai pagar R$25 milh\u00f5es para o apostador que acertar as seis dezenas que ser\u00e3o sorteadas nesta quarta-feira (27), \u00e0s 20h25 (hor\u00e1rio de Bras\u00edlia). O concurso Mega Sena 1401 ser\u00e1 realizado no Caminh\u00e3o da Sorte, que est\u00e1 estacionado no centro de Parauapebas (PA), e ter\u00e1 transmiss\u00e3o ao vivo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,355],"tags":[],"class_list":{"0":"post-39575","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-mega-sena","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-mega-sena.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/39575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=39575"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/39575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18079"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=39575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=39575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=39575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}