{"id":3879,"date":"2009-06-26T13:24:40","date_gmt":"2009-06-26T17:24:40","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=3879"},"modified":"2009-06-26T13:24:40","modified_gmt":"2009-06-26T17:24:40","slug":"incor-especialista-do-hc-explica-diferenca-entre-infarto-e-parada-cardiaca","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2009\/incor-especialista-do-hc-explica-diferenca-entre-infarto-e-parada-cardiaca\/3879","title":{"rendered":"Incor &#8211; Especialista do HC explica diferen\u00e7a entre infarto e parada card\u00edaca"},"content":{"rendered":"<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 0.0001pt; margin-left: 0px; text-align: center; line-height: normal;\" align=\"center\"><span style=\"font-size: 12pt; font-family: 'Century Gothic';\"><strong>Pacientes infartados com 50 anos ou menos, atendidos nos \u00faltimos dez anos, no Incor (Instituto do Cora\u00e7\u00e3o), representam 14% dos atendimentos<\/strong><\/span><\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 0.0001pt; margin-left: 0px; text-align: justify; line-height: normal;\"><span style=\"font-size: 12pt; font-family: 'Century Gothic';\"><br \/>\nO cora\u00e7\u00e3o funciona como uma bomba de eje\u00e7\u00e3o de sangue para todo o corpo humano. Quando se contrai, distribui sangue pelas art\u00e9rias; e quando se dilata, traz o sangue de volta para dentro dele, pelas veias. A parada card\u00edaca ocorre quando o cora\u00e7\u00e3o para de funcionar. Nessa condi\u00e7\u00e3o, ele deixa de exercer a fun\u00e7\u00e3o de bomba, inviabilizando a circula\u00e7\u00e3o do sangue pelo organismo.<\/span><\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 0.0001pt; margin-left: 0px; text-align: justify; line-height: normal;\"><span style=\"font-size: 12pt; font-family: 'Century Gothic';\">De acordo com o cardiologista e diretor da Unidade Cl\u00ednica de Coronariopatias Agudas do Incor HC\/FMUSP, doutor Jos\u00e9 Carlos Nicolau, o infarto \u00e9 a causa mais comum de parada card\u00edaca na popula\u00e7\u00e3o. \u201cAl\u00e9m de fazer com que o sangue circule pelo corpo, o cora\u00e7\u00e3o tamb\u00e9m precisa de sangue para o pr\u00f3prio funcionamento. Quando h\u00e1 obstru\u00e7\u00e3o de um vaso que alimenta o \u00f3rg\u00e3o, a regi\u00e3o relacionada a esse vaso pode vir a morrer. Isso \u00e9 o infarto do mioc\u00e1rdio (do cora\u00e7\u00e3o)\u201d, explica, acrescentando que o infarto tem tamanho e repercuss\u00e3o vari\u00e1veis, dependendo do vaso que tiver sido obstru\u00eddo.<\/span><\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 0.0001pt; margin-left: 0px; text-align: justify; line-height: normal;\"><span style=\"font-size: 12pt; font-family: 'Century Gothic';\">De 3.439 infartados, atendidos no Incor nos \u00faltimos dez anos, 479 tinham 50 anos ou menos. O especialista lembra que, quando h\u00e1 uma parada card\u00edaca, \u00e9 fundamental que haja atendimento r\u00e1pido. \u201cEm alguns casos, \u00e9 poss\u00edvel reverter o quadro. Quando o atendimento \u00e9 feito prontamente, diminuem-se os riscos de les\u00e3o cerebral\u201d, informa.<\/span><\/p>\n<p style=\"line-height: normal; margin: 0px;\"><span style=\"font-size: 12pt; font-family: 'Century Gothic';\">Al\u00e9m do infarto, h\u00e1 outras diversas causas que podem levar \u00e0 parada card\u00edaca, como insufici\u00eancia card\u00edaca em fase terminal, embolia pulmonar, arritmia card\u00edaca cong\u00eanita, entre outras.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pacientes infartados com 50 anos ou menos, atendidos nos \u00faltimos dez anos, no Incor (Instituto do Cora\u00e7\u00e3o), representam 14% dos atendimentos O cora\u00e7\u00e3o funciona como uma bomba de eje\u00e7\u00e3o de sangue para todo o corpo humano. Quando se contrai, distribui sangue pelas art\u00e9rias; e quando se dilata, traz o sangue de volta para dentro dele, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-3879","post","type-post","status-publish","format-standard","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/3879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=3879"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/3879\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=3879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=3879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=3879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}