{"id":37468,"date":"2011-12-03T21:24:04","date_gmt":"2011-12-03T23:24:04","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=37468"},"modified":"2011-12-03T21:24:28","modified_gmt":"2011-12-03T23:24:28","slug":"timemania-268-%e2%80%93-resultado-do-sorteio-deste-sabado-0312","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2011\/timemania-268-%e2%80%93-resultado-do-sorteio-deste-sabado-0312\/37468","title":{"rendered":"Timemania 268 \u2013 resultado do sorteio deste s\u00e1bado (03\/12)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18093\" title=\"resultado da timemania\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Timemania 268 \u2013 o\u00a0<strong><em>resultado<\/em><\/strong>\u00a0da\u00a0<strong><em>Timemania 268<\/em><\/strong> sorteada neste s\u00e1bado (<strong><em>03\/12<\/em><\/strong>)\u00a0pelo caminh\u00e3o da sorte em Araraquara\/SP. O\u00a0pr\u00eamio\u00a0foi\u00a0muito esperado\u00a0pelos apostadores. A expectativa\u00a0tamb\u00e9m\u00a0para\u00a0saber o time do cora\u00e7\u00e3o. No \u00faltimo sorteio o pr\u00eamio principal acumulou. O pr\u00eamio de hoje estava estimado em 6,6 milh\u00f5es de reais. Na Timemania seu palpite vale uma bolada. Ao\u00a0todo\u00a0s\u00e3o oitenta n\u00fameros e oitenta clubes de futebol, voc\u00ea escolhe dez n\u00fameros e um Time do Cora\u00e7\u00e3o.<\/p>\n<p>Confira o resultado da Timemania 268 sorteada neste s\u00e1bado (03\/12):<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"80\"><strong>01<\/strong><\/td>\n<td width=\"80\"><strong>07<\/strong><\/td>\n<td width=\"80\"><strong>18<\/strong><\/td>\n<td width=\"80\"><strong>27<\/strong><\/td>\n<td width=\"80\"><strong>39<\/strong><\/td>\n<td width=\"80\"><strong>52<\/strong><\/td>\n<td width=\"80\"><strong>70<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Time do Cora\u00e7\u00e3o: <strong>Moto Clube (MA)<\/strong><br \/>\nVoc\u00ea pode\u00a0deixar\u00a0que\u00a0o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo\u00a0por\u00a02 ou 4 concursos consecutivos (Teimosinha). Os sorteios s\u00e3o realizados nas quartas e s\u00e1bados, a\u00a0partir\u00a0das\u00a020:00h.<\/p>\n<p>Se voc\u00ea tiver de tr\u00eas a sete acertos dos 7 n\u00fameros sorteados, ganha. Se\u00a0acertar\u00a0o Time do Cora\u00e7\u00e3o, tamb\u00e9m ganha. O valor da aposta \u00e9 R$ 2 e o pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o. Dessa porcentagem, ser\u00e1 deduzido o pagamento dos pr\u00eamios com valores fixos:<\/p>\n<p>R$ 5,00 para as apostas com o Time do Cora\u00e7\u00e3o sorteado.<\/p>\n<p>R$ 2,00 para as apostas com 3 n\u00fameros sorteados;<\/p>\n<p>R$ 6,00 para as apostas com 4 n\u00fameros sorteados;<\/p>\n<p>Somente ap\u00f3s a apura\u00e7\u00e3o dos ganhadores dos pr\u00eamios com valores fixos, o valore restante do total destinado \u00e0 premia\u00e7\u00e3o ser\u00e1 distribu\u00eddo para as demais faixas de pr\u00eamio com os seguintes percentuais:<\/p>\n<p>40% para os acertadores dos sete n\u00fameros;<\/p>\n<p>30% entre os acertadores dos seis n\u00fameros;<\/p>\n<p>20% para os acertadores de cinco n\u00fameros;<\/p>\n<p>10% restantes s\u00e3o acumulados e distribu\u00eddos aos acertadores dos 7 n\u00fameros nos concursos de final 0 ou 5.<\/p>\n<p>N\u00e3o\u00a0havendo acertador, o pr\u00eamio acumula para o concurso seguinte, na faixa de pr\u00eamios com 7 acertos. N\u00e3o deixe de conferir seu bilhete de aposta.\u00a0Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Timemania 268 \u2013 o\u00a0resultado\u00a0da\u00a0Timemania 268 sorteada neste s\u00e1bado (03\/12)\u00a0pelo caminh\u00e3o da sorte em Araraquara\/SP. O\u00a0pr\u00eamio\u00a0foi\u00a0muito esperado\u00a0pelos apostadores. A expectativa\u00a0tamb\u00e9m\u00a0para\u00a0saber o time do cora\u00e7\u00e3o. No \u00faltimo sorteio o pr\u00eamio principal acumulou. O pr\u00eamio de hoje estava estimado em 6,6 milh\u00f5es de reais. Na Timemania seu palpite vale uma bolada. Ao\u00a0todo\u00a0s\u00e3o oitenta n\u00fameros e oitenta clubes de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,335,361],"tags":[],"class_list":{"0":"post-37468","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-time-mania","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/37468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=37468"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/37468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18093"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=37468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=37468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=37468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}