{"id":36800,"date":"2011-10-05T22:00:05","date_gmt":"2011-10-06T02:00:05","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=36800"},"modified":"2011-10-05T22:00:05","modified_gmt":"2011-10-06T02:00:05","slug":"timemania-251-%e2%80%93-resultado-do-sorteio-desta-quarta-feira-0510","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2011\/timemania-251-%e2%80%93-resultado-do-sorteio-desta-quarta-feira-0510\/36800","title":{"rendered":"Timemania 251 \u2013 resultado do sorteio desta quarta-feira (05\/10)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18093\" title=\"resultado da timemania\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Timemania 251 \u2013 o\u00a0<strong><em>resultado<\/em><\/strong>\u00a0da\u00a0<strong><em>Timemania 251<\/em><\/strong> sorteada nesta quarta-feira (<strong><em>05\/10<\/em><\/strong>)\u00a0pelo caminh\u00e3o da sorte em Jaragu\u00e1 do Sul\/SC. foi muito esperado pelos apostadores. A expectativa tamb\u00e9m para saber o time do cora\u00e7\u00e3o. No \u00faltimo sorteio o pr\u00eamio principal acumulou. O pr\u00eamio de hoje estava estimado em 2 milh\u00f5es de reais. Na Timemania seu palpite vale uma bolada. Ao todo s\u00e3o oitenta n\u00fameros e oitenta clubes de futebol, voc\u00ea escolhe dez n\u00fameros e um Time do Cora\u00e7\u00e3o.<\/p>\n<p>Confira o resultado da Timemania 251 sorteada nesta quarta-feira (05\/10):<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 01<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 16<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 39<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 59<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 65<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 75<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0 80<strong>\u00a0 \u00a0 \u00a0 * \u00a0 \u00a0\u00a0<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n<p>O Time do Cora\u00e7\u00e3o foi o: S\u00e3o Paulo \/ SP<\/p>\n<p>Voc\u00ea pode deixar que o sistema escolha os n\u00fameros para voc\u00ea (Surpresinha) e\/ou continuar com o seu jogo por 2 ou 4 concursos consecutivos (Teimosinha). Os sorteios s\u00e3o realizados nas quartas e s\u00e1bados, a partir das\u00a020:00h.<\/p>\n<p>Se voc\u00ea tiver de tr\u00eas a sete acertos dos 7 n\u00fameros sorteados, ganha. Se acertar o Time do Cora\u00e7\u00e3o, tamb\u00e9m ganha. O valor da aposta \u00e9 R$ 2 e o pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o. Dessa porcentagem, ser\u00e1 deduzido o pagamento dos pr\u00eamios com valores fixos:<\/p>\n<p>R$ 2,00 para as apostas com o Time do Cora\u00e7\u00e3o sorteado.<\/p>\n<p>R$ 2,00 para as apostas com 3 n\u00fameros sorteados;<\/p>\n<p>R$ 6,00 para as apostas com 4 n\u00fameros sorteados;<\/p>\n<p>Somente ap\u00f3s a apura\u00e7\u00e3o dos ganhadores dos pr\u00eamios com valores fixos, o valore restante do total destinado \u00e0 premia\u00e7\u00e3o ser\u00e1 distribu\u00eddo para as demais faixas de pr\u00eamio com os seguintes percentuais:<\/p>\n<p>40% para os acertadores dos sete n\u00fameros;<\/p>\n<p>30% entre os acertadores dos seis n\u00fameros;<\/p>\n<p>20% para os acertadores de cinco n\u00fameros;<\/p>\n<p>10% restantes s\u00e3o acumulados e distribu\u00eddos aos acertadores dos 7 n\u00fameros nos concursos de final 0 ou 5.<\/p>\n<p>N\u00e3o havendo acertador, o pr\u00eamio acumula para o concurso seguinte, na faixa de pr\u00eamios com 7 acertos. N\u00e3o deixe de conferir seu bilhete de aposta.<\/p>\n<p>Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Timemania 251 \u2013 o\u00a0resultado\u00a0da\u00a0Timemania 251 sorteada nesta quarta-feira (05\/10)\u00a0pelo caminh\u00e3o da sorte em Jaragu\u00e1 do Sul\/SC. foi muito esperado pelos apostadores. A expectativa tamb\u00e9m para saber o time do cora\u00e7\u00e3o. No \u00faltimo sorteio o pr\u00eamio principal acumulou. O pr\u00eamio de hoje estava estimado em 2 milh\u00f5es de reais. Na Timemania seu palpite vale uma bolada. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,361],"tags":[],"class_list":{"0":"post-36800","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-time-mania","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-timemania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/36800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=36800"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/36800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18093"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=36800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=36800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=36800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}