{"id":36201,"date":"2011-08-15T13:02:15","date_gmt":"2011-08-15T17:02:15","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=36201"},"modified":"2011-08-16T23:46:33","modified_gmt":"2011-08-17T03:46:33","slug":"band-comecam-as-gravacoes-de-julie-os-fantasmas","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2011\/band-comecam-as-gravacoes-de-julie-os-fantasmas\/36201","title":{"rendered":"Band: come\u00e7am as grava\u00e7\u00f5es de Julie &#038; Os Fantasmas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-36202\" title=\"band julie e os fantasmas\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/band-julie-e-os-fantasmas.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/band-julie-e-os-fantasmas.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/band-julie-e-os-fantasmas-250x161.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/band-julie-e-os-fantasmas-150x97.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A <em><strong>Band<\/strong><\/em> e a Mixer come\u00e7aram nesta quinta-feira, 11 de agosto, as grava\u00e7\u00f5es de <em><strong>Julie &amp; Os Fantasmas<\/strong><\/em>. Elenco e produ\u00e7\u00e3o j\u00e1 est\u00e3o em loca\u00e7\u00f5es de Paul\u00ednia e Campinas, cidades do interior de S\u00e3o Paulo onde a s\u00e9rie ser\u00e1 gravada. Ser\u00e3o ao todo 26 epis\u00f3dios semanais de meia-hora, que ter\u00e3o como mote central a adolesc\u00eancia e os seus fantasmas.<\/p>\n<p>Julie &amp; Os Fantasmas conta a hist\u00f3ria de Julie (Mariana Lessa), uma garota de 15 anos bastante talentosa, mas extremamente t\u00edmida. Apaixonada pelo colega de classe, Nicolas (Michel Joelsas), vive as inseguran\u00e7as da adolesc\u00eancia. Adoraria cantar, mas n\u00e3o consegue soltar a voz em p\u00fablico. Isso at\u00e9 o dia em que acidentalmente liberta de um disco de vinil os fantasmas de uma banda que desapareceu misteriosamente nos anos 80. A partir da rela\u00e7\u00e3o que estabelece com os m\u00fasicos fantasmas \u2013 Martim (Marcelo Pires), Daniel (Bruno Sigrist) e Felix (Fabio Rabello) \u2013 sua vida d\u00e1 uma guinada. Ao longo dos epis\u00f3dios, ela vai ter que lidar com esses fantasmas e com os pr\u00f3prios dilemas da adolesc\u00eancia.<\/p>\n<p>Ainda essa semana, o elenco entrou em est\u00fadio para gravar as can\u00e7\u00f5es originais que v\u00e3o compor a trilha sonora. Entre eles, a protagonista Mariana Lessa e a atriz Milena Martines, que vai interpretar a antagonista de Julie na hist\u00f3ria. Quem comandou as grava\u00e7\u00f5es foi o produtor Rick Bonadio, que assina a dire\u00e7\u00e3o musical da s\u00e9rie. Al\u00e9m de ter lan\u00e7ado bandas de sucesso como Mamonas Assassinas, Charlie Brown Jr. e NXZero, Rick produziu trilhas sonoras de sucesso na tela da Band, como Floribella e Dance Dance Dance.<\/p>\n<p>Totalmente gravada em HD (alta defini\u00e7\u00e3o de som e imagem), Julie &amp; e os Fantasmas \u00e9 uma com\u00e9dia adolescente que vai agradar os \u201cjovens\u201d de todas as idades. \u00c9 o que afirma o diretor art\u00edstico e de programa\u00e7\u00e3o da Band, H\u00e9lio Vargas: \u201cSempre nos preocupamos em oferecer conte\u00fado de qualidade, que agrade o p\u00fablico jovem, mas que tamb\u00e9m seja uma op\u00e7\u00e3o para toda a fam\u00edlia\u201d.<\/p>\n<p>Segundo o presidente da Mixer, Jo\u00e3o Daniel Tikhomiroff, Julie &amp; Os Fantasmas chega com um projeto transm\u00eddia, que possibilita total intera\u00e7\u00e3o do p\u00fablico. &#8220;O jovem est\u00e1 ligado em tudo e Julie estar\u00e1 em todos os lugares ao mesmo tempo, dando mais vida \u00e0 s\u00e9rie&#8221;. O lan\u00e7amento na TV ser\u00e1 acompanhado por outras plataformas, como blogs, redes sociais e plataformas m\u00f3veis.<\/p>\n<p>Julie &amp; os Fantasmas \u00e9 uma co-produ\u00e7\u00e3o Band e Mixer, produtora premiada que assina sucessos como Mothern, Descolados, a s\u00e9rie animada Escola pra Cachorro e longa-metragem Besouro. A s\u00e9rie estreia em outubro, na Band e no canal Nickelodeon, produtor associado da atra\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Band e a Mixer come\u00e7aram nesta quinta-feira, 11 de agosto, as grava\u00e7\u00f5es de Julie &amp; Os Fantasmas. Elenco e produ\u00e7\u00e3o j\u00e1 est\u00e3o em loca\u00e7\u00f5es de Paul\u00ednia e Campinas, cidades do interior de S\u00e3o Paulo onde a s\u00e9rie ser\u00e1 gravada. Ser\u00e3o ao todo 26 epis\u00f3dios semanais de meia-hora, que ter\u00e3o como mote central a adolesc\u00eancia [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[390,22,379,343],"tags":[],"class_list":{"0":"post-36201","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-band","8":"category-brasil","9":"category-novelas","10":"category-televisao","11":"entry","12":"gs-1","13":"gs-odd","14":"gs-even","15":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/band-julie-e-os-fantasmas.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/36201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=36201"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/36201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/36202"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=36201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=36201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=36201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}