{"id":35614,"date":"2011-06-30T15:21:58","date_gmt":"2011-06-30T19:21:58","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=35614"},"modified":"2011-07-08T04:07:48","modified_gmt":"2011-07-08T08:07:48","slug":"vostu-apresenta-o-avatar-de-ivete-sangalo-no-megacity","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2011\/vostu-apresenta-o-avatar-de-ivete-sangalo-no-megacity\/35614","title":{"rendered":"Vostu apresenta o avatar de Ivete Sangalo no MegaCity"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-35615\" title=\"avatar ivete sangalo megacity\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/avatar-ivete-sangalo-megacity.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/avatar-ivete-sangalo-megacity.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/avatar-ivete-sangalo-megacity-150x96.jpg 150w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/avatar-ivete-sangalo-megacity-250x160.jpg 250w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A Vostu, empresa de jogos sociais do Brasil, est\u00e1 lan\u00e7ando no pr\u00f3ximo  dia 5 de julho em <em><strong>MegaCity<\/strong><\/em> uma campanha com <em><strong>Ivete Sangalo<\/strong><\/em> com o  <em><strong>avatar<\/strong><\/em> oficial da cantora que ser\u00e1 utilizado no jogo.\u00a0O desenho, que \u00e9 fiel \u00e0  baiana em todos os aspectos, remete ao figurino usado no show realizado no  Madison Square Garden, em Nova York e Ivete fez quest\u00e3o de escolher as roupas e  os detalhes que comp\u00f5em a anima\u00e7\u00e3o. A cartola preta que usou no espet\u00e1culo e o  blazer colorido foram os escolhidos para montar o figurino.<\/p>\n<p>No jogo, Ivete ter\u00e1 uma ilha virtual e distribuir\u00e1 miss\u00f5es para os  jogadores. As miss\u00f5es s\u00e3o simples: o jogador precisa preparar sua cidade virtual  para receber a cantora e organizar um megashow na cidade. Depois eles ser\u00e3o  desafiados a formar o maior f\u00e3 clube para a artista dentro do MegaCity, tendo  por objetivo participar do sorteio que vai levar os vencedores a conhec\u00ea-la  pessoalmente.<\/p>\n<p>Para a a\u00e7\u00e3o, a equipe da Vostu criou, al\u00e9m do avatar da  cantora, outros itens para a Ilha da Ivete que remetem \u00e0 Bahia, como casinhas do  Pelourinho, avatar de baianas, al\u00e9m de decora\u00e7\u00e3o com as fitinhas do Nosso Senhor  do Bonfim. O comercial ir\u00e1 ao ar no mesmo dia em que a a\u00e7\u00e3o entrar\u00e1 no jogo, no  dia 5 de julho, e ser\u00e1 exibido em rede nacional.<\/p>\n<p>Sobre a Vostu<br \/>\nFundada em junho de 2007, a Vostu \u00e9 a maior desenvolvedora  de jogos sociais do Brasil e re\u00fane em seu portf\u00f3lio o primeiro jogo brasileiro  para constru\u00e7\u00e3o de megacidades, o MegaCity, al\u00e9m da maior fazenda voltada para o  p\u00fablico brasileiro, o Mini Fazenda e o primeiro e maior jogo social brasileiro  de restaurantes, o Caf\u00e9 Mania, al\u00e9m dos populares Vostu Poker, Pet Mania e Rede  do Crime, que j\u00e1 atra\u00edram mais de 50 milh\u00f5es de jogadores no Orkut e agora est\u00e1  com seus jogos dispon\u00edveis tamb\u00e9m no Facebook.<\/p>\n<p>Sobre Ivete Sangalo<br \/>\nEm 1999, depois de cinco anos de sucesso como  vocalista da Banda Eva, a baiana de Juazeiro iniciou sua carreira solo e se  tornou uma das mais importantes artistas da m\u00fasica brasileira. A cantora tem  nove CD\u2019s solo lan\u00e7ados (fora as colet\u00e2neas), quatro DVD&#8217;s e mais de 5 milh\u00f5es  de CD\u2019s e DVD\u2019s vendidos no Brasil e no exterior. Ao longo de sua carreira, mais  de 15 marcas, j\u00e1 tiveram a baiana estrelando suas pe\u00e7as. A carreira est\u00e1vel,  personalidade marcante e a capacidade de se comunicar com os mais diversos e  diferentes p\u00fablicos com a mesma naturalidade, colocaram a cantora entre as cinco  personalidades mais confi\u00e1veis pelo povo brasileiro, de acordo com uma pesquisa  realizada pelo jornal Folha de S\u00e3o Paulo em 2010. Ao todo, s\u00e3o mais de 120  f\u00e3s-clubes registrados, o site oficial da artista recebe cerca de 350 mil  visitas mensais e o seu perfil no Twitter possui hoje mais de 2 milh\u00e3o de  seguidores. Em 2010 a artista gravou o O CD e DVD &#8220;Multishow Ao Vivo \u2013 Ivete  Sangalo no Madison Square Garden&#8221;, registro do show que Ivete Sangalo fez no  templo do show business mundial em Nova York, para 15 mil pessoas. Ivete contou  com as participa\u00e7\u00f5es especiais de Seu Jorge, Nelly Furtado, o colombiano Juanes  e o argentino Diego Torres. Com apenas dois meses de lan\u00e7ado o \u00e1lbum atingiu a  marca de 500 mil c\u00f3pias vendidas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Vostu, empresa de jogos sociais do Brasil, est\u00e1 lan\u00e7ando no pr\u00f3ximo dia 5 de julho em MegaCity uma campanha com Ivete Sangalo com o avatar oficial da cantora que ser\u00e1 utilizado no jogo.\u00a0O desenho, que \u00e9 fiel \u00e0 baiana em todos os aspectos, remete ao figurino usado no show realizado no Madison Square Garden, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":35615,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,343],"tags":[],"class_list":{"0":"post-35614","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-televisao","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/avatar-ivete-sangalo-megacity.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=35614"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/35615"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=35614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=35614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=35614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}