{"id":35113,"date":"2011-05-20T12:20:48","date_gmt":"2011-05-20T16:20:48","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=35113"},"modified":"2011-05-23T13:12:34","modified_gmt":"2011-05-23T17:12:34","slug":"idolos-da-rede-record-abre-votacao-para-o-publico","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2011\/idolos-da-rede-record-abre-votacao-para-o-publico\/35113","title":{"rendered":"\u00cddolos da Rede Record abre vota\u00e7\u00e3o para o p\u00fablico"},"content":{"rendered":"<p><em><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-34401\" title=\"idolos rede record\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/idolos-rede-record.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/idolos-rede-record.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/idolos-rede-record-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/idolos-rede-record-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00cddolos<\/strong><\/em> da <em><strong>Rede Record<\/strong><\/em> &#8211; no programa \u00cddolos exibido na quinta-feira (19\/05) foi definido o TOP 10 pela <em><strong>vota\u00e7\u00e3o<\/strong><\/em> do p\u00fablico e pelos jurados. Dos 15 participantes, apenas 10 ir\u00e3o disputar a fase final do reality show &#8211; chamada Concertos, que come\u00e7a na pr\u00f3xima ter\u00e7a-feira, dia 24\/05. E a primeira apresenta\u00e7\u00e3o ter\u00e1 como tema o sertanejo, com repert\u00f3rio variado desse g\u00eanero que vem conquistando v\u00e1rias gera\u00e7\u00f5es.<\/p>\n<p>Os finalistas j\u00e1 se mudaram para a Mans\u00e3o \u00cdDOLOS, localizada em S\u00e3o Paulo. As primeiras impress\u00f5es da nova casa ser\u00e3o exibidas no epis\u00f3dio de ter\u00e7a-feira. Os candidatos ficar\u00e3o concentrados no local, morando juntos, estudando e se preparando para as grava\u00e7\u00f5es e eventos ligados \u00e0 m\u00fasica.  A competi\u00e7\u00e3o est\u00e1 apenas come\u00e7ando.<\/p>\n<p>A cada semana, depois das apresenta\u00e7\u00f5es, o p\u00fablico pode votar por SMS em seu candidato preferido. O resultado ser\u00e1 anunciado ao vivo por Rodrigo Faro sempre \u00e0s quintas-feiras. Agora \u00e9 cada um por si para garantir vaga na etapa final do reality show.<\/p>\n<p>Confira quem s\u00e3o os 10 finalistas de \u00cdDOLOS:<\/p>\n<p>*nome art\u00edstico \/ idade \/ cidade que est\u00e1 representando no programa<\/p>\n<p>Henrique Lemes\/ 16 anos \/ Guaramirim -SC<\/p>\n<p>Marjory Porto\/  26 anos \/ Florian\u00f3polis -SC<\/p>\n<p>Raphael Diniz \/ 26 anos \/ Curitiba -PR<\/p>\n<p>Fernanda Portilho \/  21 anos \/Governador Valadares -MG<\/p>\n<p>Elson J\u00fanior \/ 28 anos\/ Nova Igua\u00e7u -RJ<\/p>\n<p>Camila Morais \/ 21 anos \/ Monte Si\u00e3o &#8211; MG<\/p>\n<p>Mello J\u00fanior \/ 25 anos\/ Palmas &#8211; TO<\/p>\n<p>Hellen Caroline \/ 24 anos \/ Taubat\u00e9 -SP<\/p>\n<p>Higor Rocha \/ 16 anos \/ S\u00e3o Paulo -SP<\/p>\n<p>Karielle Gontijo \/ 20 anos \/ Mineiros -GO<\/p>\n<p>\u00cdDOLOS \u00e9 apresentado por Rodrigo Faro, sob dire\u00e7\u00e3o geral de Wanderley Villa Nova e dire\u00e7\u00e3o art\u00edstica de Fernanda Telles, e vai ao ar \u00e0s ter\u00e7as e quintas, logo ap\u00f3s a novela Vidas em Jogo.<\/p>\n<p>\u00cddolos Rede Record<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00cddolos da Rede Record &#8211; no programa \u00cddolos exibido na quinta-feira (19\/05) foi definido o TOP 10 pela vota\u00e7\u00e3o do p\u00fablico e pelos jurados. Dos 15 participantes, apenas 10 ir\u00e3o disputar a fase final do reality show &#8211; chamada Concertos, que come\u00e7a na pr\u00f3xima ter\u00e7a-feira, dia 24\/05. E a primeira apresenta\u00e7\u00e3o ter\u00e1 como tema o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22,371,343],"tags":[],"class_list":{"0":"post-35113","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-rede-record","9":"category-televisao","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/idolos-rede-record.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=35113"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/35113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/34401"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=35113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=35113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=35113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}