{"id":34732,"date":"2011-04-23T20:46:00","date_gmt":"2011-04-24T00:46:00","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=34732"},"modified":"2011-04-23T20:46:00","modified_gmt":"2011-04-24T00:46:00","slug":"lotomania-1134-%e2%80%93-resultado-do-sorteio-deste-sabado-2304","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2011\/lotomania-1134-%e2%80%93-resultado-do-sorteio-deste-sabado-2304\/34732","title":{"rendered":"Lotomania 1134 \u2013 resultado do sorteio deste s\u00e1bado (23\/04)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17778\" title=\"resultado da lotomania\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Lotomania 1134 \u2013\u00a0o\u00a0<strong><em>resultado<\/em><\/strong> do sorteio da <strong><em>Lotomania\u00a01134<\/em><\/strong>, realizado neste s\u00e1bado (<strong><em>23\/04<\/em><\/strong>), foi divulgado pelo caminh\u00e3o da sorte em Franco da Rocha\/SP. No \u00faltimo sorteio o premio principal acumulou. O pr\u00eamio principal da Lotomania 1134 de hoje estava estimado em 1 milh\u00e3o de reais. Na Lotomania, voc\u00ea escolhe 50 n\u00fameros e ganha se acertar 16, 17, 18, 19, 20 ou nenhum n\u00famero. Ela \u00e9 simples de apostar e f\u00e1cil de ganhar. Al\u00e9m de marcar no volante, voc\u00ea conta com outras formas de jogar. Voc\u00ea pode: apostar uma quantidade inferior a 50 n\u00fameros e deixar que o sistema complete o jogo para voc\u00ea; n\u00e3o marcar nada e deixar que o sistema escolha todos os n\u00fameros (Surpresinha) e\/ou repetir o mesmo jogo por 2 ou 4 semanas (Teimosinha).\u00a0Voc\u00ea pode ainda efetuar uma nova aposta com o sistema selecionando os outros 50 n\u00fameros n\u00e3o registrados no jogo original (Aposta-Espelho).<\/p>\n<p>Confira o resultado da Lotomania 1134 deste s\u00e1bado (23\/04):<\/p>\n<p><strong>01\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a005\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a009\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a017\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a022<\/strong><\/p>\n<p><strong>23\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a024\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a034\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a041\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a042<\/strong><\/p>\n<p><strong>46\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a049\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a052\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a055\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a058<\/strong><\/p>\n<p><strong>60\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a075\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a079\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a084\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a089<\/strong><\/p>\n<p>O pre\u00e7o da aposta \u00e9 \u00fanico e custa apenas R$ 1,50. Os sorteios s\u00e3o realizados \u00e0s quartas-feiras e aos s\u00e1bados, \u00e0s 20h. O pr\u00eamio bruto corresponde a 46% da arrecada\u00e7\u00e3o, j\u00e1 computado o adicional destinado ao Minist\u00e9rio do Esporte. Dessa porcentagem s\u00e3o distribu\u00eddos:<\/p>\n<p>30% entre os acertadores dos 20 n\u00fameros sorteados;<\/p>\n<p>20% entre os acertadores de 19 n\u00fameros;<\/p>\n<p>20% entre os acertadores de 18 n\u00fameros;<\/p>\n<p>10% entre os acertadores de 17 n\u00fameros<\/p>\n<p>10% entre os acertadores de 16 n\u00fameros;<\/p>\n<p>10% entre os apostadores que n\u00e3o acertaram nenhum n\u00famero.<\/p>\n<p>N\u00e3o havendo acertador na faixa de 0 acerto, o valor acumula para o concurso seguinte, na primeira faixa de premia\u00e7\u00e3o correspondente a 20 acertos. Nas demais faixas ( 16, 17, 18, 19 e 20 acertos) o valor acumula para o concurso seguinte na respectiva faixa.<\/p>\n<p>Os pr\u00eamios prescrevem 90 dias ap\u00f3s a data do sorteio. Ap\u00f3s esse prazo, os valores s\u00e3o repassados ao tesouro nacional para aplica\u00e7\u00e3o no FIES \u2013 Fundo de Financiamento ao Estudante do Ensino Superior.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lotomania 1134 \u2013\u00a0o\u00a0resultado do sorteio da Lotomania\u00a01134, realizado neste s\u00e1bado (23\/04), foi divulgado pelo caminh\u00e3o da sorte em Franco da Rocha\/SP. No \u00faltimo sorteio o premio principal acumulou. O pr\u00eamio principal da Lotomania 1134 de hoje estava estimado em 1 milh\u00e3o de reais. Na Lotomania, voc\u00ea escolhe 50 n\u00fameros e ganha se acertar 16, 17, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,359],"tags":[],"class_list":["post-34732","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-loteria","category-loto-mania","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/resultado-da-lotomania1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=34732"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/34732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/17778"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=34732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=34732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=34732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}