{"id":31876,"date":"2010-10-07T14:44:19","date_gmt":"2010-10-07T18:44:19","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=31876"},"modified":"2010-10-07T14:44:19","modified_gmt":"2010-10-07T18:44:19","slug":"mackenzie-abre-edital-permanente-para-incubadora-de-empresas","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/mackenzie-abre-edital-permanente-para-incubadora-de-empresas\/31876","title":{"rendered":"Mackenzie abre edital permanente para Incubadora de Empresas"},"content":{"rendered":"<p>O N\u00facleo de Inova\u00e7\u00e3o e Tecnologia \u2013 NIT \u2013 da Universidade Presbiteriana  Mackenzie lan\u00e7ou edital para preenchimento de <strong><em>vagas na Incubadora de Empresas<\/em><\/strong> da  Universidade. Os candidatos devem se inscrever e apresentar propostas de  empreendimentos nas \u00e1reas de meio ambiente, energias renov\u00e1veis, biotecnologia,  f\u00e1rmacos, sa\u00fade, nutri\u00e7\u00e3o, materiais, sa\u00fade, microeletr\u00f4nica, telecomunica\u00e7\u00f5es e  tecnologia da informa\u00e7\u00e3o.<\/p>\n<p>Uma das exig\u00eancias para a elabora\u00e7\u00e3o das propostas \u00e9 que pelo menos um s\u00f3cio  do neg\u00f3cio seja mackenzista, o que significa funcion\u00e1rio, aluno ou ex-aluno do  Col\u00e9gio ou da Universidade Presbiteriana Mackenzie.<\/p>\n<p>Al\u00e9m da infraestrutura f\u00edsica e tecnol\u00f3gica, a Incubadora permite o acesso a  bibliotecas, softwares e bases de dados da Universidade, cursos, palestras,  consultoria, treinamento, f\u00f3runs e workshops.<\/p>\n<p>O principal objetivo do NIT \u00e9 justamente fomentar o empreendedorismo e a  inova\u00e7\u00e3o tecnol\u00f3gica de estudantes e pesquisadores, buscando parcerias e dando  todo o suporte para a cria\u00e7\u00e3o e o desenvolvimento das empresas.<\/p>\n<p>O edital est\u00e1 aberto por tempo indeterminado. Todas as informa\u00e7\u00f5es est\u00e3o  dispon\u00edveis em www.mackenzie.br\/nit.html. Os contatos s\u00e3o 3258-8156 e  nit@mackenzie.br. O NIT fica na Rua Maria Ant\u00f4nia, 358, 3\u00ba andar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O N\u00facleo de Inova\u00e7\u00e3o e Tecnologia \u2013 NIT \u2013 da Universidade Presbiteriana Mackenzie lan\u00e7ou edital para preenchimento de vagas na Incubadora de Empresas da Universidade. Os candidatos devem se inscrever e apresentar propostas de empreendimentos nas \u00e1reas de meio ambiente, energias renov\u00e1veis, biotecnologia, f\u00e1rmacos, sa\u00fade, nutri\u00e7\u00e3o, materiais, sa\u00fade, microeletr\u00f4nica, telecomunica\u00e7\u00f5es e tecnologia da informa\u00e7\u00e3o. Uma [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":{"0":"post-31876","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-inscricao","8":"category-oportunidades","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/31876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=31876"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/31876\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=31876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=31876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=31876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}