{"id":31485,"date":"2010-09-16T11:09:58","date_gmt":"2010-09-16T15:09:58","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=31485"},"modified":"2010-09-16T11:10:50","modified_gmt":"2010-09-16T15:10:50","slug":"resultado-do-sorteio-de-setembro-da-nota-fiscal-paulista","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/resultado-do-sorteio-de-setembro-da-nota-fiscal-paulista\/31485","title":{"rendered":"Resultado do sorteio de setembro da Nota Fiscal Paulista"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18269\" title=\"nota fiscal paulista pta\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/nota-fiscal-paulista1.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/nota-fiscal-paulista1.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/nota-fiscal-paulista1-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/nota-fiscal-paulista1-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O <strong><em>resultado<\/em><\/strong> do\u00a0<strong><em><span style=\"font-weight: normal;\"><span style=\"font-style: normal;\">22\u00ba sorteio da<\/span><\/span> Nota Fiscal Paulista<\/em><\/strong>, que est\u00e1 distribuindo 1,5 milh\u00e3o  de pr\u00eamios, no total de R$ 17 milh\u00f5es, registrou em seu sistema a participa\u00e7\u00e3o  de 5.019.454 consumidores que forneceram o CPF, 2.312 entidades sociais e 2.014  condom\u00ednios que informaram o CNPJ em suas compras e aderiram ao regulamento da  premia\u00e7\u00e3o. No total, 61.172.180 bilhetes eletr\u00f4nicos concorreram. Um paulistano, morador da Vila Roschel, no bairro de Parelheiros, foi o ganhador do pr\u00eamio principal de R$ 50 mil da Nota Fiscal Paulista, no 22\u00ba sorteio. Ele concorreu com 25 bilhetes, cujas compras foram realizadas no m\u00eas de maio na Capital. A extra\u00e7\u00e3o de setembro tamb\u00e9m premiou uma moradora de Campinas, com o valor de R$ 20 mil, referente ao terceiro pr\u00eamio especial. A campineira participou da premia\u00e7\u00e3o com 31 bilhetes. Os dados do vencedor do segundo pr\u00eamio, no valor de R$ 30 mil, ainda est\u00e3o sob an\u00e1lise, por suspeita de irregularidade.<\/p>\n<p>Al\u00e9m dos tr\u00eas pr\u00eamios principais, a extra\u00e7\u00e3o do 22\u00ba sorteio da Nota Fiscal Paulista\u00a0contemplou consumidores com  300 pr\u00eamios de R$ 1.000; mil de R$ 250, 15.000 de R$ 50, 76.303 de R$ 20 e  1.407.394 de R$ 10. O resultado j\u00e1 est\u00e1 dispon\u00edvel para consulta no site  Secretaria da Fazenda. Para conferir os bilhetes, o consumidor cadastrado no  programa e que aderiu ao regulamento do sorteio deve acessar o site  <a href=\"http:\/\/www.nfp.fazenda.sp.gov.br\" target=\"_blank\">www.nfp.fazenda.sp.gov.br<\/a>.<\/p>\n<p>A Nota Fiscal Paulista foi criada em outubro de 2007 e faz parte do  Programa de Est\u00edmulo \u00e0 Cidadania Fiscal do governo do Estado de S\u00e3o Paulo. Ela  reduz, de fato, a carga tribut\u00e1ria individual dos cidad\u00e3os, que recebem cr\u00e9ditos  ao efetuarem compras de mercadorias em S\u00e3o Paulo. Os consumidores que solicitam  o documento fiscal e informam o seu CPF ou CNPJ, recebem at\u00e9 30% do ICMS  efetivamente recolhido pelo estabelecimento comercial proporcional ao valor da  sua nota. O programa conta com mais de 8,8 milh\u00f5es de participantes cadastrados  e, desde seu in\u00edcio, em outubro de 2007, mais de 9,5 bilh\u00f5es de documentos  fiscais foram registrados na Fazenda.<\/p>\n<p>Os consumidores que desejam concorrer na extra\u00e7\u00e3o de outubro, que ir\u00e1  considerar as compras realizadas em junho de 2010, t\u00eam at\u00e9 o dia 25 de setembro  para aderir ao regulamento. Quem j\u00e1 fez a ades\u00e3o anteriormente n\u00e3o precisa se  cadastrar novamente. Os pr\u00eamios em dinheiro poder\u00e3o ser resgatados em at\u00e9 cinco  anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O resultado do\u00a022\u00ba sorteio da Nota Fiscal Paulista, que est\u00e1 distribuindo 1,5 milh\u00e3o de pr\u00eamios, no total de R$ 17 milh\u00f5es, registrou em seu sistema a participa\u00e7\u00e3o de 5.019.454 consumidores que forneceram o CPF, 2.312 entidades sociais e 2.014 condom\u00ednios que informaram o CNPJ em suas compras e aderiram ao regulamento da premia\u00e7\u00e3o. No total, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,335,362],"tags":[],"class_list":{"0":"post-31485","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-loteria","9":"category-nota-fiscal-paulista","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/nota-fiscal-paulista1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/31485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=31485"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/31485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/18269"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=31485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=31485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=31485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}