{"id":31255,"date":"2010-09-03T14:36:03","date_gmt":"2010-09-03T18:36:03","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=31255"},"modified":"2010-09-03T14:36:03","modified_gmt":"2010-09-03T18:36:03","slug":"mitos-e-verdades-sobre-a-vitamina-c-e-o-resfriado","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/mitos-e-verdades-sobre-a-vitamina-c-e-o-resfriado\/31255","title":{"rendered":"Mitos e verdades sobre a vitamina C e o resfriado"},"content":{"rendered":"<p>A ingest\u00e3o de <strong><em>vitamina C<\/em><\/strong> \u00e9 tida pela maioria das pessoas como uma das principais formas de prevenir o <strong><em>resfriado<\/em><\/strong>. A ideia remonta de 1970, ano em que o qu\u00edmico norte-americano Linus Pauling, ganhador de dois pr\u00eamios Nobel, lan\u00e7ou o livro \u201cVitamina C e o Resfriado\u201d, no qual pregava que 1 grama di\u00e1rio de vitamina C era o suficiente para reduzir em 45% a incid\u00eancia de resfriados.<\/p>\n<p>Segundo Mauro Scharf, endocrinologista da DASA, que \u00e9 representada em Mato Grosso pelas marcas Cedic\/ Cedilab e portador do CRM 13009 PR, hoje m\u00e9dicos e nutricionistas questionam o m\u00e9todo Pauling de preven\u00e7\u00e3o a gripes e resfriados. Pesquisadores europeus desenvolveram o maior estudo de revis\u00e3o sobre o papel da vitamina C em rela\u00e7\u00e3o a esses males e conclu\u00edram que a receita \u00e9 absolutamente ineficaz, exceto para atletas de alta performance, como maratonistas ou triatletas.<\/p>\n<p>\u201cNo grupo pesquisado, os que tomavam a vitamina regularmente ficavam doentes com uma frequ\u00eancia 50% menor. Para o resto das pessoas os efeitos preventivos da vitamina C eram os mesmos de um placebo, ou seja, n\u00e3o tinham serventia nenhuma\u201d, afirma Scharf. O endocrinologista refor\u00e7a que esta an\u00e1lise avaliou que a vitamina C se mostrou \u00fatil apenas para aliviar os sintomas de gripes e resfriados e para diminuir o mal-estar do paciente.<\/p>\n<p>Scharf diz que ainda n\u00e3o h\u00e1 explica\u00e7\u00e3o para o fato de a suplementa\u00e7\u00e3o de vitamina C s\u00f3 funcionar como preventivo de gripes e resfriados em atletas. O estudo considerou atletas apenas aqueles que treinam no m\u00ednimo uma hora e meia por dia, de cinco a seis vezes por semana. O que se sabe \u00e9 que, depois de exerc\u00edcios muito \u00e1rduos, o organismo precisa recompor tecidos danificados ou extenuados pela atividade intensa.<\/p>\n<p>Nestas fun\u00e7\u00f5es de esfor\u00e7o f\u00edsico acontece um grande rebaixamento da presen\u00e7a de vitamina C. \u201cEm geral, at\u00e9 o que se sabe hoje, os benef\u00edcios da suplementa\u00e7\u00e3o de vitamina C na preven\u00e7\u00e3o de gripes e resfriados s\u00f3 valem para quem treina pesado\u201d, finaliza o endocrinologista.<\/p>\n<p>Fonte: The Cochrane Library<\/p>\n<p>Sobre a DASA<\/p>\n<p>A DASA \u00e9 a maior empresa de medicina diagn\u00f3stica e sa\u00fade preventiva da Am\u00e9rica Latina em termos de receita bruta e popula\u00e7\u00e3o e a quinta maior rede no mundo. Com mais de 11,5 mil colaboradores, atende aproximadamente 55 mil pacientes por dia em 321 unidades. Processa em m\u00e9dia 10 milh\u00f5es de exames por m\u00eas. Oferece mais de tr\u00eas mil tipos de exames de an\u00e1lises cl\u00ednicas e diagn\u00f3stico por imagem. Atualmente, o grupo \u00e9 formado por 18 marcas em 12 estados brasileiros e no Distrito Federal \u2013 Delboni Auriemo e Lavoisier (SP), Bronstein, L\u00e2mina e MedImagem (RJ); Club DA (RJ e SP); Pasteur e Exame (DF), MedLabor (TO), Frischmann Aisengart e \u00c1lvaro (PR), Cient\u00edficaLab (ES, MG, RJ e SP), Image Memorial (BA), L\u00e2mina (SC), Atalaia (GO), Cedic e Cedilab (MT) e LabPasteur e Unimagem (CE).<\/p>\n<p>*Informa\u00e7\u00f5es atualizadas de acordo com os resultados do 2T10.<\/p>\n<p>Sobre o Cedic e Cedilab Medicina Diagn\u00f3stica<\/p>\n<p>O Cedic e Cedilab nasceram, respectivamente, h\u00e1 14 e 9 anos no Mato Grosso e s\u00e3o considerados refer\u00eancias para o segmento de medicina diagn\u00f3stica. Juntos, somam mais de 200 colaboradores em nove unidades, que atuam na capital e na regi\u00e3o metropolitana. S\u00e3o realizados mais de tr\u00eas mil tipos de exames de an\u00e1lises cl\u00ednicas e diagn\u00f3sticos por imagem que contemplam servi\u00e7os e solu\u00e7\u00f5es diferenciados com qualidade, rapidez e alto padr\u00e3o de atendimento, como a coleta domiciliar. H\u00e1 dois anos, a marca \u00e9 escolhida como o prestador de servi\u00e7os em medicina diagn\u00f3stica mais lembrado pela popula\u00e7\u00e3o na regi\u00e3o por meio do pr\u00eamio Top of Mind, realizado pela revista RDM, com os institutos Newcomdates Tecnologia da informa\u00e7\u00e3o e Full Time Pesquisa de Mercado . O Cedic e Cedilab fazem parte da DASA, maior empresa de medicina diagn\u00f3stica na Am\u00e9rica Latina e quinta maior no mundo. Para mais informa\u00e7\u00f5es: www.cedic.com.br e www.cedilab.com.br .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ingest\u00e3o de vitamina C \u00e9 tida pela maioria das pessoas como uma das principais formas de prevenir o resfriado. A ideia remonta de 1970, ano em que o qu\u00edmico norte-americano Linus Pauling, ganhador de dois pr\u00eamios Nobel, lan\u00e7ou o livro \u201cVitamina C e o Resfriado\u201d, no qual pregava que 1 grama di\u00e1rio de vitamina [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,5],"tags":[],"class_list":["post-31255","post","type-post","status-publish","format-standard","category-brasil","category-saude-e-vida","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/31255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=31255"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/31255\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=31255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=31255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=31255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}