{"id":30528,"date":"2010-07-30T11:46:06","date_gmt":"2010-07-30T15:46:06","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=30528"},"modified":"2010-07-30T11:46:06","modified_gmt":"2010-07-30T15:46:06","slug":"finep-prorroga-edital-de-r-100-milhoes-para-setor-de-petroleo-e-gas","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/finep-prorroga-edital-de-r-100-milhoes-para-setor-de-petroleo-e-gas\/30528","title":{"rendered":"Finep prorroga edital de R$ 100 milh\u00f5es para setor de Petr\u00f3leo e G\u00e1s"},"content":{"rendered":"<p>A <strong><em>Finep<\/em><\/strong> &#8211; Financiadora de Estudos e Projetos prorrogou para as 18h do dia 16 de  agosto o prazo para apresenta\u00e7\u00e3o da Carta de Manifesta\u00e7\u00e3o de Interesse por  empresas que queiram desenvolver <strong><em>projetos com solu\u00e7\u00f5es tecnol\u00f3gicas para a  ind\u00fastria de Petr\u00f3leo e G\u00e1s<\/em><\/strong>. Com essa prorroga\u00e7\u00e3o, a data de divulga\u00e7\u00e3o dos  projetos escolhidos passa, agora, para 16 de setembro.<\/p>\n<p>O Edital  disponibiliza R$ 100 milh\u00f5es para apoiar os projetos selecionados e oferece \u00e0s  empresas a alternativa da contrapartida n\u00e3o financeira. Os projetos ser\u00e3o  desenvolvidos em sistema de coopera\u00e7\u00e3o entre ind\u00fastrias da cadeia do setor de  Petr\u00f3leo e G\u00e1s (P&amp;G) e institui\u00e7\u00f5es de pesquisa cient\u00edfica e tecnol\u00f3gica  (ICTs).<\/p>\n<p>Seis setores foram priorizados no Edital com base em um Estudo  de Competitividade do Setor de Petr\u00f3leo e G\u00e1s realizado pelo Prominp \u2013 Programa  de Mobiliza\u00e7\u00e3o da Ind\u00fastria Nacional de Petr\u00f3leo e G\u00e1s Natural, em parceria com  a Petrobras. S\u00e3o eles: Caldeiraria; Conex\u00f5es e Flanges; V\u00e1lvulas; Instrumenta\u00e7\u00e3o  e Automa\u00e7\u00e3o; V\u00e1lvulas, Umbilicais e Constru\u00e7\u00e3o Naval.<\/p>\n<p>Nessa primeira  etapa, as empresas dever\u00e3o preencher as se\u00e7\u00f5es do formul\u00e1rio contido na Carta de  Manifesta\u00e7\u00e3o de Interesse: caracteriza\u00e7\u00e3o e dados complementares da empresa  l\u00edder; identifica\u00e7\u00e3o e caracteriza\u00e7\u00e3o das demais empresas, proposta e or\u00e7amento  estimado. Na segunda etapa, ser\u00e1 a vez de as ICTs detalharem o projeto em  formul\u00e1rio pr\u00f3prio, que estar\u00e1 dispon\u00edvel no site da Finep  (http:\/\/www.finep.gov.br\/) a partir do dia 5 de outubro (novo cronograma no  anexo).<\/p>\n<p>O segundo edital<\/p>\n<p>No in\u00edcio de julho, a Finep tamb\u00e9m lan\u00e7ou  outra chamada p\u00fablica, no valor de R$ 30 milh\u00f5es, para apoiar a cria\u00e7\u00e3o,  adequa\u00e7\u00e3o e capacita\u00e7\u00e3o de laborat\u00f3rios de ICTs interessados em desenvolver  projetos voltados para o atendimento de demandas dos fornecedores da cadeia de  P&amp;G. Nessa chamada p\u00fablica, as institui\u00e7\u00f5es devem enviar seus formul\u00e1rio com  as propostas at\u00e9 o dia 8 de setembro.<\/p>\n<p>Nesse caso, ser\u00e3o tr\u00eas linhas de  apoio: (1) para laborat\u00f3rios de ensaios de desempenho de v\u00e1lvulas e acess\u00f3rios  de tubula\u00e7\u00e3o; (2) de equipamentos de seguran\u00e7a, e (3) de qualifica\u00e7\u00e3o e an\u00e1lise  de umbilicais. Os recursos vir\u00e3o do Fundo Nacional de Desenvolvimento Cient\u00edfico  e Tecnol\u00f3gico (FNDCT).<\/p>\n<p>Nas duas chamadas, o valor m\u00ednimo das propostas  dever\u00e1 ser de R$ 1 milh\u00e3o, incluindo as bolsas de estudo e pesquisa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Finep &#8211; Financiadora de Estudos e Projetos prorrogou para as 18h do dia 16 de agosto o prazo para apresenta\u00e7\u00e3o da Carta de Manifesta\u00e7\u00e3o de Interesse por empresas que queiram desenvolver projetos com solu\u00e7\u00f5es tecnol\u00f3gicas para a ind\u00fastria de Petr\u00f3leo e G\u00e1s. Com essa prorroga\u00e7\u00e3o, a data de divulga\u00e7\u00e3o dos projetos escolhidos passa, agora, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7,370,353],"tags":[],"class_list":["post-30528","post","type-post","status-publish","format-standard","category-brasil","category-economia","category-inscricao","category-oportunidades","entry","gs-1","gs-odd","gs-even","gs-featured-content-entry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/30528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=30528"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/30528\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=30528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=30528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=30528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}