{"id":30329,"date":"2010-07-20T16:11:24","date_gmt":"2010-07-20T20:11:24","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=30329"},"modified":"2010-07-20T16:11:24","modified_gmt":"2010-07-20T20:11:24","slug":"santo-andre-abre-inscricoes-para-palestras-com-eua","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/santo-andre-abre-inscricoes-para-palestras-com-eua\/30329","title":{"rendered":"Santo Andr\u00e9 abre inscri\u00e7\u00f5es para Palestras com EUA"},"content":{"rendered":"<p>A Prefeitura de <strong><em>Santo Andr\u00e9<\/em><\/strong> abriu<strong><em> inscri\u00e7\u00f5es <\/em><\/strong>para mais um evento do <strong><em>Ciclo de  Palestras \u2013 A\u00e7\u00f5es Internacionais<\/em><\/strong>, desta vez com representantes comerciais dos  <strong><em>Estados Unidos<\/em><\/strong>. O evento est\u00e1 programado para 12 de agosto, das 19h30 \u00e0s 21h50,  no Teatro Municipal, localizado na Pra\u00e7a IV Centen\u00e1rio, s\/n\u00ba, centro.<\/p>\n<p>Empres\u00e1rios interessados em participar devem entrar em contato com o  Departamento de Rela\u00e7\u00f5es Internacionais e Capta\u00e7\u00e3o de Recursos da Secretaria de  Desenvolvimento Econ\u00f4mico e Trabalho (SDET) pelo telefone (11) 4468-441 ou pelo  email dri@santoandre.sp.gov.br.<\/p>\n<p>A programa\u00e7\u00e3o \u00e9 um prato cheio para empreendedores dos mais diversos portes  e segmentos que tenham em comum o interesse em iniciar ou intensificar neg\u00f3cios  com o epicentro econ\u00f4mico da Am\u00e9rica do Norte. O ministro conselheiro do governo  norte-americano para Assuntos Comerciais, Daniel DeVito, ministrar\u00e1 palestra  intitulada Conjuntura Econ\u00f4mica e Pol\u00edtica Externa.<\/p>\n<p>O c\u00f4nsul comercial dos Estados Unidos em S\u00e3o Paulo, Sean Relley, discorrer\u00e1  sobre o tema Fazendo Neg\u00f3cios com os Estados Unidos. E o representante da  Ag\u00eancia dos Estados Unidos para o Com\u00e9rcio e Desenvolvimento, Rodrigo Mota,  abordar\u00e1 o tema Oportunidades de Financiamento a Fundo Perdido. A USTDA, na  sigla em ingl\u00eas, \u00e9 uma ag\u00eancia governamental independente, financiada pelo  Congresso norte-americano.<\/p>\n<p>Estrutura maior<\/p>\n<p>O interesse em torno dos Estados Unidos \u00e9 o motivo que levou a Secretaria de  Desenvolvimento Econ\u00f4mico a programar, pela primeira vez, um evento do Ciclo de  Palestras \u2013 A\u00e7\u00f5es Internacionais para o Teatro Municipal, com capacidade para  475 convidados sentados.<\/p>\n<p>Somente neste ano, a secretaria municipal j\u00e1 promoveu palestras com  representa\u00e7\u00f5es comerciais de Cabo Verde, China e \u00c1ustria. As duas primeiras  foram realizadas no Anfiteatro e a \u00faltima no Sal\u00e3o Burle Marx.<\/p>\n<p>\u201cOs Estados Unidos naturalmente despertam mais interesse, na condi\u00e7\u00e3o de  locomotiva econ\u00f4mica do planeta. Este fato pede uma estrutura maior\u201d \u2013 afirma  Edson Salvo Melo, secret\u00e1rio de Desenvolvimento Econ\u00f4mico e Trabalho.<\/p>\n<p>Melo lembra ainda que o estacionamento da Prefeitura de Santo Andr\u00e9 poder\u00e1  ser utilizado gratuitamente pelos convidados, uma vez que \u00e9 liberado ao p\u00fablico  a partir das 17h.<\/p>\n<p>Com\u00e9rcio bilateral<\/p>\n<p>Dados oficiais do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio (MDIC)  compilados pelo Departamento de Indicadores Sociais e Econ\u00f4micos (DISE) da SDET  mostram a for\u00e7a do fluxo comercial entre Santo Andr\u00e9 e Estados Unidos. As  empresas andreenses exportaram US$ 64,193 milh\u00f5es para os Estados Unidos no  primeiro semestre deste ano. O valor corresponde a 21% do total das exporta\u00e7\u00f5es  de Santo Andr\u00e9 no per\u00edodo, as quais atingiram US$ 303, 229 milh\u00f5es.<\/p>\n<p>Os n\u00fameros colocam os Estados Unidos na condi\u00e7\u00e3o de principal destino das  exporta\u00e7\u00f5es andreenses, ligeiramente \u00e0 frente da Argentina, com fatia de  20%.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0s importa\u00e7\u00f5es, os Estados Unidos figuram como a principal fonte,  respons\u00e1veis por US$ 69,407 milh\u00f5es do total de US$ 332,268 milh\u00f5es importados  por Santo Andr\u00e9 no acumulado de janeiro a junho deste ano, ou 22% do total. Em  seguida vem Tail\u00e2ndia, com 18%, e Indon\u00e9sia, com 11%, \u00e0 frente da vizinha  Argentina, quarta colocada com 6%. O motivo do destaque dos pa\u00edses asi\u00e1ticos na  pauta municipal \u00e9 que eles s\u00e3o grandes fornecedores de insumos para a ind\u00fastria  de pneus concentrada em Santo Andr\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Santo Andr\u00e9 abriu inscri\u00e7\u00f5es para mais um evento do Ciclo de Palestras \u2013 A\u00e7\u00f5es Internacionais, desta vez com representantes comerciais dos Estados Unidos. O evento est\u00e1 programado para 12 de agosto, das 19h30 \u00e0s 21h50, no Teatro Municipal, localizado na Pra\u00e7a IV Centen\u00e1rio, s\/n\u00ba, centro. Empres\u00e1rios interessados em participar devem entrar em [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,7,370,353],"tags":[],"class_list":{"0":"post-30329","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-economia","8":"category-inscricao","9":"category-oportunidades","10":"entry","11":"gs-1","12":"gs-odd","13":"gs-even","14":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/30329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=30329"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/30329\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=30329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=30329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=30329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}