{"id":29842,"date":"2010-06-27T17:29:17","date_gmt":"2010-06-27T21:29:17","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=29842"},"modified":"2010-06-30T18:48:51","modified_gmt":"2010-06-30T22:48:51","slug":"meteorologia-%e2%80%93-previsao-do-tempo-para-segunda-feira-2806","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/meteorologia-%e2%80%93-previsao-do-tempo-para-segunda-feira-2806\/29842","title":{"rendered":"Meteorologia \u2013 previs\u00e3o do tempo para segunda-feira 28\/06"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28410\" title=\"previsao do tempo temperatura\" src=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura.jpg 300w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura-250x160.jpg 250w, https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura-150x96.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Previs\u00e3o do tempo<\/em><\/strong> \u2013 a <strong><em>meteorologia<\/em><\/strong> divulgou a previs\u00e3o do tempo e <strong><em>temperatura<\/em><\/strong> para segunda-feira 28\/06, e informa que o norte do RS e o sudeste de SC ter\u00e1 muitas nuvens e possibilidade de pancadas de chuva no per\u00edodo da tarde. Segundo a previs\u00e3o do tempo \u00e1reas de instabilidade provocar\u00e3o chuvas isoladas no centro e litoral sul do RS. No norte e nordeste do RS e no sul de SC haver\u00e1 possibilidade de chuva. Nas outras \u00e1reas de SC e no sul e leste do PR o dia ser\u00e1 com varia\u00e7\u00e3o de nebulosidade. Dados da previs\u00e3o do tempo indicam que no norte do ES, no leste, sul e nordeste da BA e no semi-\u00e1rido do Nordeste o dia ser\u00e1 de tempo inst\u00e1vel. No Rec\u00f4ncavo Baiano, litoral norte da BA e litoral entre PE e RN o dia ser\u00e1 com chuvas. Entre o litoral do CE e o litoral do MA haver\u00e1 pancadas de chuva a tarde. No norte da Regi\u00e3o Norte o dia ser\u00e1 quente com pancadas de chuva. A previs\u00e3o do tempo destaca que nas outras \u00e1reas do Brasil uma massa de ar seco deixa o dia com predom\u00ednio de sol e a umidade do ar baixa, principalmente no Centro-Oeste.<\/p>\n<p>Regi\u00e3o Centro-Oeste \u2013 previs\u00e3o do tempo em 28\/06\/2010: No sudoeste de MT e no oeste de MS: sol entre poucas nuvens. Nas demais \u00e1reas: predom\u00ednio de sol. A umidade relativa do ar poder\u00e1 ficar abaixo dos 30%. As temperaturas estar\u00e3o elevadas. Temperatura m\u00e1xima:35C em Cuiab\u00e1. Temperatura m\u00ednima: 14C no sul de MS.<\/p>\n<p>Regi\u00e3o Nordeste \u2013 previs\u00e3o do tempo em 28\/06\/2010: No litoral entre o PE e o RN e no Rec\u00f4ncavo Baiano: muitas nuvens e chuva. Na faixa leste do Nordeste: tempo inst\u00e1vel, com chuva isolada a qualquer hora. No norte do MA e do PI: sol entre nuvens e pancadas de chuva. Nas demais \u00e1reas do MA e do PI e no oeste da BA: predom\u00ednio de sol. Nas demais \u00e1reas: sol entre poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 34C no norte do PI. Temperatura m\u00ednima: 15C no oeste da BA.<\/p>\n<p>Regi\u00e3o Norte \u2013 previs\u00e3o do tempo em 28\/06\/2010: No centro-norte da Regi\u00e3o: sol entre nuvens e pancadas de chuva. Nas demais \u00e1reas: sol e poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 35C no sul do AM. Temperatura m\u00ednima: 14C no sudeste do PA.<\/p>\n<p>Regi\u00e3o Sudeste \u2013 previs\u00e3o do tempo em 28\/06\/2010: No norte do ES e nordeste de MG: c\u00e9u nublado, com tempo inst\u00e1vel e chuva a qualquer hora. Nas demais \u00e1reas da Regi\u00e3o: sol entre poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 30C no oeste de SP. Temperaturas m\u00ednima: 0C na serra da mantiqueira.<\/p>\n<p>Regi\u00e3o Sul \u2013 previs\u00e3o do tempo em 28\/06\/2010: No sul do RS: sol entre poucas nuvens. No centro do RS: muitas nuvens e chuvas isoladas. No norte do RS e no sudeste de SC: muitas nuvens e possibilidade de pancadas de chuva no per\u00edodo da tarde. No norte do PR: predom\u00ednio de sol. Nas demais \u00e1reas: sol e poucas nuvens. As temperaturas estar\u00e3o est\u00e1veis. Temperatura m\u00e1xima: 28C no noroeste do PR. Temperatura minima: 12C nas \u00e1reas de serra.<\/p>\n<p>Previs\u00e3o do tempo e temperatura CPTEC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o do tempo \u2013 a meteorologia divulgou a previs\u00e3o do tempo e temperatura para segunda-feira 28\/06, e informa que o norte do RS e o sudeste de SC ter\u00e1 muitas nuvens e possibilidade de pancadas de chuva no per\u00edodo da tarde. Segundo a previs\u00e3o do tempo \u00e1reas de instabilidade provocar\u00e3o chuvas isoladas no centro e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,327],"tags":[],"class_list":{"0":"post-29842","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-clima","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"https:\/\/www.redenoticia.com.br\/noticia\/imagens\/previsao-do-tempo-temperatura.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/29842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=29842"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/29842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media\/28410"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=29842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=29842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=29842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}