{"id":29121,"date":"2010-06-07T18:18:09","date_gmt":"2010-06-07T22:18:09","guid":{"rendered":"http:\/\/www.redenoticia.com.br\/noticia\/?p=29121"},"modified":"2010-06-07T18:18:09","modified_gmt":"2010-06-07T22:18:09","slug":"fundacao-volkswagen-abre-inscricao-para-concurso-de-projetos-sociais","status":"publish","type":"post","link":"https:\/\/www.redenoticia.com.br\/noticia\/2010\/fundacao-volkswagen-abre-inscricao-para-concurso-de-projetos-sociais\/29121","title":{"rendered":"Funda\u00e7\u00e3o Volkswagen abre inscri\u00e7\u00e3o para concurso de projetos sociais"},"content":{"rendered":"<p>A <strong><em>Funda\u00e7\u00e3o Volkswagen<\/em><\/strong> receber\u00e1 at\u00e9 o dia 30 de junho <strong><em>inscri\u00e7\u00f5es para o concurso Volkswagen na Comunidade 2010<\/em><\/strong>, que concede uma premia\u00e7\u00e3o de R$ 30 mil em dinheiro e um curso de capacita\u00e7\u00e3o para a gest\u00e3o de projetos sociais para as institui\u00e7\u00f5es vencedoras do concurso. O edital com as regras do concurso e o formul\u00e1rio de inscri\u00e7\u00e3o est\u00e3o dispon\u00edveis no site da Funda\u00e7\u00e3o Volkswagen: <a href=\"http:\/\/www.fundacaovolkswagen.org.br\" target=\"_blank\">www.fundacaovolkswagen.org.br<\/a>.<\/p>\n<p>Nas duas edi\u00e7\u00f5es anteriores (2008 e 2009), o concurso recebeu aproximadamente 500 projetos inscritos, premiou 20 organiza\u00e7\u00f5es e investiu mais de R$ 1 milh\u00e3o nas comunidades, beneficiando diretamente 1.600 pessoas.<\/p>\n<p>Para a escolha dos vencedores, o concurso avaliar\u00e1 projetos das regi\u00f5es de S\u00e3o Bernardo do Campo (SP), Taubat\u00e9 (SP), S\u00e3o Carlos (SP) e S\u00e3o Jos\u00e9 dos Pinhais (PR), onde est\u00e3o situadas as f\u00e1bricas da Volkswagen do Brasil, e de S\u00e3o Paulo (Jabaquara), onde fica o pr\u00e9dio de Servi\u00e7os Financeiros, e de Vinhedo (SP), onde est\u00e1 situado o Centro de Pe\u00e7as e Acess\u00f3rios (PAC) da empresa.<\/p>\n<p>Amplia\u00e7\u00e3o do concurso<br \/>\nNeste ano, pela primeira vez, tamb\u00e9m concorrer\u00e3o a um pr\u00eamio os projetos apresentados pelos colaboradores dos escrit\u00f3rios regionais de vendas e servi\u00e7os financeiros da Volkswagen do Brasil, que est\u00e3o situados em Curitiba (PR), Campinas (SP), S\u00e3o Paulo (SP), Rio de Janeiro (RJ), Bras\u00edlia (DF) e Recife (PE).<\/p>\n<p>Haver\u00e1 tamb\u00e9m um pr\u00eamio especial para as organiza\u00e7\u00f5es vencedoras da edi\u00e7\u00e3o do concurso de 2009, denominado Pr\u00eamio de Sustentabilidade, com a finalidade de financiar a amplia\u00e7\u00e3o ou o aperfei\u00e7oamento do projeto implementado. O pr\u00eamio ser\u00e1 concedido \u00e0 organiza\u00e7\u00e3o que tiver obtido os melhores resultados, conforme avalia\u00e7\u00e3o da comiss\u00e3o organizadora do concurso.<\/p>\n<p>Trabalho volunt\u00e1rio<br \/>\nPara participar do concurso, a organiza\u00e7\u00e3o deve ser n\u00e3o governamental e legalmente constitu\u00edda. Al\u00e9m disso, os projetos devem ser inscritos por interm\u00e9dio de colaboradores da Volkswagen do Brasil que prestem trabalho volunt\u00e1rio na comunidade ou que desejam apadrinhar algum projeto social. Se necess\u00e1rio, a Funda\u00e7\u00e3o Volkswagen pode indicar \u00e0 organiza\u00e7\u00e3o um colaborador interessado em inscrever um projeto.<\/p>\n<p>&#8220;Por meio do concurso Volkswagen na Comunidade, al\u00e9m de promover o desenvolvimento das comunidades onde estamos presentes, tamb\u00e9m estamos incentivando nossos colaboradores a contribu\u00edrem com a transforma\u00e7\u00e3o social do Brasil&#8221;, comentou Concei\u00e7\u00e3o Mirandola, diretora da Funda\u00e7\u00e3o Volkswagen.<\/p>\n<p>Volkswagen do Brasil<br \/>\nAssuntos Corporativos e Rela\u00e7\u00f5es com a Imprensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Funda\u00e7\u00e3o Volkswagen receber\u00e1 at\u00e9 o dia 30 de junho inscri\u00e7\u00f5es para o concurso Volkswagen na Comunidade 2010, que concede uma premia\u00e7\u00e3o de R$ 30 mil em dinheiro e um curso de capacita\u00e7\u00e3o para a gest\u00e3o de projetos sociais para as institui\u00e7\u00f5es vencedoras do concurso. O edital com as regras do concurso e o formul\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22,370,353],"tags":[],"class_list":{"0":"post-29121","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-brasil","7":"category-inscricao","8":"category-oportunidades","9":"entry","10":"gs-1","11":"gs-odd","12":"gs-even","13":"gs-featured-content-entry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/29121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/comments?post=29121"}],"version-history":[{"count":0,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/posts\/29121\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/media?parent=29121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/categories?post=29121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redenoticia.com.br\/noticia\/wp-json\/wp\/v2\/tags?post=29121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}